{"id":1105,"date":"2021-02-17T15:02:26","date_gmt":"2021-02-17T15:02:26","guid":{"rendered":"http:\/\/cordobanewsnet.wordpress.com\/?p=5004"},"modified":"2021-02-17T15:02:26","modified_gmt":"2021-02-17T15:02:26","slug":"enterate-todo-sobre-la-vuelta-del-boleto-educativo-gratuito","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/02\/17\/enterate-todo-sobre-la-vuelta-del-boleto-educativo-gratuito\/","title":{"rendered":"Enterate todo sobre la vuelta del Boleto Educativo Gratuito"},"content":{"rendered":"<p><!-- \/featured-media --> <\/p>\n<div class=\"post-content clear\" readability=\"46.837711069418\">\n<p>El 1\u00ba de marzo inician las clases y la asistencia ser\u00e1 obligatoria. Despu\u00e9s de un a\u00f1o de educaci\u00f3n virtual, alumnos y docentes se vuelven a reencontrar en el aula con protocolos para evitar contagios de coronavirus.<\/p>\n<p>El regreso llega con una novedad que beneficiar\u00e1 a muchos cordobeses que se trasladan en transporte p\u00fablico. El Gobierno de C\u00f3rdoba inform\u00f3 que&nbsp;<strong>desde este 17 de febrero ya se puede tramitar el Boleto Educativo Gratuito<\/strong>&nbsp;(BEG).<\/p>\n<p>Para obtenerlo o renovarlo, deber\u00e1n completar el&nbsp;<strong><a href=\"https:\/\/www.cba.gov.ar\/boletos-gratuitos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Formulario \u00danico de Postulantes (FUP) a trav\u00e9s de Ciudadano Digital<\/a><\/strong>.&nbsp;A partir de la puesta en marcha de un sistema de asistencia mixta presencial y virtual en las instituciones educativas, el beneficio otorgar\u00e1 la cantidad de pasajes necesarios en funci\u00f3n de los d\u00edas de asistencia presencial.&nbsp;<\/p>\n<p><em><strong><a rel=\"noreferrer noopener\" href=\"http:\/\/eldoce.tv\/politica\/regreso-aula-clases-presenciales-alberto-fernandez-prometio-vacunar-coronavirus-docentes-antes-posible_109530\" target=\"_blank\">\u201d<\/a><\/strong><\/em><\/p>\n<p>Aquellas personas que no puedan inscribirse de manera online, podr\u00e1n consultar a la Secretar\u00eda de Transporte (0800-888-1234 de Atenci\u00f3n al Ciudadano de lunes a viernes, de 8 a 20).<\/p>\n<div id=\"jp-post-flair\" class=\"sharedaddy sd-like-enabled sd-sharing-enabled\">\n<div class=\"sharedaddy sd-sharing-enabled\">\n<div class=\"robots-nocontent sd-block sd-social sd-social-icon-text sd-sharing\">\n<h3 class=\"sd-title\">Share this:<\/h3>\n<\/div>\n<\/div>\n<div class=\"sharedaddy sd-block sd-like jetpack-likes-widget-wrapper jetpack-likes-widget-unloaded\" id=\"like-post-wrapper-143108178-5004-602d3cc10797c\" data-src=\"\/\/widgets.wp.com\/likes\/index.html?ver=20200826#blog_id=143108178&amp;post_id=5004&amp;origin=cordobanewsnet.wordpress.com&amp;obj_id=143108178-5004-602d3cc10797c\" data-name=\"like-post-frame-143108178-5004-602d3cc10797c\">\n<h3 class=\"sd-title\">Me gusta esto:<\/h3>\n<p><span class=\"button\"><span>Me gusta<\/span><\/span> <span class=\"loading\">Cargando&#8230;<\/span><\/p>\n<p><span class=\"sd-text-color\"><\/span><\/div>\n<p><h3 class=\"jp-relatedposts-headline\"><em>Relacionado<\/em><\/h3>\n<\/p>\n<\/div><\/div>\n<p><!--\/.post-content--> <\/p>\n<footer class=\"post-meta-container clear\" readability=\"0.4047619047619\">\n<div class=\"entry-author author-avatar-show\" readability=\"13.114754098361\">\n<div class=\"author-avatar\"> <img loading=\"lazy\" alt src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/02\/enterate-todo-sobre-la-vuelta-del-boleto-educativo-gratuito.png\" class=\"avatar avatar-90\" height=\"90\" width=\"90\"> <\/div>\n<p><!-- .author-avatar --> <\/p>\n<p><h2 class=\"author-title\">Publicado por <span class=\"author-name\">Redacci\u00f3n<\/span><\/h2>\n<\/p>\n<p><!-- .author-heading --> <\/p>\n<p class=\"author-bio\"> <a class=\"author-link\" href=\"https:\/\/cordobanewsnet.wordpress.com\/author\/prettomatias\/\" rel=\"author\"> Ver todas las entradas de Redacci\u00f3n <\/a> <\/p>\n<p><!-- .author-bio --> <\/div>\n<p><!-- .entry-auhtor --> <\/footer>\n<p> <!-- \/post-meta-container --> <!-- #respond --> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 1\u00ba de marzo inician las clases y la asistencia ser\u00e1 obligatoria. Despu\u00e9s de un a\u00f1o de educaci\u00f3n virtual, alumnos y docentes se vuelven a reencontrar en el aula con protocolos para evitar contagios de coronavirus. El regreso llega con una novedad que beneficiar\u00e1 a muchos cordobeses que se trasladan en transporte p\u00fablico. El Gobierno [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1106,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/1105"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=1105"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/1105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/1106"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=1105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=1105"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=1105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}