{"id":1111,"date":"2021-02-17T16:14:56","date_gmt":"2021-02-17T16:14:56","guid":{"rendered":"https:\/\/es.digitaltrends.com\/?p=787828"},"modified":"2021-02-17T16:14:56","modified_gmt":"2021-02-17T16:14:56","slug":"asi-es-el-look-de-emma-stone-como-cruella-de-vil","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/02\/17\/asi-es-el-look-de-emma-stone-como-cruella-de-vil\/","title":{"rendered":"As\u00ed es el look de Emma Stone como Cruella de Vil"},"content":{"rendered":"<div><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/02\/asi-es-el-look-de-emma-stone-como-cruella-de-vil.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p><span>Brillante, malvada y un poco loca. As\u00ed es como Disney describe la interpretaci\u00f3n de Emma Stone como Cruella de Vil en la pel\u00edcula que se estrenar\u00e1 en mayo pr\u00f3ximo, y de la que hoy vemos su primer tr\u00e1iler.<\/span><\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/gmRKv7n2If8\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\">[embedded content]<\/iframe><\/p>\n<p><span>De las im\u00e1genes vistas en el primer avance se desprende que en la nueva <\/span><i><span>live action<\/span><\/i><span> de Disney mostrar\u00e1 a una Cruella con menos glamour que la interpretada por la actriz Glenn Close en 1996. Eso no quiere que la personificaci\u00f3n de Stone no est\u00e9 cuidada, pues del personaje se ven claras influencias de la est\u00e9tica punk de la dise\u00f1adora Vivianne Westwood. Las referencias no son una casualidad. La sinopsis de la pel\u00edcula la ubica en el Londres de los a\u00f1os 70, en la v\u00edspera del nacimiento del movimiento punk en el 77. Parte de la trama se inserta en este contexto, pues la protagonista es una dise\u00f1adora de nombre Estella que, por alguna raz\u00f3n, enloquece hasta convertirse en Cruella.<\/span><\/p>\n<p><span>Sobre la trama de la pel\u00edcula, se sabe que <\/span><i><span>Cruella<\/span><\/i><span> ser\u00e1 una especie de precuela a <\/span><i><span>101 D\u00e1lmatas<\/span><\/i><span>, en la que se contar\u00e1 la historia que dio origen a la odiosa villana obsesionada con los abrigos de piel.<\/span><\/p>\n<p><span>Por ahora, el estreno de <\/span><i><span>Cruella <\/span><\/i><span>se mantiene para el pr\u00f3ximo 28 de mayo. La pel\u00edcula tambi\u00e9n tendr\u00e1 las actuaciones de Emma Thompson, Paul Walter Hauser y Joel Fry, todos bajo la direcci\u00f3n de Craig Gillespie. Se prev\u00e9 que la pel\u00edcula llegue a los cines, sin embargo, como ya ha ocurrido con otras producciones, su estreno podr\u00eda verse aplazado por la pandemia del COVID-19, lo que podr\u00eda convertirla en otra producci\u00f3n de alto presupuesto limitada a <a href=\"https:\/\/es.digitaltrends.com\/entretenimiento\/mejores-series-en-disney-plus\/\">un estreno en Disney Plus<\/a>.<\/span><\/p>\n<h4 class=\"h-editors-recs-title\"> Recomendaciones del editor\t<\/h4>\n<p> <span id=\"publisher-md\" itemprop=\"publisher\" itemscope itemtype=\"https:\/\/schema.org\/Organization\"> <span itemprop=\"url\" itemtype=\"https:\/\/schema.org\/Url\" content=\"https:\/\/es.digitaltrends.com\"> <span itemprop=\"logo\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"> <meta itemprop=\"url\" content=\"https:\/\/cdn.dtcn.com\/dt\/dt-logo-small.png\"> <meta itemprop=\"width\" content=\"0\"> <meta itemprop=\"height\" content=\"0\"> <\/span> <meta itemprop=\"name\" content=\"Digital Trends Espa\u00f1ol\"> <\/span> <span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"> <meta itemprop=\"url\" content=\"https:\/\/icdn2.digitaltrends.com\/image\/digitaltrends_es\/emma-stone-cruella.jpg\"> <\/span> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brillante, malvada y un poco loca. As\u00ed es como Disney describe la interpretaci\u00f3n de Emma Stone como Cruella de Vil en la pel\u00edcula que se estrenar\u00e1 en mayo pr\u00f3ximo, y de la que hoy vemos su primer tr\u00e1iler. [embedded content] De las im\u00e1genes vistas en el primer avance se desprende que en la nueva live [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1112,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/1111"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=1111"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/1111\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/1112"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=1111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=1111"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=1111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}