{"id":1127,"date":"2021-02-17T16:36:13","date_gmt":"2021-02-17T16:36:13","guid":{"rendered":"https:\/\/puntoapunto.com.ar\/?p=273154"},"modified":"2021-02-17T16:36:13","modified_gmt":"2021-02-17T16:36:13","slug":"el-gobierno-acuso-a-grandes-empresas-por-generar-desabastecimiento","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/02\/17\/el-gobierno-acuso-a-grandes-empresas-por-generar-desabastecimiento\/","title":{"rendered":"El Gobierno acus\u00f3 a grandes empresas por generar desabastecimiento"},"content":{"rendered":"<div><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/02\/el-gobierno-acuso-a-grandes-empresas-por-generar-desabastecimiento.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>\u201cLas imputaciones se realizaron luego de verificar que estas empresas&nbsp;<strong>habr\u00edan incumplido la intimaci\u00f3n a incrementar su producci\u00f3n hasta el m\u00e1s alto grado de su capacidad instalada y arbitrar los medios a su alcance para asegurar su transporte y distribuci\u00f3n con el fin de satisfacer la demanda<\/strong>, establecida por la resoluci\u00f3n 100\/2020\u201d, inform\u00f3 Comercio Interior en un comunicado.<\/p>\n<p>En rigor, esta resoluci\u00f3n, que establece el marco legal para la implementaci\u00f3n de los <a href=\"https:\/\/puntoapunto.com.ar\/wp-admin\/post.php?post=272194&amp;action=edit\">Precios M\u00e1ximos<\/a>; \u201ctiene como finalidad proteger a las y los consumidores de posibles abusos en los precios y garantizar el normal abastecimiento de productos en supermercados\u201d.<\/p>\n<p>Durante las fiscalizaciones realizadas en comercios, inspectores de la Subsecretar\u00eda \u201cidentificaron algunos faltantes en g\u00f3ndolas de productos de consumo masivo\u201d.<\/p>\n<h4>Los detalles<\/h4>\n<p>A partir de esta evidencia, \u201cse realizaron inspecciones en las oficinas administrativas de diversas empresas proveedoras. Esto que deriv\u00f3 en distintos requerimientos de informaci\u00f3n sobre stocks e inventarios durante noviembre y diciembre de 2020, y enero de 2021\u201d.<\/p>\n<p>\u201cDel an\u00e1lisis de la informaci\u00f3n remitida por las empresas se comprob\u00f3 una importante ca\u00edda de la producci\u00f3n o en la distribuci\u00f3n de diversas gamas de productos\u201d, indic\u00f3 el \u00e1rea que conduce Paula Espa\u00f1ol.<\/p>\n<h4>Las marcas y sus productos<\/h4>\n<p>Por ejemplo, en la empresa multinacional&nbsp;<strong>Unilever<\/strong>, que elabora alimentos, art\u00edculos de limpieza e higiene personal,&nbsp;<strong>\u201cse detect\u00f3 una ca\u00edda de casi el 100% en su inventario de aderezos\u201d<\/strong>, precis\u00f3 Comercio Interior.<\/p>\n<p>En la multinacional alimenticia&nbsp;<strong>Danone<\/strong>, por su parte, \u201cse corrobor\u00f3 una&nbsp;<strong>disminuci\u00f3n relevante en la producci\u00f3n y despacho de quesos cremas y postres<\/strong>&nbsp;durante el trimestre relevado\u201d.<\/p>\n<p>En la compa\u00f1\u00eda multinacional&nbsp;<strong>Procter &amp; Gamble (P&amp;G)<\/strong>, que elabora productos de limpieza y para el cuidado personal, \u201cse identificaron una&nbsp;<strong>reducci\u00f3n importante en el stock de varias presentaciones de productos de marcas emblem\u00e1ticas de pa\u00f1ales y detergentes<\/strong>\u201d.<\/p>\n<p>La panificadora y elaboradora de pastas&nbsp;<strong>Fargo<\/strong>&nbsp;\u201ctambi\u00e9n evidenci\u00f3 una&nbsp;<strong>reducci\u00f3n en el stock de diversas presentaciones de ravioles y \u00f1oquis<\/strong>,&nbsp;<strong>tapas de empanadas y de pan lactal<\/strong>&nbsp;en todas sus variedades\u201d.<\/p>\n<p>En aceites, la empresa local&nbsp;<strong>Aceitera General Deheza (AGD)<\/strong>&nbsp;\u201cacredit\u00f3 una&nbsp;<strong>baja de inventario<\/strong>&nbsp;en su totalidad de marcas y presentaciones\u201d.<\/p>\n<p>En la empresa <strong>Molinos R\u00edo de la Plata<\/strong>&nbsp;\u201cse relev\u00f3 una&nbsp;<strong>importante reducci\u00f3n de inventarios de harinas<\/strong>, productos a base de arroz, arroz y aceites\u201d.<\/p>\n<p><strong>Bunge<\/strong>, compa\u00f1\u00eda global de agronegocios, \u201ctambi\u00e9n se corrobor\u00f3 una&nbsp;<strong>baja en el despacho de aceites envasados<\/strong>&nbsp;y una variaci\u00f3n negativa de stocks de harinas\u201d.<\/p>\n<p>Por \u00faltimo la l\u00e1ctea&nbsp;<strong>Mastellone<\/strong>, la distribuidora de golosinas Potigian; la empresa regional de alimentos agroindustriales Molinos Ca\u00f1uelas y el frigor\u00edfico Paladini \u201cno aportaron la informaci\u00f3n con el detalle requerido para realizar un an\u00e1lisis completo de imputadas por este motivo\u201d.<\/p>\n<p>\u201cSe verific\u00f3 una reducci\u00f3n de la producci\u00f3n o en la distribuci\u00f3n de alimentos, bebidas, productos de higiene personal y limpieza que incumplen con lo establecido en la resoluci\u00f3n 100 y modificatorias. L<strong>as imputaciones intiman a las empresas para que en el plazo perentorio de 5 d\u00edas h\u00e1biles acredite ante la Subsecretar\u00eda de modo fehaciente haber dado cabal cumplimiento a la norma.<\/strong> Adem\u00e1s se les requiere que restablezcan los niveles de stock registrados a noviembre 2020; y arbitren las medidas conducentes para asegurar el transporte y provisi\u00f3n de los productos para su efectiva comercializaci\u00f3n\u201d, remarc\u00f3 Comercio Interior.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLas imputaciones se realizaron luego de verificar que estas empresas&nbsp;habr\u00edan incumplido la intimaci\u00f3n a incrementar su producci\u00f3n hasta el m\u00e1s alto grado de su capacidad instalada y arbitrar los medios a su alcance para asegurar su transporte y distribuci\u00f3n con el fin de satisfacer la demanda, establecida por la resoluci\u00f3n 100\/2020\u201d, inform\u00f3 Comercio Interior en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1128,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/1127"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=1127"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/1127\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/1128"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=1127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=1127"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=1127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}