{"id":1294,"date":"2021-02-22T19:23:37","date_gmt":"2021-02-22T19:23:37","guid":{"rendered":"http:\/\/nuevacordoba.net\/index.php\/2021\/02\/22\/manifiesto-detras-del-mitico-encuentro-entre-trotsky-y-breton\/"},"modified":"2021-02-22T19:23:37","modified_gmt":"2021-02-22T19:23:37","slug":"manifiesto-detras-del-mitico-encuentro-entre-trotsky-y-breton","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/02\/22\/manifiesto-detras-del-mitico-encuentro-entre-trotsky-y-breton\/","title":{"rendered":"\u00abManifiesto\u00bb, detr\u00e1s del m\u00edtico encuentro entre Trotsky y Breton"},"content":{"rendered":"<div class=\"image\" id=\"image\" readability=\"8\"> <img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/02\/manifiesto-detras-del-mitico-encuentro-entre-trotsky-y-breton.jpg\" alt=\"&quot;Manifiesto&quot; es la tercera obra de Rath, autor de &quot;\u00bfQui\u00e9n mat\u00f3 a Mariano Ferreyra?&quot; y &quot;Alicia&quot;.\" title=\"&quot;Manifiesto&quot; es la tercera obra de Rath, autor de &quot;\u00bfQui\u00e9n mat\u00f3 a Mariano Ferreyra?&quot; y &quot;Alicia&quot;.\"><\/p>\n<p>\u00abManifiesto\u00bb es la tercera obra de Rath, autor de \u00ab\u00bfQui\u00e9n mat\u00f3 a Mariano Ferreyra?\u00bb y \u00abAlicia\u00bb.<\/p>\n<\/div>\n<p>\u00abManifiesto\u00bb, tercera pel\u00edcula de Alejandro Rath, aborda de forma l\u00fadica y en tono de ensayo el encuentro entre Le\u00f3n Trotsky y Andre Breton de 1938, en un filme que se puede ver a partir de este martes gratis en Cine.ar Play y el viernes a las 22 en Canal Encuentro.<\/p>\n<p>\u00abInteresado en el desaf\u00edo de desarrollar cinematogr\u00e1ficamente debates e ideas sobre la relaci\u00f3n entre el arte y la pol\u00edtica, que rondan mi cabeza cotidianamente, fui escribiendo ideas sueltas, escenas inconexas, peque\u00f1as vi\u00f1etas\u00bb, dijo a T\u00e9lam <strong>el realizador de \u00ab\u00bfQui\u00e9n mat\u00f3 a Mariano Ferreyra?\u00bb y \u00abAlicia\u00bb.<\/strong><\/p>\n<blockquote readability=\"6\">\n<p>Pompeyo Audivert es el revolucionario ruso e Iv\u00e1n Moschner es el escritor surrealista franc\u00e9s. Ambos se re\u00fanen en una casa enclavada en un bosque costero.<span class=\"comilla\">\u201d<\/span><\/p>\n<\/blockquote>\n<p>Aislados y sin internet, deben componer a sus personajes. La presi\u00f3n que se ejercen entre ambos comienza a romper la delgada l\u00ednea entre el int\u00e9rprete y la interpretaci\u00f3n, y all\u00ed, entre enso\u00f1aciones, piensan como trasladar al mundo del arte la acci\u00f3n y libertad pol\u00edtica.<\/p>\n<p><strong>\u00abEl trabajo fue de una profundidad e intensidad que al mismo tiempo no perdi\u00f3 nunca su car\u00e1cter l\u00fadico y libre<\/strong>. Sobre la base de una selecci\u00f3n de textos de la \u00e9poca, escribimos escenas tanto en la previa al rodaje como en el rodaje mismo. A medida que avanz\u00e1bamos en el rodaje \u00edbamos debatiendo con Iv\u00e1n, Pompeyo y con todo el equipo, reflexionando y escribiendo nuevas escenas\u00bb, coment\u00f3 Rath.<\/p>\n<p>As\u00ed, junto a Gabriela Cabez\u00f3n C\u00e1mara, C\u00e9sar Gonz\u00e1lez, Mar\u00eda Negro y Adriana de los Santos desarrollaron varias ideas m\u00e1s, que cruzaron con los debates de Trotsky y Breton \u00abdefiniendo los dispositivos esc\u00e9nicos en los que esos cruces pod\u00edan darse\u00bb.<\/p>\n<div class=\"image-left\" readability=\"8\"> <img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/02\/manifiesto-detras-del-mitico-encuentro-entre-trotsky-y-breton-1.jpg\" alt=\"El filme de Alejandro Rath, en pleno rodaje.\" title=\"El filme de Alejandro Rath, en pleno rodaje.\"><\/p>\n<p>El filme de Alejandro Rath, en pleno rodaje.<\/p>\n<\/div>\n<p><strong>-Rath, \u00bfcu\u00e1l cre\u00e9s fue la importancia del encuentro entre Breton y Trotsky?<\/strong><\/p>\n<p>-El encuentro se da en un momento crucial de la historia. Unos a\u00f1os antes de la segunda guerra mundial, cuando el avance del nazismo presagiaba ese estallido, y mientras en la Rusia sovi\u00e9tica el estalinismo ya hab\u00eda avanzado fuertemente en su proceso de degeneraci\u00f3n de los principios de la revoluci\u00f3n. En ese contexto, artistas de todo el mundo justificaban, hac\u00edan la vista gorda o directamente eran parte del \u201crealismo socialista\u201d mientras se suced\u00edan los asesinatos y la persecuci\u00f3n a cualquier tipo de oposici\u00f3n pol\u00edtica al r\u00e9gimen. Las conclusiones de los debates del \u201c\u00c1guila y el Le\u00f3n\u201d en torno a la defensa incondicional de la libertad para la creaci\u00f3n art\u00edstica son todav\u00eda hoy un llamado de atenci\u00f3n respecto de los peligros que representa la burocratizaci\u00f3n de un proceso revolucionario para el arte.<\/p>\n<p><strong>-Pareciera haber un contraste entre el pasar acomodado en una casa en el bosque entre \u00abBreton\u00bb y \u00abTrotsky\u00bb y la vida del operario al que ellos dicen representar.<\/strong><\/p>\n<p>-La elecci\u00f3n de la casa y de la costa argentina en pleno invierno tiene que ver con la b\u00fasqueda de colocar a los personajes en un espacio abstracto para el desarrollo de un trabajo intelectual profundo. Evidentemente esto contrasta con la construcci\u00f3n del espacio del obrero que interpreta C\u00e9sar. Pero ese contraste no pretende ser una cr\u00edtica al lugar que ocupan Trotsky y Breton, sino m\u00e1s bien una denuncia de la imposibilidad del desarrollo de una producci\u00f3n intelectual o art\u00edstica libre en las condiciones de vida cada vez peores que le impone el capitalismo a las masas.<\/p>\n<p><strong>-\u00bfCre\u00e9s que, m\u00e1s all\u00e1 de las ideolog\u00edas, las elites gobernantes se encuentran disociadas de la vida cotidiana y la necesidad de las personas?<\/strong><\/p>\n<p>-Creo que el problema es la organizaci\u00f3n social, el capitalismo. Un sistema que est\u00e1 basado en el lucro antes que en las necesidades de las personas y en la relaci\u00f3n de cuidado de estas personas con la naturaleza no tiene mucho m\u00e1s para entregarnos, salvo hundirnos progresivamente en la barbarie. La experiencia con las vacunas para prevenir el coronavirus es muy ilustrativa, en lugar de propiciar la circulaci\u00f3n del conocimiento cient\u00edfico, hacen uso del secreto para mejorar sus perspectivas de negocio y est\u00e1n en una carrera que tiene m\u00e1s que ver con un c\u00e1lculo econ\u00f3mico que con el bienestar de la humanidad. Las consecuencias est\u00e1n a la vista, el mayor porcentaje de las vacunas disponibles en el mundo est\u00e1 concentrado en unos pocos pa\u00edses, casualmente los m\u00e1s poderosos.<\/p>\n<p><strong>-\u00bfCu\u00e1l fue el desaf\u00edo que encontraste en realizar esta pel\u00edcula?<\/strong><\/p>\n<p>-El desaf\u00edo principal era encontrar la forma para representar textos muy literarios e ideas complejas de una manera atractiva y cinematogr\u00e1fica. Tambi\u00e9n trabajar una construcci\u00f3n de \u00e9poca con muy poco presupuesto. Fueron claves las referencias del surrealismo para superar estos problemas, trabajar con la idea de los sue\u00f1os y el inconsciente. C\u00f3mo estos actores que ensayan textos dif\u00edciles van siendo tomados por sus personajes a partir del trabajo de repetici\u00f3n y abstracci\u00f3n, intentando acceder a un nuevo nivel de realidad o representaci\u00f3n. Todo esto era un salto al vac\u00edo en muchos sentidos y hubo cosas que funcionaron mejor que otras, pero la clave fue trabajar con libertad y abiertos a que las ideas y preconceptos se transformen permanentemente. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abManifiesto\u00bb es la tercera obra de Rath, autor de \u00ab\u00bfQui\u00e9n mat\u00f3 a Mariano Ferreyra?\u00bb y \u00abAlicia\u00bb. \u00abManifiesto\u00bb, tercera pel\u00edcula de Alejandro Rath, aborda de forma l\u00fadica y en tono de ensayo el encuentro entre Le\u00f3n Trotsky y Andre Breton de 1938, en un filme que se puede ver a partir de este martes gratis en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1295,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/1294"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=1294"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/1294\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/1295"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=1294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=1294"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=1294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}