{"id":1400,"date":"2021-02-22T22:16:33","date_gmt":"2021-02-22T22:16:33","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-ascenso\/quilmes-culio_0_u1wRAETJO.html"},"modified":"2021-02-22T22:16:33","modified_gmt":"2021-02-22T22:16:33","slug":"la-tormenta-ya-paso-estoy-feliz","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/02\/22\/la-tormenta-ya-paso-estoy-feliz\/","title":{"rendered":"\u00abLa tormenta ya pas\u00f3, estoy feliz\u00bb"},"content":{"rendered":"<div><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/02\/la-tormenta-ya-paso-estoy-feliz.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>La cabeza de un jugador de f\u00fatbol gira m\u00e1s all\u00e1 de una pelota. Detr\u00e1s de los peinados modernos, los ca\u00f1os y los gritos de gol, existe una persona con sentimientos: un hombre de carne y hueso que piensa, razona y siente. Algunos lo pueden expresar con palabras para ser contenido y otro no. A veces no es sencillo tomar decisiones en medio de la vor\u00e1gine del exitismo del deporte y la demanda de los hinchas. Emmanuel Culio sinti\u00f3 en noviembre del a\u00f1o pasado que su cuerpo necesitaba desconectarse, parar la pelota y atender cuestiones m\u00e1s importantes para volver con m\u00e1s fuerza y ganas. Le demand\u00f3 unos meses, pero el volante de 37 a\u00f1os ya est\u00e1 listo para mentalizarse en el sue\u00f1o de Quilmes de volver a Primera.<\/p>\n<p>Faltaban pocas semanas para que iniciara la definici\u00f3n de la PN, cuando el futbolista le hizo el click. \u00bfEl motivo? Con su mujer afectada por una enfermedad, \u00e9l habl\u00f3 con la dirigencia y Facundo Sava para tomarse una licencia sin goce de sueldo y enfocarse en el dif\u00edcil momento que se encontraba atravesando su familia. \u201cRecuerdo que tom\u00e9 la decisi\u00f3n tras el partido amistoso contra Platense, en el que me fui expulsado y pate\u00e9 una silla. Era extra\u00f1o porque yo no tengo ese temperamento\u201d, asegur\u00f3.<\/p>\n<p>Culio sostuvo que tom\u00f3 la postura ya que \u201cten\u00eda que ser sincero conmigo mismo\u201d y debido a que \u201cno le serv\u00eda al equipo\u201d. Sin embargo, esos momentos complicados quedaron en el pasado. \u201cEstoy muy feliz. Esta todo mucho mejor y por eso estoy regres\u00e9. Para m\u00ed lo primero siempre es la familia. La tormenta ya pas\u00f3 y quedan uno o dos pasitos m\u00e1s\u201d, cont\u00f3 en Radio FMQ.<\/p>\n<p>En su retorno, el mediocampista se volvi\u00f3 a ganar la consideraci\u00f3n del entrenador, m\u00e1s all\u00e1 de los meses de inactividad. Claro, con una extensa carrera por Europa, donde supo jugar en el Cluj de Rumania, Deportivo La Coru\u00f1a, Zaragoza y Mallorca, su experiencia es fundamental en el armando que pretende el Colo. As\u00ed es que en el primer amistoso de pretemporada (ca\u00edda 1-0 ante Talleres de Escalada), Emmanuel fue titular. Casi como un nuevo refuerzo.<\/p>\n<div class=\"entry-tags\">\n<h2>TEMAS QUE APARECEN EN ESTA NOTA<\/h2>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La cabeza de un jugador de f\u00fatbol gira m\u00e1s all\u00e1 de una pelota. Detr\u00e1s de los peinados modernos, los ca\u00f1os y los gritos de gol, existe una persona con sentimientos: un hombre de carne y hueso que piensa, razona y siente. Algunos lo pueden expresar con palabras para ser contenido y otro no. A veces [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1401,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/1400"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=1400"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/1400\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/1401"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=1400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=1400"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=1400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}