{"id":23839,"date":"2022-08-31T23:07:54","date_gmt":"2022-08-31T23:07:54","guid":{"rendered":"https:\/\/es.digitaltrends.com\/?p=959430"},"modified":"2022-08-31T23:07:54","modified_gmt":"2022-08-31T23:07:54","slug":"la-biopic-de-milli-vanilli-tiene-su-primer-adelanto","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2022\/08\/31\/la-biopic-de-milli-vanilli-tiene-su-primer-adelanto\/","title":{"rendered":"La biopic de Milli Vanilli tiene su primer adelanto"},"content":{"rendered":"<p>Se hicieron famosos en los a\u00f1os noventa, y su \u00e9xito lleg\u00f3 de la mano de canciones como <em>Girl You Know It\u2019s True, <\/em>que justamente da nombre a la&nbsp;<a href=\"https:\/\/es.digitaltrends.com\/entretenimiento\/mike-mas-alla-de-tyson-trailer\/\"><strong>biopic<\/strong><\/a> que contar\u00e1 la historia de Robert Pilatus y Fabrice Morvan, el duo Milli Vanilli.<\/p>\n<p>Y este 31 de agosto se revelaron las primeras im\u00e1genes de la producci\u00f3n, que tiene a Tijan Njie y Elan Ben Ali que interpretar\u00e1n los respectivos papeles principales de Pilatus y Morvan. Matthias Schweigh\u00f6fer interpreta al productor musical alem\u00e1n Frank Farian. El elenco tambi\u00e9n incluye a Graham Rogers como el asistente estadounidense de Milli Vanilli, Todd, y Bella Dayne como Milli, la mano derecha de Farian.<\/p>\n<p><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/la-biopic-de-milli-vanilli-tiene-su-primer-adelanto.gif\" data-dt-lazy-src=\"https:\/\/es.digitaltrends.com\/wp-content\/uploads\/2022\/08\/Captura-web_31-8-2022_1957_deadline.com_.jpeg?fit=720%2C407&amp;p=1\" onerror=\"dti_load_error(this)\" class=\"alignnone size-large wp-image-959471 dt-lazy-load dt-lazy-pending\" alt> <img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/la-biopic-de-milli-vanilli-tiene-su-primer-adelanto.gif\" data-dt-lazy-src=\"https:\/\/es.digitaltrends.com\/wp-content\/uploads\/2022\/08\/Captura-web_31-8-2022_19044_deadline.com_.jpeg?fit=720%2C392&amp;p=1\" onerror=\"dti_load_error(this)\" class=\"alignnone size-large wp-image-959472 dt-lazy-load dt-lazy-pending\" alt><\/p>\n<p>Simon Verhoeven est\u00e1 dirigiendo <a href=\"https:\/\/es.digitaltrends.com\/entretenimiento\/peliculas-mas-esperadas-2022\/\"><strong>la pel\u00edcula<\/strong><\/a>, con Quirin Berg y Max Wiedemann produciendo.<\/p>\n<p>\u00ab<em>Girl You Know It\u2019s True&nbsp;<\/em>se centra en la historia real del notorio esc\u00e1ndalo que involucra a los bailarines Pilatus y el ascenso a la fama de Morvan a fines de la d\u00e9cada de 1980 como la sensaci\u00f3n pop Milli Vanilli. Orquestados por Farian, se convierten en estrellas mundiales con tres \u00e9xitos No. 1 en los Estados Unidos e incluso ganaron un Grammy. Pero solo un peque\u00f1o c\u00edrculo de conocedores sab\u00eda que el d\u00fao nunca cant\u00f3 una palabra de sus canciones. Cuando finalmente se revel\u00f3 la verdad, miraron al abismo en el centro de uno de los mayores esc\u00e1ndalos en la historia de la m\u00fasica\u00bb, dice la sinopsis.<\/p>\n<h4 class=\"b-editors-recs-title h-editors-recs-title\"> Recomendaciones del editor\t<\/h4>\n<p> <span id=\"publisher-md\" itemprop=\"publisher\" itemscope itemtype=\"https:\/\/schema.org\/Organization\"> <span itemprop=\"url\" itemtype=\"https:\/\/schema.org\/Url\" content=\"https:\/\/es.digitaltrends.com\"> <span itemprop=\"logo\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"> <meta itemprop=\"url\" content=\"https:\/\/cdn.dtcn.com\/dt\/dt-logo-small.png\"> <meta itemprop=\"width\" content=\"0\"> <meta itemprop=\"height\" content=\"0\"> <\/span> <meta itemprop=\"name\" content=\"Digital Trends Espa\u00f1ol\"> <\/span> <span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"> <meta itemprop=\"url\" content=\"https:\/\/es.digitaltrends.com\/wp-content\/uploads\/2022\/08\/Captura-web_31-8-2022_19044_deadline.com_.jpeg?p=1\"> <\/span> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se hicieron famosos en los a\u00f1os noventa, y su \u00e9xito lleg\u00f3 de la mano de canciones como Girl You Know It\u2019s True, que justamente da nombre a la&nbsp;biopic que contar\u00e1 la historia de Robert Pilatus y Fabrice Morvan, el duo Milli Vanilli. Y este 31 de agosto se revelaron las primeras im\u00e1genes de la producci\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23840,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/23839"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=23839"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/23839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/23840"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=23839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=23839"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=23839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}