{"id":23992,"date":"2022-08-31T22:31:11","date_gmt":"2022-08-31T22:31:11","guid":{"rendered":"https:\/\/es.digitaltrends.com\/?p=959433"},"modified":"2022-08-31T22:31:11","modified_gmt":"2022-08-31T22:31:11","slug":"hijo-de-jeff-bezos-y-serie-los-anillos-de-poder-papa-por-favor-no-jodas-esto","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2022\/08\/31\/hijo-de-jeff-bezos-y-serie-los-anillos-de-poder-papa-por-favor-no-jodas-esto\/","title":{"rendered":"Hijo de Jeff Bezos y serie Los Anillos de Poder: \u00abPap\u00e1, por favor no jodas esto\u00bb"},"content":{"rendered":"<p>Alta expectaci\u00f3n en los fan\u00e1ticos existe por el inminente estreno este 2 de septiembre de la serie&nbsp; <em><a href=\"https:\/\/es.digitaltrends.com\/entretenimiento\/los-anillos-de-poder-el-senor-de-los-anillos-guia-tierra-media\/\"><strong>El Se\u00f1or de los Anillos: Los Anillos de Poder<\/strong><\/a>. <\/em>Y tanto es as\u00ed que <a href=\"https:\/\/es.digitaltrends.com\/negocios\/jeff-bezos-primer-anuncio-empleo-amazon\/\"><strong>Jeff Bezos<\/strong><\/a>, m\u00e1ximo due\u00f1o de Amazon, no pod\u00eda estar ajeno al lanzamiento en su modo avant-premier.<\/p>\n<p>En la oportunidad, el tambi\u00e9n accionista mayoritario del Washington Post, cont\u00f3 varias an\u00e9cdotas en relaci\u00f3n a este producto, el m\u00e1s caro y ambicioso en la era del streaming.<\/p>\n<figure class=\"alignnone\"><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/hijo-de-jeff-bezos-y-serie-los-anillos-de-poder-papa-por-favor-no-jodas-esto.gif\" data-dt-lazy-src=\"https:\/\/es.digitaltrends.com\/wp-content\/uploads\/2022\/07\/Captura-web_6-7-2022_113255_www.latercera.com_.jpeg?fit=720%2C452&amp;p=1\" onerror=\"dti_load_error(this)\" class=\" size-large wp-image-952293 dt-lazy-load dt-lazy-pending\" alt><\/figure>\n<p>\u00abMi hijo es un gran fan de Tolkien y despu\u00e9s de que Amazon se involucr\u00f3, se acerc\u00f3 a m\u00ed, me mir\u00f3 a los ojos y me dijo: \u2018Pap\u00e1, por favor, no jodas esto&#8217;\u00bb.<\/p>\n<p>Bezos concluy\u00f3 r\u00e1pidamente con una cita de Tolkien, proclamando: \u00abNo todos los que vagan est\u00e1n perdidos\u00bb.<\/p>\n<p>Pero el due\u00f1o de Amazon adem\u00e1s agradeci\u00f3 a los showrunners de la serie \u00abignorarme exactamente en los momentos correctos\u00bb cuando estaba dando notas sobre los primeros guiones.<\/p>\n<p>\u00abEl sue\u00f1o de todos los showrunners es obtener notas sobre los primeros guiones y cortes del presidente ejecutivo, simplemente les encanta eso\u00bb, brome\u00f3. \u00abQuiero agradecerles a ambos por escuchar cada vez que ayud\u00f3, pero sobre todo necesito agradecerles por ignorarme exactamente en los momentos correctos\u00bb.<\/p>\n<h4 class=\"b-editors-recs-title h-editors-recs-title\"> Recomendaciones del editor\t<\/h4>\n<p> <span id=\"publisher-md\" itemprop=\"publisher\" itemscope itemtype=\"https:\/\/schema.org\/Organization\"> <span itemprop=\"url\" itemtype=\"https:\/\/schema.org\/Url\" content=\"https:\/\/es.digitaltrends.com\"> <span itemprop=\"logo\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"> <meta itemprop=\"url\" content=\"https:\/\/cdn.dtcn.com\/dt\/dt-logo-small.png\"> <meta itemprop=\"width\" content=\"0\"> <meta itemprop=\"height\" content=\"0\"> <\/span> <meta itemprop=\"name\" content=\"Digital Trends Espa\u00f1ol\"> <\/span> <span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"> <meta itemprop=\"url\" content=\"https:\/\/es.digitaltrends.com\/wp-content\/uploads\/2022\/08\/los-anillos-de-poder-jeff-bezos.jpg?p=1\"> <\/span> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alta expectaci\u00f3n en los fan\u00e1ticos existe por el inminente estreno este 2 de septiembre de la serie&nbsp; El Se\u00f1or de los Anillos: Los Anillos de Poder. Y tanto es as\u00ed que Jeff Bezos, m\u00e1ximo due\u00f1o de Amazon, no pod\u00eda estar ajeno al lanzamiento en su modo avant-premier. En la oportunidad, el tambi\u00e9n accionista mayoritario del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23993,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/23992"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=23992"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/23992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/23993"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=23992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=23992"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=23992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}