{"id":24006,"date":"2022-09-06T01:45:00","date_gmt":"2022-09-06T01:45:00","guid":{"rendered":"http:\/\/nuevacordoba.net\/index.php\/2022\/09\/06\/este-martes-comienza-el-tango-buenos-aires-festival-y-mundial\/"},"modified":"2022-09-06T01:45:00","modified_gmt":"2022-09-06T01:45:00","slug":"este-martes-comienza-el-tango-buenos-aires-festival-y-mundial","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2022\/09\/06\/este-martes-comienza-el-tango-buenos-aires-festival-y-mundial\/","title":{"rendered":"Este martes comienza el \u00abTango Buenos Aires Festival y Mundial\u00bb"},"content":{"rendered":"<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/este-martes-comienza-el-tango-buenos-aires-festival-y-mundial.jpg\" width=\"100%\" height=\"100%\" alt=\"El festival presentar conciertos exhibiciones homenajes danzas cine videoclips muestras y presentaciones de libros\"><figcaption> El festival presentar\u00e1 conciertos, exhibiciones, homenajes, danzas, cine, videoclips, muestras y presentaciones de libros. <\/figcaption><\/figure>\n<p>La nueva edici\u00f3n del <strong>Tango Buenos Aires Festival y Mundial<\/strong>, que se realizar\u00e1 entre ma\u00f1ana y hasta el domingo 18 de septiembre en 30 sedes porte\u00f1as, presentar\u00e1 conciertos, exhibiciones, homenajes, danzas, cine, videoclips, muestras y presentaciones de libros.<\/p>\n<p><strong>\u201cEl foco de este a\u00f1o est\u00e1 puesto en visibilizar la federalidad que sostiene al tango desde siempre\u201d<\/strong>, expres\u00f3 a T\u00e9lam <strong>Natacha Poberaj<\/strong>, directora art\u00edstica de cl\u00e1sico encuentro que contar\u00e1 <strong>con la participaci\u00f3n de 1500 artistas de todo el pa\u00eds<\/strong>.<\/p>\n<p>La apertura se concretar\u00e1 en el Auditorio de la Usina del Arte este martes, a las 19.30, con <strong>\u201cNoche de leyendas\u201d,<\/strong> un espect\u00e1culo dedicado a las grandes figuras del baile milonguero y a la bailarina <strong>Mar\u00eda Nieves<\/strong>, due\u00f1a de un estilo \u00fanico, en el d\u00eda de su cumplea\u00f1os 88..<\/p>\n<p>Participar\u00e1n <strong>Julio Dupl\u00e1a<\/strong>, milonguero y escritor, que presentar\u00e1 una exhibici\u00f3n con parejas milongueras hist\u00f3ricas: <strong>Nilda y Luis Virtuani, Hayde\u00e9 <\/strong>y<strong> Oscar H\u00e9ctor Malagrino, Monique Larrain<\/strong> y<strong> Sergio De La Rosa, Silvia Mucci <\/strong>y<strong> Juan Alonso, Susana Soar <\/strong>y<strong> Jorge Garc\u00eda, Liliana <\/strong>y<strong> Jorge Rodr\u00edguez; <\/strong>y tambi\u00e9n estar\u00e1 <strong>\u201cPocho\u201d Pizarro,<\/strong> con su famoso baile con las escobas y su cadencia en el tango sal\u00f3n y canyengue.<\/p>\n<p>Luego de cinco a\u00f1os, el cordob\u00e9s <strong>Ariel Ardit<\/strong> cantar\u00e1 en formato de <strong>Sexteto T\u00edpico<\/strong>, dirigido por el arreglador y pianista <strong>Andr\u00e9s Linetzky<\/strong>; e integrado por <strong>Ramiro Boero <\/strong>y<strong> Yuki Okumura<\/strong> en bandoneones, <strong>Pedro Pablo Pedroso <\/strong>y<strong> Carolina Rodr\u00edguez<\/strong> en violines y <strong>Pablo Guzm\u00e1n<\/strong> en contrabajo, junto al que interpretar\u00e1 repertorio grabado en sus discos anteriores.<\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/este-martes-comienza-el-tango-buenos-aires-festival-y-mundial-1.jpg\" width=\"100%\" height=\"100%\" alt=\"Natacha Poberaj El espritu es el una fiesta donde seguimos celebrando la posibilidad de abrazarnos cada vez\"><figcaption> Natacha Poberaj: \u201cEl esp\u00edritu es el una fiesta donde seguimos celebrando la posibilidad de abrazarnos cada vez\u201d. <\/figcaption><\/figure>\n<p><br open> Los conciertos de la <strong>Orquesta T\u00edpica Sans Souci<\/strong> -creada en 1998 con el fin rescatar el estilo musical de las orquestas t\u00edpicas de Miguel Cal\u00f3 y Osmar Maderna-, <strong>Lil\u00ed Gard\u00e9s <\/strong>y<strong> Spinettango<\/strong>, la agrupaci\u00f3n cordobesa<strong> Los Altiyeros,<\/strong> creada por <strong>Dami\u00e1n Torres<\/strong> <strong>Quinteto<\/strong> y el cantor <strong>Santiago Mu\u00f1iz<\/strong> para homenajear en clave tanguera a Luis Alberto Spinetta, son algunos de los atractivos de la grilla.<\/p>\n<p>Tambi\u00e9n se destaca la proyecci\u00f3n de la pel\u00edcula <strong>\u201cNelly Omar, cantora nacional\u201d<\/strong>, dirigida por <strong>Nelly Saporitti<\/strong>, sobrina nieta de Nelly, que se podr\u00e1 ver en El Cultural San Mart\u00edn; se trata de su primera presentaci\u00f3n en una sala de cine.<\/p>\n<p>Vecinos y turistas podr\u00e1n disfrutar del universo de la m\u00fasica de Buenos Aires, en el marco de un festival que incluye la gran final en la calle Diagonal Norte con el Obelisco de fondo que se transmitir\u00e1 para todo el pa\u00eds desde buenosaires.gob.ar\/tangoba, donde tambi\u00e9n est\u00e1 disponible la programaci\u00f3n y podr\u00e1n reservarse la entradas en forma gratuita.<\/p>\n<p>\u201cEl esp\u00edritu es el una fiesta donde seguimos celebrando la posibilidad de abrazarnos cada vez\u201d, dijo Poberaj acerca del encuentro que apunta a ofrecer un panorama de la escena tanguera actual, con figuras consagrados y nuevos exponentes del g\u00e9nero.<\/p>\n<p>Durante este a\u00f1o, se abrieron convocatorias a todo el pa\u00eds donde se postularon m\u00e1s de 300 propuestas art\u00edsticas, de las cuales surgi\u00f3 el 70 por ciento de la programaci\u00f3n de esta edici\u00f3n.<\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/este-martes-comienza-el-tango-buenos-aires-festival-y-mundial-2.jpg\" width=\"100%\" height=\"100%\" alt=\"El martes 13 ser la Gala de las Preliminares en el Auditorio de la Usina del Arte\"><figcaption> El martes 13 ser\u00e1 la Gala de las Preliminares en el Auditorio de la Usina del Arte. <\/figcaption><\/figure>\n<p><br open><strong>\u201cEste encuentro tanguero fue evolucionando a trav\u00e9s de los a\u00f1os gracias al equipo que trabaja desde siempre para que suceda y a la comunidad tanguera y al p\u00fablico que acompa\u00f1a y disfruta cada vez\u201d<\/strong>, reflexion\u00f3 la directora. bailarina profesional, due\u00f1a de una extensa trayectoria, campeona mundial de baile en el 2006.<\/p>\n<p><strong>\u201cEl a\u00f1o pasado salimos adelante valientemente, m\u00e1s all\u00e1 de las dificultades que planteaba la pandemia. Este 2022, con energ\u00edas renovadas, el festival se va a centrar en la promoci\u00f3n y la difusi\u00f3n del tango como hecho cultural en todo su esplendor, entendiendo la importancia del imperdible encuentro tanguero en la Ciudad y el mundo\u201d<\/strong>, agreg\u00f3.<\/p>\n<p>Cerca de cumplirse los 100 a\u00f1os de su construcci\u00f3n,<strong> el Palacio Barolo se suma como sede del festival<\/strong>, y en su hall central tocar\u00e1 este jueves a las 19. de <strong>Del Bajo Quinteto<\/strong>, grupo dedicado a la creaci\u00f3n y difusi\u00f3n del nuevo tango; sus integrantes son estudiantes y egresados de los conservatorios de m\u00fasica Astor Piazzolla y Manuel de Falla.<\/p>\n<p>El martes 13 de septiembre se realizar\u00e1 la <strong>Gala de las Preliminares en el Auditorio de la Usina del Arte<\/strong>; una velada para honrar a las parejas que llegan desde diferentes lugares del pa\u00eds y del mundo. Estos bailarines estar\u00e1n presentes en las Milongas itinerantes del festival (recorriendo 14 pistas porte\u00f1as)., Adem\u00e1s, como todos los a\u00f1os, el festival propone un micr\u00f3fono abierto para los int\u00e9rpretes de tango.<\/p>\n<p>Las rondas clasificatorias del Mundial de Tango se llevar\u00e1n a adelante en la Usina del Arte. La competencia de Tango de Pista se realizar\u00e1 el 9 y 10 de septiembre mientras que Tango Escenario, los d\u00edas 11 y 12 de septiembre. Las Semifinales ser\u00e1n el 14 de septiembre para Tango de Pista y el 15 para Tango Escenario, tambi\u00e9n en la Usina del Arte. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El festival presentar\u00e1 conciertos, exhibiciones, homenajes, danzas, cine, videoclips, muestras y presentaciones de libros. La nueva edici\u00f3n del Tango Buenos Aires Festival y Mundial, que se realizar\u00e1 entre ma\u00f1ana y hasta el domingo 18 de septiembre en 30 sedes porte\u00f1as, presentar\u00e1 conciertos, exhibiciones, homenajes, danzas, cine, videoclips, muestras y presentaciones de libros. \u201cEl foco de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24007,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24006"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=24006"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/24007"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=24006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=24006"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=24006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}