{"id":24012,"date":"2022-09-05T23:47:36","date_gmt":"2022-09-05T23:47:36","guid":{"rendered":"https:\/\/prensa.cba.gov.ar\/?p=515390"},"modified":"2022-09-05T23:47:36","modified_gmt":"2022-09-05T23:47:36","slug":"mas-controles-de-caza-y-pesca-durante-el-fin-de-semana-en-el-interior","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2022\/09\/05\/mas-controles-de-caza-y-pesca-durante-el-fin-de-semana-en-el-interior\/","title":{"rendered":"M\u00e1s controles de caza y pesca durante el fin de semana en el interior"},"content":{"rendered":"<ul>\n<li><strong>La Polic\u00eda Ambiental y la Patrulla Rural realizaron controles en Pozo del Molle y el dique Piedras Moras.<\/strong><\/li>\n<li><strong>Frenaron un evento ilegal de tiro al pich\u00f3n y labraron actas por falta de licencias de pesca<\/strong>.<\/li>\n<\/ul>\n<p>Durante el fin de semana, personal de Polic\u00eda Ambiental del Ministerio de Coordinaci\u00f3n, y Patrulla Rural realizaron inspecciones conjuntas en Pozo del Molle y en el dique Piedras Moras para frenar actividades de caza y pesca furtiva.<\/p>\n<p>El operativo se llev\u00f3 a cabo el pasado s\u00e1bado tras la recepci\u00f3n de una denuncia an\u00f3nima que alertaba que en una zona rural de Pozo del Molle se estar\u00eda preparando un evento de tiro al pich\u00f3n, pr\u00e1ctica de caza que se encuentra vedada en nuestra provincia por la crueldad animal que supone.<\/p>\n<p>El tiro al pich\u00f3n, tambi\u00e9n conocido como tiro a la paloma o al vuelo, consiste en herir o abatir animales luego de liberarlos del cautiverio, aprovech\u00e1ndose de su desconcierto e indefensi\u00f3n. Por ello, est\u00e1 totalmente prohibida su pr\u00e1ctica en todo el territorio cordob\u00e9s.<\/p>\n<p><em>\u201cAl ingresar al predio, mediante orden de allanamiento, los agentes constataron que hab\u00eda m\u00e1s de 70 personas participando de un torneo. Si bien en el momento que se efect\u00fao el procedimiento no hab\u00eda nadie practicando la actividad, los inspectores observaron que las instalaciones estaban preparadas para realizar el tiro al pich\u00f3n\u201d,<\/em> inform\u00f3 Adri\u00e1n Rinaudo, secretario de Polic\u00eda Ambiental.<\/p>\n<p>Una vez desarticulada la actividad clandestina, se revis\u00f3 el establecimiento minuciosamente y secuestraron: escopetas, cartuchos, elementos para realizar esta actividad de caza, jaulas, bolsas de arpillera con palomas muertas y otras bolsas con palomas vivas que fueron liberadas al finalizar el control.<\/p>\n<figure class=\"wp-block-coblocks-gallery-masonry masonry-grid has-small-gutter\">\n<figure class=\"wp-block-image size-large masonry-brick\"><img loading=\"lazy\" width=\"990\" height=\"660\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/mas-controles-de-caza-y-pesca-durante-el-fin-de-semana-en-el-interior.jpg\" alt=\"Image gallery image\" class=\"wp-image-515393\"><\/figure>\n<figure class=\"wp-block-image size-large masonry-brick\"><img loading=\"lazy\" width=\"990\" height=\"660\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/mas-controles-de-caza-y-pesca-durante-el-fin-de-semana-en-el-interior-1.jpg\" alt=\"Image gallery image\" class=\"wp-image-515395\"><\/figure>\n<\/figure>\n<p>Luego, otra comitiva de inspectores de Polic\u00eda Ambiental, acompa\u00f1ados tambi\u00e9n por efectivos policiales de la Patrulla Rural recorri\u00f3, durante la jornada del domingo, las inmediaciones del dique Piedras Moras para controlar a los pescadores.<\/p>\n<p>Se inspeccion\u00f3 el pared\u00f3n, las distintas costas del dique y la zona del balneario municipal, en donde hab\u00eda pescadores sin la licencia correspondiente. Se secuestraron ca\u00f1as, se labraron 13 actas y se les inform\u00f3 la forma correcta de practicar la actividad para evitar multas.<\/p>\n<p><strong>\u00bfC\u00f3mo gestionar el carnet digital de pesca?<\/strong><\/p>\n<p>Primero, se debe ingresar al sitio <a href=\"https:\/\/cazaypesca.cba.gov.ar\" target=\"_blank\" rel=\"noreferrer noopener\">cazaypesca.cba.gov.ar<\/a>, iniciar sesi\u00f3n con usuario de CiDi nivel 2 y acceder a la secci\u00f3n \u201cIngresar al sistema\u201d. Luego completar una \u201cNueva solicitud\u201d, generar el cedul\u00f3n de pago y abonarlo a trav\u00e9s de los medios disponibles.<\/p>\n<p>Una vez que se acredite, el solicitante encontrar\u00e1 en la web el carnet digital con sus datos y un c\u00f3digo QR que deber\u00e1 mostrar en caso de inspecciones.<\/p>\n<p>Los conceptos de licencias anuales corresponden al a\u00f1o calendario, por lo que se vencen el 31 de diciembre de cada a\u00f1o y deben renovarse al a\u00f1o siguiente. Tambi\u00e9n existe la posibilidad de gestionar el carnet por d\u00eda.<\/p>\n<p>En caso de consultas, comunicarse al \u00e1rea de Administraci\u00f3n de Secretar\u00eda de Ambiente para recibir asistencia y asesoramiento por correo electr\u00f3nico: <strong>admambientecba@gmail.com. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda Ambiental y la Patrulla Rural realizaron controles en Pozo del Molle y el dique Piedras Moras. Frenaron un evento ilegal de tiro al pich\u00f3n y labraron actas por falta de licencias de pesca. Durante el fin de semana, personal de Polic\u00eda Ambiental del Ministerio de Coordinaci\u00f3n, y Patrulla Rural realizaron inspecciones conjuntas en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24013,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24012"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=24012"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24012\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/24013"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=24012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=24012"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=24012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}