{"id":24029,"date":"2022-09-06T14:55:10","date_gmt":"2022-09-06T14:55:10","guid":{"rendered":"http:\/\/nuevacordoba.net\/index.php\/2022\/09\/06\/sudafrica-llegara-a-la-argentina-con-bajas-para-jugar-ante-los-pumas-en-la-cancha-de-velez\/"},"modified":"2022-09-06T14:55:10","modified_gmt":"2022-09-06T14:55:10","slug":"sudafrica-llegara-a-la-argentina-con-bajas-para-jugar-ante-los-pumas-en-la-cancha-de-velez","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2022\/09\/06\/sudafrica-llegara-a-la-argentina-con-bajas-para-jugar-ante-los-pumas-en-la-cancha-de-velez\/","title":{"rendered":"Sud\u00e1frica llegar\u00e1 a la Argentina con bajas para jugar ante Los Pumas en la cancha de V\u00e9lez"},"content":{"rendered":"<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/sudafrica-llegara-a-la-argentina-con-bajas-para-jugar-ante-los-pumas-en-la-cancha-de-velez.jpg\" width=\"100%\" height=\"100%\" alt=\"El conjunto sudfricano con bajas para enfrentar a los Pumas Foto TWSpringboks\"><figcaption> El conjunto sud\u00e1fricano con bajas para enfrentar a los Pumas \/ Foto: TW@Springboks <\/figcaption><\/figure>\n<p><strong>El seleccionado de rugby de Sud\u00e1frica, vigente campe\u00f3n mundial, llegar\u00e1 a la Argentina con tres bajas para jugar el 17 de septiembre ante Los Pumas<\/strong>, en cancha de V\u00e9lez por la quinta fecha del Rugby Championship.<\/p>\n<p>Seg\u00fan inform\u00f3 el sitio especializado A Pleno Rugby los Springbooks, que vienen de ganarle a Australia, de visitantes por 24 a 8, llegar\u00e1n con la ausencias del centro Lukhanyo Am, el medio apertura Andre Pollard y el hooker Bongi Mbonambi.<\/p>\n<p><strong>Am, uno de los jugadores m\u00e1s importantes del equipo<\/strong> que dirige Jacques Nienaber, <strong>fue operado de la rodilla el pasado viernes y tiene entre ocho y 12 semanas de recuperaci\u00f3n<\/strong>, por lo que tampoco estar\u00eda para la gira de noviembre por Europa.<\/p>\n<p>Por el lado de Pollard, tambi\u00e9n tiene una lesi\u00f3n en una rodilla y estima que tendr\u00e1 seis semanas sin actividad, por lo tanto no estar\u00e1 en los cotejos frente a Argentina y viajar\u00e1 a Inglaterra para iniciar su nuevo ciclo en Leicester.<\/p>\n<blockquote class=\"twitter-tweet\" readability=\"5.5094339622642\">\n<p lang=\"es\" dir=\"ltr\">En Sud\u00e1frica afirman que Bongi Mbonambi es tambi\u00e9n baja en los Springboks para enfrentar a Los Pumas.<\/p>\n<p>Mir\u00e1 &gt;&gt; <a href=\"https:\/\/t.co\/IIGSgMK9xc\">https:\/\/t.co\/IIGSgMK9xc<\/a> <a href=\"https:\/\/t.co\/PSZl8zk03S\">pic.twitter.com\/PSZl8zk03S<\/a><\/p>\n<p>\u2014 A Pleno Rugby (@aplenorugby) <a href=\"https:\/\/twitter.com\/aplenorugby\/status\/1566885630285602817?ref_src=twsrc%5Etfw\">September 5, 2022<\/a><\/p><\/blockquote>\n<p>Finalmente, Mbonambi, tambi\u00e9n sufre una lesi\u00f3n en una rodilla y no viajar\u00e1 a Buenos Aires pero hay alguna posibilidad de que juegue en la \u00faltima fecha del RCH el 24 de este mes en la ciudad sudafricana de Durban.<\/p>\n<p>Sud\u00e1frica en este RCH le gan\u00f3 a Nueva Zelanda 26-10 y cayo ante los All Blacks 35-23, ambas como local, y luego visito a Australia cayendo 25-17 y venciendo 24-8.<\/p>\n<p>El RCH es liderado por Nueva Zelanda con 10 unidades, seguido por Australia, Argentina y Sud\u00e1frica con nueve, en el edici\u00f3n m\u00e1s pareja de la historia. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El conjunto sud\u00e1fricano con bajas para enfrentar a los Pumas \/ Foto: TW@Springboks El seleccionado de rugby de Sud\u00e1frica, vigente campe\u00f3n mundial, llegar\u00e1 a la Argentina con tres bajas para jugar el 17 de septiembre ante Los Pumas, en cancha de V\u00e9lez por la quinta fecha del Rugby Championship. Seg\u00fan inform\u00f3 el sitio especializado A [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24030,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24029"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=24029"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/24030"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=24029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=24029"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=24029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}