{"id":24105,"date":"2022-09-08T15:07:09","date_gmt":"2022-09-08T15:07:09","guid":{"rendered":"http:\/\/nuevacordoba.net\/index.php\/2022\/09\/08\/maradona-sera-homenajeado-desde-el-10-10-hasta-el-partido-por-la-paz-del-14-de-noviembre\/"},"modified":"2022-09-08T15:07:09","modified_gmt":"2022-09-08T15:07:09","slug":"maradona-sera-homenajeado-desde-el-10-10-hasta-el-partido-por-la-paz-del-14-de-noviembre","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2022\/09\/08\/maradona-sera-homenajeado-desde-el-10-10-hasta-el-partido-por-la-paz-del-14-de-noviembre\/","title":{"rendered":"Maradona ser\u00e1 homenajeado desde el 10-10 hasta el Partido por la Paz del 14 de noviembre"},"content":{"rendered":"<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/maradona-sera-homenajeado-desde-el-10-10-hasta-el-partido-por-la-paz-del-14-de-noviembre.jpg\" width=\"100%\" height=\"100%\" alt=\"Maradona ser homenajeado desde el prximo lunes 10 de octubre\"><figcaption> Maradona ser\u00e1 homenajeado desde el pr\u00f3ximo lunes 10 de octubre. <\/figcaption><\/figure>\n<p>El astro argentino Diego Armando <strong>Maradona ser\u00e1 homenajeado desde el pr\u00f3ximo lunes 10 de octubre<\/strong>, emblem\u00e1tica fecha 10-10, hasta el Partido por la Paz que se jugar\u00e1 el 14 de noviembre en el Estadio Ol\u00edmpico de Roma, anunci\u00f3 la organizaci\u00f3n pontificia Scholas Occurrentes, a cargo del evento.<\/p>\n<p>Maradona fue promotor y figura principal como capit\u00e1n del equipo Scholas en el primer Partido por la Paz realizado en 2016.<\/p>\n<p>La tercera edici\u00f3n del evento futbol\u00edstico e interreligioso con fines ben\u00e9ficos <strong>estar\u00e1 precedida este a\u00f1o por una serie de evocaciones virtuales del astro, que falleci\u00f3 en Buenos Aires el 25 de noviembre de 2020.<\/strong><\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/maradona-sera-homenajeado-desde-el-10-10-hasta-el-partido-por-la-paz-del-14-de-noviembre-1.jpg\" width=\"100%\" height=\"100%\" alt=\"Maradona fue promotor del encuentro en 2016\"><figcaption> Maradona fue promotor del encuentro en 2016. <\/figcaption><\/figure>\n<p>El programa de homenajes a distancia se prolongar\u00e1 hasta el 14 de noviembre, seis d\u00edas antes del inicio del Mundial Qatar 2022, cuando se realice el partido con la presencia de numerosas figuras del deporte mundial y un desarrollo tecnol\u00f3gico de holopresencia mediante el que se podr\u00e1 revivir diferentes momentos de la vida del Diez.<\/p>\n<p><strong>En el Ol\u00edmpico de Roma, ser\u00e1 entregar\u00e1 la pelota de la Paz bendecida por el papa Francisco<\/strong>, informaron los organizadores en un comunicado.<\/p>\n<p>\u00abEl deseo de todos es la paz. Al jugar en equipo, la competencia en vez de ser guerra es semilla de paz. Este partido o lo ganamos todos, o los que m\u00e1s pierden van a seguir siendo los nin\u0303os y los jo\u0301venes. El si\u0301mbolo de este Partido de la Paz es el olivo. Los invito a jugar por la Paz\u201d, declar\u00f3 el sumo pont\u00edfice al presentar el evento el 19 de mayo pasado en el Aula Magna de la Pontificia Universidad Urbaniana,<\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/maradona-sera-homenajeado-desde-el-10-10-hasta-el-partido-por-la-paz-del-14-de-noviembre-2.jpg\" width=\"100%\" height=\"100%\" alt=\"Diego ser homenajeado el mes que viene\"><figcaption> Diego ser\u00e1 homenajeado el mes que viene. <\/figcaption><\/figure>\n<p><strong>En esa ocasi\u00f3n, Su Santidad comparti\u00f3 el lanzamiento con el exfutbolista argentino Maximiliano Rodr\u00edguez<\/strong> y los brasile\u00f1os Ronaldinho y Dani Alves. Adem\u00e1s, otras figuras como Lionel Messi, \u00c1ngel Di Mar\u00eda, Jos\u00e9 Mourinho, Luis Su\u00e1rez y Gianluigi Buffon enviaron su adhesi\u00f3n con mensajes grabados.<\/p>\n<p>El Partido por la Paz cuenta con el patrocinio institucional del Comit\u00e9 Ol\u00edmpico Nacional Italiano (CONI) y contribuir\u00e1 al apoyo de los programas del Movimiento Pontificio Scholas Occurrentes, <strong>creado por el papa Francisco con la misi\u00f3n de vincular la tecnolog\u00eda, el arte y el deporte para promover la educaci\u00f3n y la integraci\u00f3n de todas las comunidades.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maradona ser\u00e1 homenajeado desde el pr\u00f3ximo lunes 10 de octubre. El astro argentino Diego Armando Maradona ser\u00e1 homenajeado desde el pr\u00f3ximo lunes 10 de octubre, emblem\u00e1tica fecha 10-10, hasta el Partido por la Paz que se jugar\u00e1 el 14 de noviembre en el Estadio Ol\u00edmpico de Roma, anunci\u00f3 la organizaci\u00f3n pontificia Scholas Occurrentes, a cargo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24106,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24105"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=24105"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/24106"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=24105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=24105"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=24105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}