{"id":24146,"date":"2022-09-09T14:08:16","date_gmt":"2022-09-09T14:08:16","guid":{"rendered":"https:\/\/cordoba.gob.ar\/?p=33211"},"modified":"2022-09-09T14:08:16","modified_gmt":"2022-09-09T14:08:16","slug":"llaryora-hacer-aulas-es-importante-pero-ensenar-roboticaprogramacion-e-ingles-es-fundamental-para-el-futuro-de-nuestros-ninos","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2022\/09\/09\/llaryora-hacer-aulas-es-importante-pero-ensenar-roboticaprogramacion-e-ingles-es-fundamental-para-el-futuro-de-nuestros-ninos\/","title":{"rendered":"Llaryora: \u201cHacer aulas es importante, pero ense\u00f1ar rob\u00f3tica,programaci\u00f3n e ingl\u00e9s es fundamental para el futuro de nuestros ni\u00f1os\u201d"},"content":{"rendered":"<div><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/llaryora-hacer-aulas-es-importante-pero-ensenar-roboticaprogramacion-e-ingles-es-fundamental-para-el-futuro-de-nuestros-ninos.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<ul>\n<li><strong>El intendente Mart\u00edn Llaryora agradeci\u00f3 a la comunidad docente por la capacitaci\u00f3n que realiza en nuevas tecnolog\u00edas, para as\u00ed transmitir los conocimientos a los alumnos.<\/strong><\/li>\n<\/ul>\n<hr>\n<p>En el marco de la inauguraci\u00f3n del aula 26 de su gesti\u00f3n, en la Escuela Municipal Dr. Jorge Orgaz, ubicada en el barrio Villa Rivera Indarte, el intendente Mart\u00edn LLaryora afirm\u00f3 \u201cla educaci\u00f3n en las nuevas tecnolog\u00edas que reciben los ni\u00f1os de las escuelas municipales, la vinculaci\u00f3n con la rob\u00f3tica, programaci\u00f3n e ingl\u00e9s, es la mejor herramienta que los alumnos pueden tener de cara al futuro laboral que les tocar\u00e1 enfrentar en los pr\u00f3ximos a\u00f1os\u201d.<\/p>\n<p>El intendente Mart\u00edn Llaryora resalt\u00f3 la labor de los docentes que se actualizan y adec\u00faan a las nuevas realidades pedag\u00f3gicas y tecnol\u00f3gicas que ofrecen los nuevos paradigmas educativos: \u201cNuestros ni\u00f1os necesitan una educaci\u00f3n moderna, de avanzada y para lograrlo necesitamos no s\u00f3lo de la decisi\u00f3n del Ejecutivo de realizar una alta inversi\u00f3n en equipamiento tecnol\u00f3gico y aulas nuevas, sino que precisamos de una comunidad educativa que quiera volver a aprender, a capacitarse en las nuevas tecnolog\u00edas para poder transmitir esos conocimientos en los ni\u00f1os de nuestras escuelas\u201d.<\/p>\n<p>La nueva sala cuenta con 54,75 metros cuadrados y est\u00e1 provista de nuevo mobiliario, tecnolog\u00eda de \u00faltima generaci\u00f3n, robots, y computadoras provistas de una alta conectividad a internet.<\/p>\n<p>Al espacio se le suma una galer\u00eda de 18,50 metros cuadrados que ensambla la nueva construcci\u00f3n con la escuela.<\/p>\n<p>La obra, cuya inversi\u00f3n final fue de $8.490.000, sum\u00f3 adem\u00e1s diferentes refacciones entre las que se encuentran la readecuaci\u00f3n el\u00e9ctrica, como tambi\u00e9n la reparaci\u00f3n de juegos y mobiliarios existentes.<\/p>\n<p>Al respecto, el secretario de Educaci\u00f3n, Horacio Ferreyra expres\u00f3 su satisfacci\u00f3n por alcanzar el 50% de las aulas prometidas. \u201cCon esta aula n\u00famero 26 estamos cumpliendo con el 50% de la meta que nuestro intendente nos plante\u00f3 hace un a\u00f1o en construcci\u00f3n de aulas y esto nos da fuerzas y ganas porque hay que seguir avanzando\u201d.<\/p>\n<p>Adem\u00e1s, en la inauguraci\u00f3n estuvo presente el vice intendente Municipal, Daniel Passerini, quien aprovech\u00f3 la oportunidad para resaltar la importancia de la educaci\u00f3n p\u00fablica: \u201cEstamos orgullosos de que en C\u00f3rdoba la educaci\u00f3n sea un derecho de calidad que est\u00e1 garantizado a nivel municipal y provincial. Estar presentes en esta escuela, nos invoca a buenos valores, a la convivencia y a respetarnos mutuamente, y por eso desde el municipio continuamos implementando educaci\u00f3n p\u00fablica de calidad como un pilar para sostener esos valores.\u201d<\/p>\n<p><strong>Escuela Dr. Jorge Orgaz <\/strong><\/p>\n<p>Ubicada en el extremo norte de la ciudad, la escuela Dr. Jorge Orgaz, es una de las escuelas Verdes municipales, que fomenta en sus estudiantes la sensibilidad y el inter\u00e9s por los problemas ambientales.<\/p>\n<p>Andrea Peralta, directora del establecimiento, resalt\u00f3: \u201cPara la escuela p\u00fablica no hay soluciones al margen del Estado. Por eso cobra sentido invertir en educaci\u00f3n porque es invertir en futuro\u201d.<\/p>\n<p>La instituci\u00f3n cuenta con una aproximaci\u00f3n al ambiente y al bosque nativo desde diversos dispositivos y formatos de aprendizaje.<\/p>\n<p>A trav\u00e9s de su predio verde, rodeado de \u00e1rboles, la escuela propone un punto de aprendizaje que movilice a sus alumnos a apropiarse, a trav\u00e9s de la lectura y la escritura, de diferentes conceptos de educaci\u00f3n ambiental y cuidado del bosque nativo.<\/p>\n<p>A su vez, este espacio verde es utilizado por sus alumnos para la recreaci\u00f3n y se proyecta la refuncionalizaci\u00f3n del vivero, de sus hornos de pan, lumbricario, huerta y aula al aire libre con el objetivo de desarrollar aptitudes y conocimientos enmarcados en el trabajo en equipo para la Educaci\u00f3n Ambiental, fomentando en sus estudiantes la capacidad de buscar, reconocer, plantear y resolver problemas del ambiente.<\/p>\n<p>La Escuela Dr. Jorge Orgaz, inici\u00f3 sus actividades en marzo de 1984. La familia Fajardo prest\u00f3 su casa para que asistieran los 50 primeros estudiantes inscriptos en 1\u00b0 y 2\u00b0 grado, aunque fue reci\u00e9n el 17 de junio de 1988 cuando qued\u00f3 oficialmente inaugurada. Con el paso de los a\u00f1os, la escuela creci\u00f3 ediliciamente y tambi\u00e9n en cantidad de alumnos.<\/p>\n<p>Hoy tiene 347 estudiantes distribuidos en nivel inicial, con sala de 4 y 5 a\u00f1os y nivel primario. Adem\u00e1s 27 alumnos asisten a la modalidad educativa para j\u00f3venes y adultos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El intendente Mart\u00edn Llaryora agradeci\u00f3 a la comunidad docente por la capacitaci\u00f3n que realiza en nuevas tecnolog\u00edas, para as\u00ed transmitir los conocimientos a los alumnos. En el marco de la inauguraci\u00f3n del aula 26 de su gesti\u00f3n, en la Escuela Municipal Dr. Jorge Orgaz, ubicada en el barrio Villa Rivera Indarte, el intendente Mart\u00edn LLaryora [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24147,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24146"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=24146"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/24147"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=24146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=24146"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=24146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}