{"id":24165,"date":"2022-09-09T23:23:25","date_gmt":"2022-09-09T23:23:25","guid":{"rendered":"https:\/\/prensa.cba.gov.ar\/?p=516219"},"modified":"2022-09-09T23:23:25","modified_gmt":"2022-09-09T23:23:25","slug":"se-lanzo-el-consorcio-gestion-integrada-cuencas-a-el-gato-sta-catalina","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2022\/09\/09\/se-lanzo-el-consorcio-gestion-integrada-cuencas-a-el-gato-sta-catalina\/","title":{"rendered":"Se lanz\u00f3 el Consorcio Gesti\u00f3n Integrada Cuencas A\u00b0 El Gato-Sta Catalina"},"content":{"rendered":"<div><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/se-lanzo-el-consorcio-gestion-integrada-cuencas-a-el-gato-sta-catalina.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<ul>\n<li><strong><strong>Es el sexto consorcio de la provincia y abarca el departamento R\u00edo Cuarto. <\/strong><\/strong><\/li>\n<li><strong><strong>Hay m\u00e1s de 4.500.000 hect\u00e1reas en C\u00f3rdoba bajo la modalidad Gesti\u00f3n Integrada.<\/strong><\/strong><\/li>\n<\/ul>\n<p>En el marco de la 88\u00b0 Exposici\u00f3n Rural de R\u00edo Cuarto, el Ministerio de Agricultura y Ganader\u00eda lanz\u00f3 el Consorcio de Gesti\u00f3n Integrada de Cuencas Arroyo El Gato-Santa Catalina, con la firma del acta constitutiva del mismo.<\/p>\n<p>Este consorcio abarca el departamento R\u00edo Cuarto, que es el primer productor de ma\u00edz, de man\u00ed y tercer productor de soja, ocho localidades, 9 parajes, un Consorcio Regional Caminero y dos Consorcios de Conservaci\u00f3n de Suelos (Jag\u00fceles \u2013 La Brianza).<\/p>\n<p>Abarca una superficie de 540.000 hect\u00e1reas y es el sexto en la provincia; sum\u00e1ndose a los de Jes\u00fas Mar\u00eda-R\u00edo Pinto; R\u00edo Xanaes, Tegua-Chaz\u00f3n, Marcos Ju\u00e1rez, y Cuenca Alta La Picasa; recientemente presentado en Laboulaye.<\/p>\n<p>Para la implementaci\u00f3n del plan b\u00e1sico del consorcio, se suscribi\u00f3 un convenio con la Facultad de Agronom\u00eda y Veterinaria de la Universidad Nacional de R\u00edo Cuarto.<\/p>\n<p><em>\u201cEl desarrollo sostenible es una pol\u00edtica de Estado y hay un compromiso de los productores con el cuidado ambiental y de los recursos. El reordenamiento del territorio es un desaf\u00edo y a trav\u00e9s de la gesti\u00f3n integrada de cuencas se avanza en ese sentido\u201d<\/em>, dijo el ministro Sergio Busso.<\/p>\n<p>Y a\u00f1adi\u00f3 que se aportar\u00e1 una planta de biodi\u00e9sel al flamante consorcio, que permitir\u00e1 cambiar la matriz energ\u00e9tica.<\/p>\n<p>Con este consorcio, la provincia suma 4.500.000 hect\u00e1reas bajo este sistema. De las 8.000.000 de hect\u00e1reas productivas de vocaci\u00f3n agr\u00edcola de la provincia, el 47% trabaja desde la integralidad, nucleando m\u00e1s del 30% de los productores cordobeses.<\/p>\n<p>Acompa\u00f1aron al ministro, el diputado Carlos Guti\u00e9rrez, el legislador Benigno Rins; la decana de la Facultad, Carmen Cholaky; los secretarios de Agricultura y Ganader\u00eda, Marcos Blanda y Catalina Boetto, el vicepresidente de APRHI, Guillermo Vilchez, y la directora general de la Delegaci\u00f3n del Gobierno de C\u00f3rdoba en R\u00edo Cuarto, Samantha David entre otras autoridades.<\/p>\n<h3><strong>Gesti\u00f3n Integrada<\/strong><\/h3>\n<p>La modalidad \u201cGesti\u00f3n Integrada\u201d surgi\u00f3 con la finalidad de promover el manejo coordinado de los planes, programas, proyectos, obras y de los recursos naturales; conformando equipos multidisciplinarios tendientes a dar soluciones integrales a la problem\u00e1tica relacionada a suelo, agua, caminos e infraestructura.<\/p>\n<p>Los seis consorcios est\u00e1n integrados por 125 localidades, 23 Consorcios de Conservaci\u00f3n de Suelo, las 19 Consorcios Regionales de la provincia, 17 Consorcios Canaleros.<\/p>\n<p>Del total de los productores inscriptos en el Programa de Buenas Pr\u00e1cticas Agropecuarias (BPAs) en el 2021, el 30% trabaja como consorcios de gesti\u00f3n integrada y m\u00e1s de 120.000 hect\u00e1reas se han sistematizados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es el sexto consorcio de la provincia y abarca el departamento R\u00edo Cuarto. Hay m\u00e1s de 4.500.000 hect\u00e1reas en C\u00f3rdoba bajo la modalidad Gesti\u00f3n Integrada. En el marco de la 88\u00b0 Exposici\u00f3n Rural de R\u00edo Cuarto, el Ministerio de Agricultura y Ganader\u00eda lanz\u00f3 el Consorcio de Gesti\u00f3n Integrada de Cuencas Arroyo El Gato-Santa Catalina, con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24166,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24165"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=24165"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/24166"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=24165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=24165"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=24165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}