{"id":24169,"date":"2022-09-10T15:26:34","date_gmt":"2022-09-10T15:26:34","guid":{"rendered":"http:\/\/nuevacordoba.net\/index.php\/2022\/09\/10\/argentina-juega-ante-nueva-zelanda-en-cuartos-de-final-del-mundial-de-seven\/"},"modified":"2022-09-10T15:26:34","modified_gmt":"2022-09-10T15:26:34","slug":"argentina-juega-ante-nueva-zelanda-en-cuartos-de-final-del-mundial-de-seven","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2022\/09\/10\/argentina-juega-ante-nueva-zelanda-en-cuartos-de-final-del-mundial-de-seven\/","title":{"rendered":"Argentina juega ante Nueva Zelanda en cuartos de final del Mundial de Seven"},"content":{"rendered":"<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/argentina-juega-ante-nueva-zelanda-en-cuartos-de-final-del-mundial-de-seven.jpg\" width=\"100%\" height=\"100%\" alt=\"Pumas 7 en busca de las semifinales de la copa del mundo Foto TWlospumas7arg\"><figcaption> Pumas 7 en busca de las semifinales de la copa del mundo \/ Foto: TW@lospumas7arg <\/figcaption><\/figure>\n<p>El seleccionado argentino<strong> rugby seven, Los Pumas 7s, jugar\u00e1<\/strong> este s\u00e1bado,<strong> desde las 14.35<\/strong>, <strong>ante Nueva Zelanda<\/strong>, vigente campe\u00f3n mundial,<strong> por los cuartos de final de la Copa del Mundo<\/strong> que se desarrolla en Ciudad del Cabo, Sud\u00e1frica.<\/p>\n<p>El cotejo se jugar\u00e1 en el Cape Town Stadium, con aforo para 55.000 espectadores en tanto que los otros cotejos de cuartos de final ser\u00e1n Francia-Australia (desde las 15:35), Samoa-Fiji (16:35) y Sud\u00e1frica-Irlanda (17:33).<\/p>\n<p>Argentina, dirigido por Santiago G\u00f3mez Cora, lleg\u00f3 a esta instancia luego de vencer en octavos de final a Kenia por 22 a 7 y Nueva Zelanda a Escocia por 43 a 5.<\/p>\n<blockquote class=\"twitter-tweet\" readability=\"6.099173553719\">\n<p lang=\"es\" dir=\"ltr\">\u00a1Contin\u00faa la acci\u00f3n en Ciudad del Cabo!<\/p>\n<p>Hoy <a href=\"https:\/\/twitter.com\/lospumas7arg?ref_src=twsrc%5Etfw\">@lospumas7arg<\/a> ir\u00e1n en busca de las semifinales.<\/p>\n<p>\u00a1Hacenos llegar tu mensaje de aliento! \ud83c\udde6\ud83c\uddf7<a href=\"https:\/\/twitter.com\/hashtag\/SeVenComoNunca?src=hash&amp;ref_src=twsrc%5Etfw\">#SeVenComoNunca<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/RWC7s?src=hash&amp;ref_src=twsrc%5Etfw\">#RWC7s<\/a> <a href=\"https:\/\/t.co\/93o9GGDLTD\">pic.twitter.com\/93o9GGDLTD<\/a><\/p>\n<p>\u2014 Los Pumas 7s (@lospumas7arg) <a href=\"https:\/\/twitter.com\/lospumas7arg\/status\/1568569981142540291?ref_src=twsrc%5Etfw\">September 10, 2022<\/a><\/p><\/blockquote>\n<p>Los otros resultados de octavos de final fueron: Irlanda 17-Inglaterra 5, Francia 19-Canad\u00e1 12 y Samoa 40-Estados Unidos 12 y Australia 35-Uruguay 0, Fiji 29-Gales 5 y Sud\u00e1frica 32-Chile 5.<\/p>\n<p><strong>Las semifinales y la final se jugar\u00e1n este domingo<\/strong> y <strong>el vencedor de de Argentina-Nueva Zelanda jugar\u00e1 ante el de Sud\u00e1frica<\/strong>&#8211;<strong>Irlanda,<\/strong> mientras que el de Francia-Australia lo har\u00e1 ante el triunfador de Samoa-Fiji.<\/p>\n<p>El certamen tiene un nuevo sistema de competencia por eliminaci\u00f3n directa. Por eso, los ocho mejores seleccionados de la clasificaci\u00f3n anual ingresaron directamente a octavos y esos equipos fueron Argentina, Inglaterra, Francia, Estados Unidos, Nueva Zelanda, Fiji, Australia y Sud\u00e1frica.<\/p>\n<p>Se jugaron siete mundiales hasta ahora con tres ganados por Nueva Zelanda, dos por Fiji, uno por Inglaterra y Gales. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pumas 7 en busca de las semifinales de la copa del mundo \/ Foto: TW@lospumas7arg El seleccionado argentino rugby seven, Los Pumas 7s, jugar\u00e1 este s\u00e1bado, desde las 14.35, ante Nueva Zelanda, vigente campe\u00f3n mundial, por los cuartos de final de la Copa del Mundo que se desarrolla en Ciudad del Cabo, Sud\u00e1frica. El cotejo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24170,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24169"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=24169"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/24170"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=24169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=24169"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=24169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}