{"id":24171,"date":"2022-09-09T20:14:49","date_gmt":"2022-09-09T20:14:49","guid":{"rendered":"https:\/\/es.digitaltrends.com\/?p=960369"},"modified":"2022-09-09T20:14:49","modified_gmt":"2022-09-09T20:14:49","slug":"este-actor-fue-confirmado-como-ezra-bridger-para-la-serie-ahsoka","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2022\/09\/09\/este-actor-fue-confirmado-como-ezra-bridger-para-la-serie-ahsoka\/","title":{"rendered":"Este actor fue confirmado como Ezra Bridger para la serie Ahsoka"},"content":{"rendered":"<p>Una de las series animadas m\u00e1s queridas por los fan\u00e1ticos de&nbsp;<a href=\"https:\/\/es.digitaltrends.com\/cine\/starwars-guerra-galaxias-celebracion-peliculas\/\"><strong>Star Wars<\/strong><\/a> es <strong>Rebels<\/strong>, una ficci\u00f3n que cuenta la historia de <strong>Ezra Bridger<\/strong>, \u00abun&nbsp;Padawan&nbsp;Jedi&nbsp;humano&nbsp;que se convirti\u00f3 en un luchador rebelde y un l\u00edder revolucionario durante la rebeli\u00f3n inicial contra el&nbsp;Imperio Gal\u00e1ctico\u00bb, como cuenta el <a href=\"https:\/\/starwars.fandom.com\/es\/wiki\/Ezra_Bridger\" target=\"_blank\" rel=\"noopener\">Fandom<\/a> de Star Wars.<\/p>\n<p>Y el personaje que alcanz\u00f3 a luchar contra Darth Maul y que vio en una <a href=\"https:\/\/es.digitaltrends.com\/entretenimiento\/darth-vader-regreso-obi-wan-kenobi\/\"><strong>visi\u00f3n a Darth Vader<\/strong><\/a>, ahora estar\u00e1 de carne y hueso en<strong> la serie <em>Ahsoka<\/em><\/strong> que protagoniza Rosario Dawson.<\/p>\n<figure class=\"alignnone\"><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/este-actor-fue-confirmado-como-ezra-bridger-para-la-serie-ahsoka.gif\" data-dt-lazy-src=\"https:\/\/es.digitaltrends.com\/wp-content\/uploads\/2022\/09\/Captura-web_9-9-2022_16926_www.hollywoodreporter.com_.jpeg?fit=720%2C409&amp;p=1\" onerror=\"dti_load_error(this)\" class=\" size-large wp-image-960378 dt-lazy-load dt-lazy-pending\" alt><\/figure>\n<p>En el papel de Ezra Bridger se pondr\u00e1 el actor Eman Esfandi, su trayectoria incluye la pel\u00edcula de terror de Robert Rodr\u00edguez <em>Red 11<\/em>, que se proyect\u00f3 en Cannes en 2019, as\u00ed como un peque\u00f1o papel en la nominada a mejor pel\u00edcula&nbsp;<em>King Richard.&nbsp;<\/em>Tambi\u00e9n aparece en el pr\u00f3ximo drama militar gay&nbsp;<em>The Inspection.<\/em><\/p>\n<p>Durante meses, los rumores han girado sobre qui\u00e9n interpretar\u00eda a Ezra en la serie, con el nombre de la estrella de&nbsp;<em>Aladdin,<\/em> Mena Massoud como una pieza segura para la serie.<\/p>\n<p>\u00abMe alegro de que los rumores se detengan ahora. Desafortunadamente, nunca tuve una oportunidad justa, pero supongo que no era para m\u00ed\u00bb, <a href=\"https:\/\/twitter.com\/MenaMassoud\/status\/1568320638733139968\" target=\"_blank\" rel=\"nofollow noopener\">escribi\u00f3 Massoud en Twitter el<\/a> viernes. \u00abNo puedo negar que el tipo se ve exactamente como Ezra. \u00a1Espero que haya hecho justicia!\u00bb<\/p>\n<blockquote class=\"h-lazy-embed\" data-width=\"500\" data-dnt=\"true\" data-initial-classes=\"twitter-tweet\" data-embed-name=\"twitter\" data-sdk-src=\"\/\/platform.twitter.com\/widgets.js\">\n<p lang=\"en\" dir=\"ltr\">Glad the rumors will stop now. Never really had a fair shot at it unfortunately (1 self-tape months ago) but just wasn\u2019t meant for me I guess. Can\u2019t deny the dude looks exactly like Ezra. Hope it\u2019s done justice!<\/p>\n<p>&amp;mdash; Mena Massoud (@MenaMassoud) <a href=\"https:\/\/twitter.com\/MenaMassoud\/status\/1568320638733139968?ref_src=twsrc%5Etfw\">September 9, 2022<\/a><\/p>\n<\/blockquote>\n<p>La serie de <a href=\"https:\/\/es.digitaltrends.com\/topic\/disney-plus\/\"><strong>Disney Plus<\/strong> <\/a>est\u00e1 protagonizada por Dawson como la Jedi titular Ahsoka Tano, quien salt\u00f3 por primera vez a la acci\u00f3n en vivo en la segunda temporada de <em>The Mandalorian<\/em>&nbsp;y tambi\u00e9n apareci\u00f3 en&nbsp;<em>The Book of Boba Fett<\/em>. Otras estrellas incluyen a Mary Elizabeth Winstead, la actriz ucraniana Ivanna Sakhno y la australiana&nbsp;Natasha Liu Bordizzo. Hayden Christensen repite su papel como Anakin Skywalker y Ray Stevenson interpreta a un villano misterioso.<\/p>\n<h4 class=\"b-editors-recs-title h-editors-recs-title\"> Recomendaciones del editor\t<\/h4>\n<p> <span id=\"publisher-md\" itemprop=\"publisher\" itemscope itemtype=\"https:\/\/schema.org\/Organization\"> <span itemprop=\"url\" itemtype=\"https:\/\/schema.org\/Url\" content=\"https:\/\/es.digitaltrends.com\"> <span itemprop=\"logo\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"> <meta itemprop=\"url\" content=\"https:\/\/cdn.dtcn.com\/dt\/dt-logo-small.png\"> <meta itemprop=\"width\" content=\"0\"> <meta itemprop=\"height\" content=\"0\"> <\/span> <meta itemprop=\"name\" content=\"Digital Trends Espa\u00f1ol\"> <\/span> <span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"> <meta itemprop=\"url\" content=\"https:\/\/es.digitaltrends.com\/wp-content\/uploads\/2022\/09\/Captura-web_9-9-2022_16926_www.hollywoodreporter.com_.jpeg?p=1\"> <\/span> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una de las series animadas m\u00e1s queridas por los fan\u00e1ticos de&nbsp;Star Wars es Rebels, una ficci\u00f3n que cuenta la historia de Ezra Bridger, \u00abun&nbsp;Padawan&nbsp;Jedi&nbsp;humano&nbsp;que se convirti\u00f3 en un luchador rebelde y un l\u00edder revolucionario durante la rebeli\u00f3n inicial contra el&nbsp;Imperio Gal\u00e1ctico\u00bb, como cuenta el Fandom de Star Wars. Y el personaje que alcanz\u00f3 a luchar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24172,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24171"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=24171"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24171\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/24172"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=24171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=24171"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=24171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}