{"id":24190,"date":"2022-09-10T20:55:00","date_gmt":"2022-09-10T20:55:00","guid":{"rendered":"https:\/\/www.bbc.com\/mundo\/noticias-internacional-62865181"},"modified":"2022-09-10T20:55:00","modified_gmt":"2022-09-10T20:55:00","slug":"cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2022\/09\/10\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso\/","title":{"rendered":"Cu\u00e1ndo y c\u00f3mo ser\u00e1 el funeral de la reina Isabel II: gu\u00eda paso a paso"},"content":{"rendered":"<div dir=\"ltr\" class=\"e1j2237y6 bbc-q4ibpr ebmt73l0\">\n<div class=\"bbc-1atl7vu euvj3t14\">\n<ul role=\"list\" class=\"bbc-k0l9bd euvj3t12\">\n<li role=\"listitem\" class=\"bbc-1a3w4ok euvj3t11\">Redacci\u00f3n <\/li>\n<li role=\"listitem\" class=\"bbc-1p92jtu euvj3t10\">BBC News Mundo<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"e1j2237y7 bbc-q4ibpr ebmt73l0\"><time datetime=\"2022-09-10\" class=\"bbc-1dafq0j e1mklfmt0\">10 septiembre 2022, 16:51 GMT<\/time><\/p>\n<p><time datetime=\"2022-09-10\" class=\"bbc-1dafq0j e1mklfmt0\">Actualizado 2 horas<\/time><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-172p16q ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-189y18v ebmt73l0\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\" readability=\"8\"><picture class=\"bbc-yfiktt e1mo64ex1\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/6898\/production\/_126667762_familybalmoralflowerspa.jpg.webp 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/6898\/production\/_126667762_familybalmoralflowerspa.jpg.webp 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/6898\/production\/_126667762_familybalmoralflowerspa.jpg.webp 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/6898\/production\/_126667762_familybalmoralflowerspa.jpg.webp 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/6898\/production\/_126667762_familybalmoralflowerspa.jpg.webp 800w\" type=\"image\/webp\" sizes=\"(min-width: 1008px) 645px, 100vw\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/6898\/production\/_126667762_familybalmoralflowerspa.jpg 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/6898\/production\/_126667762_familybalmoralflowerspa.jpg 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/6898\/production\/_126667762_familybalmoralflowerspa.jpg 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/6898\/production\/_126667762_familybalmoralflowerspa.jpg 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/6898\/production\/_126667762_familybalmoralflowerspa.jpg 800w\" type=\"image\/jpeg\" sizes=\"(min-width: 1008px) 645px, 100vw\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso.jpg\" alt=\"Miembros de la familia real miran tributos fuera de Balmoral\" width=\"976\" height=\"549\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/picture>\n<p role=\"text\" class=\"bbc-1s1cxbv ewbcsnk0\"><span class=\"bbc-1gnhmg2 ed7bp6y0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Reuters<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g ebmt73l0\" readability=\"6.5\"><figcaption dir=\"ltr\" class=\"bbc-rhuvwm e6i104o0\" readability=\"3\"><span class=\"bbc-1gnhmg2 ed7bp6y0\">Pie de foto, <\/span><\/p>\n<p>Los miembros de la familia real se detuvieron en su camino de regreso de un servicio de oraci\u00f3n para ver los tributos que se le dejaron a la reina en las afueras de Balmoral el s\u00e1bado.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>El funeral de la reina Isabel II de Inglaterra se realizar\u00e1 el lunes 19 de septiembre en la Abad\u00eda de Westminster en Londres, confirm\u00f3 este s\u00e1bado el Palacio de Buckingham.<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Ser\u00e1 llevada del Palacio de Buckingham a Westminster Hall, en el edificio del Parlamento, el mi\u00e9rcoles, donde el ata\u00fad descansar\u00e1 sobre un catafalco.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">La reina estar\u00e1 en capilla ardiente durante <b>cuatro d\u00edas antes de su funeral<\/b><b>, tiempo en el que el p\u00fablico podr\u00e1 despedirse.<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">El rey Carlos III tambi\u00e9n se embarcar\u00e1 en una gira por las cuatro naciones que conforman Reino Unido.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Esta es una <b>gu\u00eda d\u00eda a d\u00eda<\/b> de c\u00f3mo ser\u00e1 el funeral de Isabel II, quien protagoniz\u00f3 el reinado m\u00e1s largo de la historia brit\u00e1nica.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-172p16q ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-189y18v ebmt73l0\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\"><noscript><picture class=\"bbc-yfiktt e1mo64ex1\"><source srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-1.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-2.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-3.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-4.webp 800w\" type=\"image\/webp\" sizes=\"(min-width: 1008px) 645px, 100vw\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/50D5\/production\/_124939602_queen_index_976x549_v3.png 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/50D5\/production\/_124939602_queen_index_976x549_v3.png 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/50D5\/production\/_124939602_queen_index_976x549_v3.png 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/50D5\/production\/_124939602_queen_index_976x549_v3.png 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/50D5\/production\/_124939602_queen_index_976x549_v3.png 800w\" type=\"image\/png\" sizes=\"(min-width: 1008px) 645px, 100vw\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-1.jpg\" alt=\"Reina Isabel II.\" width=\"976\" height=\"549\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/picture><\/noscript><\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<p><h2 id=\"Domingo-11-de-septiembre\" tabindex=\"-1\" class=\"bbc-1f03ibc eglt09e0\">Domingo 11 de septiembre<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">El ata\u00fad de roble de la reina, que se encuentra en el sal\u00f3n de baile del Castillo de Balmoral (Escocia), donde falleci\u00f3 este jueves, ser\u00e1 transportado a un coche f\u00fanebre.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Su cuerpo partir\u00e1 de Balmoral alrededor de las 10:00 (hora local), avanzando lentamente en el viaje de seis horas a Edimburgo, que se encuentra a m\u00e1s de 160 km de distancia por carretera.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-172p16q ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-189y18v ebmt73l0\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\"><noscript><picture class=\"bbc-yfiktt e1mo64ex1\"><source srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-5.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-6.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-7.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-8.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-9.webp 800w\" type=\"image\/webp\" sizes=\"(min-width: 1008px) 645px, 100vw\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/A023\/production\/_126659904_holyroodhouse_to_st_giles_cathedral_spanish_640_2x-nc.png 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/A023\/production\/_126659904_holyroodhouse_to_st_giles_cathedral_spanish_640_2x-nc.png 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/A023\/production\/_126659904_holyroodhouse_to_st_giles_cathedral_spanish_640_2x-nc.png 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/A023\/production\/_126659904_holyroodhouse_to_st_giles_cathedral_spanish_640_2x-nc.png 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/A023\/production\/_126659904_holyroodhouse_to_st_giles_cathedral_spanish_640_2x-nc.png 800w\" type=\"image\/png\" sizes=\"(min-width: 1008px) 645px, 100vw\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso.png\" alt=\"Ubicaciones clave en Edimburgo del f\u00e9retro de Isabel II\" width=\"1280\" height=\"1042\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/picture><\/noscript><\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">El f\u00e9retro llegar\u00e1 al Palacio de Holyroodhouse -residencia oficial de la monarqu\u00eda brit\u00e1nica en la capital escocesa- y reposar\u00e1 en el Sal\u00f3n del Trono.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">En Londres, el rey se reunir\u00e1 con el secretario general de la Commonwealth en el Palacio de Buckingham. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"7\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Posteriormente recibir\u00e1 a los altos comisionados de los pa\u00edses de los que es jefe de Estado.<\/p>\n<\/div>\n<p><h2 id=\"Lunes-12-de-septiembre\" tabindex=\"-1\" class=\"bbc-1f03ibc eglt09e0\">Lunes 12 de septiembre<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">El rey Carlos comenzar\u00e1 el d\u00eda con una visita a Westminster Hall, donde ambas c\u00e1maras del Parlamento se reunir\u00e1n para expresar sus condolencias.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Acompa\u00f1ado de Camila, la reina consorte, el rey viajar\u00e1 en avi\u00f3n a Edimburgo. Es parte de la operaci\u00f3n Spring Tide, el nombre en clave de su primer viaje por las cuatro naciones del Reino Unido como rey.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-172p16q ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-189y18v ebmt73l0\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\" readability=\"8\"><noscript><picture class=\"bbc-yfiktt e1mo64ex1\"><source srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-10.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-11.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-12.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-13.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-14.webp 800w\" type=\"image\/webp\" sizes=\"(min-width: 1008px) 645px, 100vw\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/16CFC\/production\/_124363439_gettyimages-1314665602abbey.jpg 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/16CFC\/production\/_124363439_gettyimages-1314665602abbey.jpg 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/16CFC\/production\/_124363439_gettyimages-1314665602abbey.jpg 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/16CFC\/production\/_124363439_gettyimages-1314665602abbey.jpg 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/16CFC\/production\/_124363439_gettyimages-1314665602abbey.jpg 800w\" type=\"image\/jpeg\" sizes=\"(min-width: 1008px) 645px, 100vw\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-2.jpg\" alt=\"Westminster Abbey\" width=\"976\" height=\"549\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/picture><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv ewbcsnk0\"><span class=\"bbc-1gnhmg2 ed7bp6y0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g ebmt73l0\" readability=\"6\"><figcaption dir=\"ltr\" class=\"bbc-rhuvwm e6i104o0\" readability=\"2\"><span class=\"bbc-1gnhmg2 ed7bp6y0\">Pie de foto, <\/span><\/p>\n<p>La Abad\u00eda de Westminster.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Por la tarde, el f\u00e9retro de la reina viajar\u00e1 en procesi\u00f3n hasta la Catedral de St Giles, acompa\u00f1ado por el rey y miembros de la familia real.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">El cuerpo de la reina estar\u00e1 en una capilla ardiente en St Giles durante 24 horas y los miembros del p\u00fablico podr\u00e1n presentar sus respetos.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">A continuaci\u00f3n, el rey regresar\u00e1 a Holyrood, donde tendr\u00e1 una audiencia con la primera ministra escocesa, Nicola Sturgeon. \u00c9l y la reina consorte luego asistir\u00e1n al parlamento escoc\u00e9s, donde recibir\u00e1n una moci\u00f3n de condolencia.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Por la noche, el rey Carlos realizar\u00e1 una vigilia con miembros de la familia real en la Catedral de St Giles.<\/p>\n<\/div>\n<p><h2 id=\"Martes-13-de-septiembre\" tabindex=\"-1\" class=\"bbc-1f03ibc eglt09e0\">Martes 13 de septiembre<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"14\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">La princesa Ana, la \u00fanica hija de la reina, acompa\u00f1ar\u00e1 el ata\u00fad desde la Catedral de St Giles hasta el aeropuerto de Edimburgo, y luego, seg\u00fan lo planeado, hasta la base de la fuerza a\u00e9rea real RAF Northolt.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Se espera que el \u00faltimo vuelo de la reina de Escocia a Londres llegue poco antes de las 19:00 hora local.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Desde all\u00ed viajar\u00e1 al Palacio de Buckingham, residencia oficial de los monarcas brit\u00e1nicos en Londres desde 1837. La llegada del ata\u00fad al palacio ser\u00e1 presenciada por el rey Carlos III y Camilla, la reina consorte, antes de ser llevado al Bow Room.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"e18mih2h1 bbc-9m7iam ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-vx18wi ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-rprdln ebmt73l0\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\" readability=\"8\"><noscript><picture class=\"bbc-yfiktt e1mo64ex1\"><source srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-15.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-16.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-17.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-18.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-19.webp 800w\" type=\"image\/webp\" sizes=\"(min-width: 1008px) 645px, 100vw\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/142FE\/production\/_126668628_19fc332646a1b49088f1f91483c4050d8c86f79e.jpg 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/142FE\/production\/_126668628_19fc332646a1b49088f1f91483c4050d8c86f79e.jpg 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/142FE\/production\/_126668628_19fc332646a1b49088f1f91483c4050d8c86f79e.jpg 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/142FE\/production\/_126668628_19fc332646a1b49088f1f91483c4050d8c86f79e.jpg 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/142FE\/production\/_126668628_19fc332646a1b49088f1f91483c4050d8c86f79e.jpg 800w\" type=\"image\/jpeg\" sizes=\"(min-width: 1008px) 645px, 100vw\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-3.jpg\" alt=\"El rey Carlos III y la reina consorte Camila.\" width=\"2333\" height=\"3500\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/picture><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv ewbcsnk0\"><span class=\"bbc-1gnhmg2 ed7bp6y0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Reuters<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Antes de eso, el rey y Camilla visitar\u00e1n Belfast en Irlanda del Norte. Luego viajar\u00e1n al Castillo de Hillsborough para ver una exposici\u00f3n sobre la larga asociaci\u00f3n de la reina con Irlanda del Norte.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">El rey Carlos se reunir\u00e1 luego con el secretario de Estado para Irlanda del Norte, el diputado Chris Heaton-Harris, as\u00ed como con otros l\u00edderes del partido. Tambi\u00e9n recibir\u00e1 un mensaje de condolencias encabezado por el presidente de la Asamblea de Irlanda del Norte.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Despu\u00e9s de una reuni\u00f3n con l\u00edderes religiosos, el rey Carlos y Camila asistir\u00e1n a un servicio de oraci\u00f3n en la Catedral de Santa Ana y luego regresar\u00e1n a Londres.<\/p>\n<\/div>\n<p><h2 id=\"Mi\u00e9rcoles-14-de-septiembre\" tabindex=\"-1\" class=\"bbc-1f03ibc eglt09e0\">Mi\u00e9rcoles 14 de septiembre<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">El cuerpo de la reina se trasladar\u00e1 en procesi\u00f3n desde el Palacio de Buckingham hasta Westminster Hall por la tarde.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Su f\u00e9retro ser\u00e1 transportado en una carroza de la Tropa Real de Artiller\u00eda a Caballo del rey, y estar\u00e1 acompa\u00f1ado por un desfile militar y miembros de la familia real.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"7\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">El rey Carlos encabezar\u00e1 la procesi\u00f3n detr\u00e1s del carruaje.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-37mmq3 ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-189y18v ebmt73l0\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\"><noscript><picture class=\"bbc-yfiktt e1mo64ex1\"><source srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-20.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-21.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-22.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-23.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-24.webp 800w\" type=\"image\/webp\" sizes=\"(min-width: 1008px) 645px, 100vw\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/3830\/production\/_126648341_procesion_mundo_640x2-nc-003.png 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/3830\/production\/_126648341_procesion_mundo_640x2-nc-003.png 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/3830\/production\/_126648341_procesion_mundo_640x2-nc-003.png 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/3830\/production\/_126648341_procesion_mundo_640x2-nc-003.png 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/3830\/production\/_126648341_procesion_mundo_640x2-nc-003.png 800w\" type=\"image\/png\" sizes=\"(min-width: 1008px) 645px, 100vw\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-4.jpg\" alt=\"Procesi\u00f3n para el velorio del Isabel II.\" width=\"1280\" height=\"1280\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/picture><\/noscript><\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"7\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">La gente podr\u00e1 verlo mientras recorre las calles de Londres.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Tambi\u00e9n habr\u00e1 grandes pantallas de televisi\u00f3n instaladas para la ocasi\u00f3n especialmente en los parques reales de la capital.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">La procesi\u00f3n viajar\u00e1 a lo largo de Queen&#8217;s Gardens, The Mall, Horse Guards y Horse Guards Arch, Whitehall, Parliament Street, Parliament Square y New Palace Yard.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Una vez en Westminster Hall, el ata\u00fad ser\u00e1 ubicado sobre una plataforma elevada conocida como catafalco, envuelto en el estandarte real, y se le colocar\u00e1 encima la corona imperial del Estado, el orbe y el cetro.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-172p16q ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-189y18v ebmt73l0\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\" readability=\"8\"><noscript><picture class=\"bbc-yfiktt e1mo64ex1\"><source srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-25.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-26.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-27.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-28.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-29.webp 800w\" type=\"image\/webp\" sizes=\"(min-width: 1008px) 645px, 100vw\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/A978\/production\/_126648334_gettyimages-930175812.jpg 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/A978\/production\/_126648334_gettyimages-930175812.jpg 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/A978\/production\/_126648334_gettyimages-930175812.jpg 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/A978\/production\/_126648334_gettyimages-930175812.jpg 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/A978\/production\/_126648334_gettyimages-930175812.jpg 800w\" type=\"image\/jpeg\" sizes=\"(min-width: 1008px) 645px, 100vw\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-5.jpg\" alt=\"La reina madre fue velada en el Sal\u00f3n de Westminster en 2002.\" width=\"976\" height=\"650\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/picture><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv ewbcsnk0\"><span class=\"bbc-1gnhmg2 ed7bp6y0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g ebmt73l0\" readability=\"6\"><figcaption dir=\"ltr\" class=\"bbc-rhuvwm e6i104o0\" readability=\"2\"><span class=\"bbc-1gnhmg2 ed7bp6y0\">Pie de foto, <\/span><\/p>\n<p>La reina madre fue velada en el Sal\u00f3n de Westminster en 2002.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Cada esquina de la plataforma estar\u00e1 custodiada por soldados de las unidades al servicio de la casa real.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">El arzobispo de Canterbury, Justin Welby, llevar\u00e1 a cabo un breve servicio religioso al que asistir\u00e1n el rey Carlos y otros miembros de la familia real antes de que el sal\u00f3n se abra al p\u00fablico.<\/p>\n<\/div>\n<p><h2 id=\"Jueves-15-de-septiembre\" tabindex=\"-1\" class=\"bbc-1f03ibc eglt09e0\">Jueves 15 de septiembre<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Este es el primer d\u00eda de los cuatro en los que el cuerpo de la reina permanecer\u00e1 en Westminster Hall hasta la ma\u00f1ana del funeral de Estado.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Se espera que cientos de miles de personas puedan presentar sus respetos en el edificio del siglo XI, la parte m\u00e1s antigua del Palacio de Westminster y el coraz\u00f3n del gobierno brit\u00e1nico. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"e18mih2h1 bbc-9m7iam ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-vx18wi ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-rprdln ebmt73l0\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\"><noscript><picture class=\"bbc-yfiktt e1mo64ex1\"><source srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-30.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-31.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-32.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-33.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-34.webp 800w\" type=\"image\/webp\" sizes=\"(min-width: 1008px) 645px, 100vw\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/1120\/production\/_126648340_ataud_mundo_640x2-nc.png 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/1120\/production\/_126648340_ataud_mundo_640x2-nc.png 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/1120\/production\/_126648340_ataud_mundo_640x2-nc.png 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/1120\/production\/_126648340_ataud_mundo_640x2-nc.png 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/1120\/production\/_126648340_ataud_mundo_640x2-nc.png 800w\" type=\"image\/png\" sizes=\"(min-width: 1008px) 645px, 100vw\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-1.png\" alt=\"estandarte real, corona imperial del Estado, orbe y cetro que se colocar\u00e1n al f\u00e9retro de la reina Isabel II\" width=\"2560\" height=\"4480\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/picture><\/noscript><\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<p><h2 id=\"Viernes-16-de-septiembre\" tabindex=\"-1\" class=\"bbc-1f03ibc eglt09e0\">Viernes 16 de septiembre<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">El ata\u00fad de la reina permanecer\u00e1 por segundo d\u00eda en Westminster Hall, donde la gente podr\u00e1 presentar sus respetos.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">El rey y Camilla viajar\u00e1n a Gales, la \u00faltima de su primera visita a las cuatro naciones de Reino Unido como rey.<\/p>\n<\/div>\n<p><h2 id=\"Lunes-19-de-septiembre\" tabindex=\"-1\" class=\"bbc-1f03ibc eglt09e0\">Lunes 19 de septiembre<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Durante la ma\u00f1ana el ata\u00fad ser\u00e1 llevado en procesi\u00f3n a la Abad\u00eda de Westminster para el funeral de Estado.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-37mmq3 ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-189y18v ebmt73l0\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\"><noscript><picture class=\"bbc-yfiktt e1mo64ex1\"><source srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-35.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-36.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-37.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-38.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-39.webp 800w\" type=\"image\/webp\" sizes=\"(min-width: 1008px) 645px, 100vw\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/6B5C\/production\/_126648472_abadia_mundo_640x2-nc-2x.png 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/6B5C\/production\/_126648472_abadia_mundo_640x2-nc-2x.png 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/6B5C\/production\/_126648472_abadia_mundo_640x2-nc-2x.png 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/6B5C\/production\/_126648472_abadia_mundo_640x2-nc-2x.png 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/6B5C\/production\/_126648472_abadia_mundo_640x2-nc-2x.png 800w\" type=\"image\/png\" sizes=\"(min-width: 1008px) 645px, 100vw\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-6.jpg\" alt=\"Gr\u00e1fico Sal\u00f3n de Westminster y Abad\u00eda de Westminster.\" width=\"2560\" height=\"2560\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/picture><\/noscript><\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"e18mih2h1 bbc-9m7iam ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-vx18wi ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-rprdln ebmt73l0\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\"><noscript><picture class=\"bbc-yfiktt e1mo64ex1\"><source srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-40.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-41.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-42.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-43.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-44.webp 800w\" type=\"image\/webp\" sizes=\"(min-width: 1008px) 645px, 100vw\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/16CC8\/production\/_126648339_dentro_abadia_mundo_640x2-nc.png 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/16CC8\/production\/_126648339_dentro_abadia_mundo_640x2-nc.png 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/16CC8\/production\/_126648339_dentro_abadia_mundo_640x2-nc.png 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/16CC8\/production\/_126648339_dentro_abadia_mundo_640x2-nc.png 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/16CC8\/production\/_126648339_dentro_abadia_mundo_640x2-nc.png 800w\" type=\"image\/png\" sizes=\"(min-width: 1008px) 645px, 100vw\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-2.png\" alt=\"Interior Abad\u00eda de Westminster\" width=\"1280\" height=\"1822\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/picture><\/noscript><\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Entre los invitados que se unir\u00e1n a los miembros de su familia estar\u00e1n altos pol\u00edticos de Reino Unido y jefes de Estado de todo el mundo.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Despu\u00e9s del funeral, el ata\u00fad viajar\u00e1 en procesi\u00f3n desde la Abad\u00eda de Westminster hasta Wellington Arch, desde donde viajar\u00e1 a Windsor.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-172p16q ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-189y18v ebmt73l0\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\"><noscript><picture class=\"bbc-yfiktt e1mo64ex1\"><source srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-45.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-46.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-47.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-48.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-49.webp 800w\" type=\"image\/webp\" sizes=\"(min-width: 1008px) 645px, 100vw\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/145B8\/production\/_126648338_windsor_mundo_640x2-nc.png 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/145B8\/production\/_126648338_windsor_mundo_640x2-nc.png 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/145B8\/production\/_126648338_windsor_mundo_640x2-nc.png 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/145B8\/production\/_126648338_windsor_mundo_640x2-nc.png 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/145B8\/production\/_126648338_windsor_mundo_640x2-nc.png 800w\" type=\"image\/png\" sizes=\"(min-width: 1008px) 645px, 100vw\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-3.png\" alt=\"Procesi\u00f3n funeraria del f\u00e9retro de Isabel II a Windsor.\" width=\"1280\" height=\"1068\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/picture><\/noscript><\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">El coche f\u00fanebre llevar\u00e1 el ata\u00fad a lo largo de Long Walk hasta la Capilla de San Jorge en la Capilla de Windsor, donde se llevar\u00e1 a cabo un servicio de entierro religioso.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"e18mih2h1 bbc-9m7iam ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-vx18wi ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-rprdln ebmt73l0\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\"><noscript><picture class=\"bbc-yfiktt e1mo64ex1\"><source srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-50.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-51.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-52.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-53.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-54.webp 800w\" type=\"image\/webp\" sizes=\"(min-width: 1008px) 645px, 100vw\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/926C\/production\/_126648473_capilla_mundo_640x2-nc-003.png 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/926C\/production\/_126648473_capilla_mundo_640x2-nc-003.png 320w, https:\/\/ichef.bbci.co.uk\/news\/480\/cpsprodpb\/926C\/production\/_126648473_capilla_mundo_640x2-nc-003.png 480w, https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/926C\/production\/_126648473_capilla_mundo_640x2-nc-003.png 624w, https:\/\/ichef.bbci.co.uk\/news\/800\/cpsprodpb\/926C\/production\/_126648473_capilla_mundo_640x2-nc-003.png 800w\" type=\"image\/png\" sizes=\"(min-width: 1008px) 645px, 100vw\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-7.jpg\" alt=\"Dentro de la capilla de San Jorge\" width=\"1280\" height=\"1836\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/picture><\/noscript><\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Habr\u00e1 un per\u00edodo de duelo nacional hasta el d\u00eda del funeral de Estado, anunci\u00f3 el gobierno. La familia real cumplir\u00e1 un per\u00edodo de luto durante siete d\u00edas m\u00e1s.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-172p16q ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-189y18v ebmt73l0\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\"><noscript><picture class=\"bbc-yfiktt e1mo64ex1\"><source srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-55.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-56.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-57.webp 464w\" type=\"image\/webp\" sizes=\"(min-width: 1008px) 645px, 100vw\"><source srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/16B24\/production\/_109446929_line976.jpg 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/16B24\/production\/_109446929_line976.jpg 320w, https:\/\/ichef.bbci.co.uk\/news\/464\/cpsprodpb\/16B24\/production\/_109446929_line976.jpg 464w\" type=\"image\/jpeg\" sizes=\"(min-width: 1008px) 645px, 100vw\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/09\/cuando-y-como-sera-el-funeral-de-la-reina-isabel-ii-guia-paso-a-paso-8.jpg\" alt=\"L\u00ednea\" width=\"464\" height=\"2\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/picture><\/noscript><\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><i class=\"bbc-h1y5j7 eih42320\">Recuerda que puedes recibir notificaciones de BBC News Mundo. Descarga la nueva versi\u00f3n de nuestra app y act\u00edvalas para no perderte nuestro mejor contenido.<\/i><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n BBC News Mundo 10 septiembre 2022, 16:51 GMT Actualizado 2 horas Fuente de la imagen, Reuters Pie de foto, Los miembros de la familia real se detuvieron en su camino de regreso de un servicio de oraci\u00f3n para ver los tributos que se le dejaron a la reina en las afueras de Balmoral el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24191,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24190"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=24190"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/24190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/24191"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=24190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=24190"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=24190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}