{"id":25887,"date":"2022-10-31T16:29:54","date_gmt":"2022-10-31T16:29:54","guid":{"rendered":"https:\/\/prensa.cba.gov.ar\/?p=523871"},"modified":"2022-10-31T16:29:54","modified_gmt":"2022-10-31T16:29:54","slug":"rio-cuarto-schiaretti-anuncio-15-centros-comerciales-a-cielo-abierto","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2022\/10\/31\/rio-cuarto-schiaretti-anuncio-15-centros-comerciales-a-cielo-abierto\/","title":{"rendered":"R\u00edo Cuarto: Schiaretti anunci\u00f3 15 centros comerciales a cielo abierto"},"content":{"rendered":"<ul>\n<li><strong>El gobernador encabez\u00f3 la firma del acuerdo de cooperaci\u00f3n entre la Provincia, 15 municipios y c\u00e1maras del sector comercial.<\/strong><\/li>\n<li><strong>Surgi\u00f3 de la sinergia entre los sectores p\u00fablico y privado para generar un espacio comercial delimitado, ordenado, sustentable y competitivo.<\/strong><\/li>\n<li><strong>Se pretende mejorar las condiciones de habitabilidad urbanas y el fortalecimiento del comercio minorista.<\/strong><\/li>\n<\/ul>\n<p>El gobernador Juan Schiaretti presidi\u00f3 este lunes, en la ciudad de R\u00edo Cuarto, la firma del convenio marco de cooperaci\u00f3n institucional para el desarrollo y ejecuci\u00f3n de centros comerciales a cielo abierto<strong> <\/strong>de la provincia de C\u00f3rdoba.&nbsp;<\/p>\n<p>El acuerdo fue suscrito por la Provincia, 15 municipios y c\u00e1maras del sector comercial. La intenci\u00f3n es contribuir al desarrollo y la gesti\u00f3n de los centros comerciales a cielo abierto en la provincia de C\u00f3rdoba, con una mejora de las condiciones de habitabilidad urbana y el fortalecimiento competitivo de las peque\u00f1as y medianas empresas dedicadas al comercio minorista y la prestaci\u00f3n de servicios.<\/p>\n<p>Durante el acto, que tuvo lugar en la sede del Centro Empresario, Comercial, Industrial y de Servicios (Cecis), Schiaretti expres\u00f3: \u201c<em>Los centros comerciales a cielo abierto son, por un lado, el mejoramiento y embellecimiento de una ciudad; y por el otro, el facilitarle y mejorarle la vida a sus habitantes cuando tienen que realizar una compra, ir a tomar algo a un bar o ir a comer en un restaurante<\/em>\u201d.<\/p>\n<p>\u201c<em>Significa tambi\u00e9n hacer sinergia entre el sector p\u00fablico, los intendentes, con la colaboraci\u00f3n del Estado provincial, para que nuestros comercios y prestadores de servicio puedan vender m\u00e1s mercader\u00eda y mejores servicios. Y mayor venta significa mayor actividad econ\u00f3mica, mayor posibilidad de puestos de trabajo. Y trabajo es lo que precisamos para progresar en nuestra provincia<\/em>\u201d, a\u00f1adi\u00f3.<\/p>\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2022\/10\/Schiaretti-Rio-Cuarto-31-10.mp3\"><\/audio><figcaption>Audio: Juan Schiaretti<\/figcaption><\/figure>\n<figure class=\"wp-container-2 wp-block-gallery-1 wp-block-gallery has-nested-images columns-default is-cropped has-lightbox\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1599\" height=\"1066\" data-id=\"523877\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/10\/rio-cuarto-schiaretti-anuncio-15-centros-comerciales-a-cielo-abierto.jpg\" alt class=\"wp-image-523877\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1599\" height=\"1066\" data-id=\"523887\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/10\/rio-cuarto-schiaretti-anuncio-15-centros-comerciales-a-cielo-abierto-1.jpg\" alt class=\"wp-image-523887\"><\/figure>\n<\/figure>\n<p>El convenio fue suscripto por los intendentes de: R\u00edo Cuarto, Juan Manuel Llamosas; Villa General Belgrano, Oscar Santarelli; Cosqu\u00edn, Gabriel Musso; Miramar de Ansenuza, Adri\u00e1n Walker; Jes\u00fas Mar\u00eda, Luis Picat; Santa Rosa de Calamuchita, Claudio Chavero; San Francisco, Dami\u00e1n Bernarte; Colonia Caroya, Gustavo Brand\u00e1n; Bell Ville, Carlos Briner; Cruz del Eje, Claudio Far\u00edas; Alta Gracia, Marcos Torres Lima; General Deheza, Franco Morra; Villa Nueva, Natalio Graglia; Arroyito, Gustavo Benedetti; y el jefe de gabinete de Villa Mar\u00eda, H\u00e9ctor Mu\u00f1oz.&nbsp;<\/p>\n<p>El intendente local Juan Manuel Llamosas agradeci\u00f3 al gobernador \u201c<em>por esta visi\u00f3n de articulaci\u00f3n con el sector privado, no solo con el comercio, sino tambi\u00e9n con el campo, con los consorcios, industrias, con cada acci\u00f3n que hace m\u00e1s efectivos los recursos, aportando todos: Gobierno provincial, municipal, y el sector privado, lo que redunda en desarrollo y m\u00e1s beneficios<\/em>\u201d.<\/p>\n<p>A su turno, el ministro de Industria, Comercio y Miner\u00eda, Eduardo Accastello, indic\u00f3: \u201c<em>Las buenas iniciativas e ideas las transformamos en pol\u00edticas p\u00fablicas como esta, que es la estrategia de trabajo en nuevas herramientas de consumo para que, articulado de manera asociativa entre el sector p\u00fablico y el privado, se generen mayores ventajas para los comerciantes<\/em>\u201d.&nbsp;<\/p>\n<p>\u201c<em>Es una promoci\u00f3n de la actividad comercial, una difusi\u00f3n, una revitalizaci\u00f3n de los espacios comunes con acciones complementarias en materia de seguridad, tecnol\u00f3gica y de conectividad<\/em>\u201d, agreg\u00f3 el funcionario.&nbsp;<\/p>\n<figure class=\"wp-container-4 wp-block-gallery-3 wp-block-gallery has-nested-images columns-default is-cropped has-lightbox\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1599\" height=\"1066\" data-id=\"523884\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/10\/rio-cuarto-schiaretti-anuncio-15-centros-comerciales-a-cielo-abierto-2.jpg\" alt class=\"wp-image-523884\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1599\" height=\"1066\" data-id=\"523885\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/10\/rio-cuarto-schiaretti-anuncio-15-centros-comerciales-a-cielo-abierto-3.jpg\" alt class=\"wp-image-523885\"><\/figure>\n<\/figure>\n<p>Acastello detall\u00f3 adem\u00e1s que la inversi\u00f3n total de la iniciativa es de 450 millones de pesos, importe que aporta mitad la Provincia y mitad los municipios (30 millones cada localidad).&nbsp;<\/p>\n<p>Cabe destacar que los fondos para arrancar con los 15 centros comerciales a cielo abierto estar\u00e1n a disposici\u00f3n de los municipios en 30 d\u00edas. El plan es comenzar y concluir las obras cuanto antes, a la vez que ampliar el programa en 2023 a 10 municipios m\u00e1s, remarc\u00f3 el ministro de Industria, Comercio y Miner\u00eda.<\/p>\n<h4><strong>Trabajo p\u00fablico-privado<\/strong><\/h4>\n<p>Tambi\u00e9n adhirieron al convenio los presidentes de la Confederaci\u00f3n Argentina de la Mediana Empresa, Alfredo Gonz\u00e1lez; la Federaci\u00f3n Comercial de C\u00f3rdoba, Ezequiel Cerezo; y la C\u00e1mara de Comercio de C\u00f3rdoba, Jos\u00e9 Viale.&nbsp;<\/p>\n<p>El acuerdo se sustenta en la sinergia entre los sectores p\u00fablico y privado para lograr un espacio comercial delimitado, ordenado, sustentable y competitivo.<\/p>\n<p>En este sentido, el presidente de la Confederaci\u00f3n Argentina de la Mediana Empresa (Came), Alfredo Gonz\u00e1lez, destac\u00f3 el trabaj\u00f3 entre el sector privado y el estado: \u201c<em>Esta acci\u00f3n es la primera vez que se genera en este formato y no tengo dudas de que se va a repetir en otras provincias. Por eso, quiero felicitar al gobernador, a todo su equipo y a los intendentes. En Came van a encontrar siempre interlocutores v\u00e1lidos para poder trasladar estas acciones p\u00fablico-privadas<\/em>\u201d.<\/p>\n<figure class=\"wp-container-6 wp-block-gallery-5 wp-block-gallery has-nested-images columns-default is-cropped has-lightbox\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1599\" height=\"1066\" data-id=\"523879\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/10\/rio-cuarto-schiaretti-anuncio-15-centros-comerciales-a-cielo-abierto-4.jpg\" alt class=\"wp-image-523879\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1392\" height=\"928\" data-id=\"523890\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/10\/rio-cuarto-schiaretti-anuncio-15-centros-comerciales-a-cielo-abierto-5.jpg\" alt class=\"wp-image-523890\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1599\" height=\"1066\" data-id=\"523878\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/10\/rio-cuarto-schiaretti-anuncio-15-centros-comerciales-a-cielo-abierto-6.jpg\" alt class=\"wp-image-523878\"><\/figure>\n<\/figure>\n<p>Por su parte, el presidente de la Federaci\u00f3n Comercial de C\u00f3rdoba, Ezequiel Cerezo, consider\u00f3 que \u201c<em>este nuevo modelo asociativo es para nosotros muy virtuoso; no tenemos duda que va a generar muchos beneficios, no solamente para el comercio minorista sino tambi\u00e9n para toda la sociedad, generando recursos innovadores para la ciudad y permitiendo que comerciantes, residentes y visitantes lo puedan disfrutar<\/em>\u201d.<\/p>\n<p>En otro momento de su alocuci\u00f3n, Juan Schiaretti subray\u00f3: \u201c<em>Esta iniciativa parti\u00f3 del sector comercial de la provincia de C\u00f3rdoba, por un lado, y de la Came, que es un organismo nacional que nuclea a numerosos comerciantes. Y como es una buena iniciativa que corresponde a lo que somos, sentimos y actuamos los cordobeses, la adoptamos y la llevamos adelante<\/em>\u201d.&nbsp;<\/p>\n<p>Acompa\u00f1aron tambi\u00e9n al gobernador el diputado nacional Carlos Guti\u00e9rrez; la directora general del Centro C\u00edvico en R\u00edo Cuarto, Samantha David; legisladores y dem\u00e1s autoridades.&nbsp;&nbsp;<\/p>\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/10\/rio-cuarto-schiaretti-anuncio-15-centros-comerciales-a-cielo-abierto-7.jpg\" alt class=\"wp-image-523881\" width=\"599\" height=\"399\"><\/figure>\n<h4>Comercios minoristas<\/h4>\n<p>Los centros comerciales a cielo abierto son organizaciones de comerciantes minoristas que trabajan con una planificaci\u00f3n urbana y comercial sustentable, a fines de lograr una identidad propia y distintiva.&nbsp;<\/p>\n<p>Se busca incorporar mejores condiciones para los ciudadanos y gestionar, de manera conjunta, la oferta comercial del sector con estructura gerencial, imagen com\u00fan, variedad y calidad en la oferta de productos y servicios, para procurar as\u00ed un entorno urbano agradable, accesible y seguro para los clientes.<\/p>\n<p><em>\u201cNosotros somos la expresi\u00f3n y queremos ser la voz de aquellos que cuidan, defienden y promueven la producci\u00f3n y el trabajo. Eso es C\u00f3rdoba y eso tambi\u00e9n es lo que queremos para nuestra Patria<\/em>\u201d, dijo el gobernador sobre el final de su discurso.&nbsp;<\/p>\n<p>Y concluy\u00f3: \u201c<em>Queremos que haya producci\u00f3n y trabajo. Por eso lo promovemos, por eso tomamos las iniciativas que nos presentan quienes representan al sector privado. Juntos es como vamos a conseguir que haya m\u00e1s producci\u00f3n y empleo<\/em>\u201d.&nbsp;<\/p>\n<figure class=\"wp-container-8 wp-block-gallery-7 wp-block-gallery has-nested-images columns-default is-cropped has-lightbox\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1392\" height=\"928\" data-id=\"523888\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/10\/rio-cuarto-schiaretti-anuncio-15-centros-comerciales-a-cielo-abierto-8.jpg\" alt class=\"wp-image-523888\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1392\" height=\"928\" data-id=\"523886\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/10\/rio-cuarto-schiaretti-anuncio-15-centros-comerciales-a-cielo-abierto-9.jpg\" alt class=\"wp-image-523886\"><\/figure>\n<\/figure>\n<h4>Seg\u00fan el convenio, las partes firmantes buscan:<\/h4>\n<ul>\n<li>Contribuir a la modernizaci\u00f3n y sostenibilidad econ\u00f3mica de los comercios minoristas y empresas de servicios, en particular las peque\u00f1as y medianas, ubicadas en centros comerciales a cielo abierto.<\/li>\n<li>Crear condiciones de mejor accesibilidad de los centros comerciales urbanos para los habitantes y visitantes de las ciudades que adhieran al programa.<\/li>\n<li>Revitalizar los centros comerciales urbanos y cascos hist\u00f3ricos de las ciudades.<\/li>\n<li>Mejorar la calidad del servicio al p\u00fablico por parte de los comercios minoristas.<\/li>\n<li>Incrementar los puestos de trabajo en el sector comercial y de servicios.<\/li>\n<li>Mejorar la comunicaci\u00f3n y la promoci\u00f3n de la oferta comercial y tur\u00edstica de las ciudades, en particular de las zonas comerciales.<\/li>\n<li>Integrar en los centros tradicionales de las ciudades las actividades comerciales con las culturales, tur\u00edsticas y de recreaci\u00f3n social.&nbsp;<\/li>\n<li>Inducir la inversi\u00f3n de los sectores p\u00fablico y privado en los centros comerciales urbanos.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador encabez\u00f3 la firma del acuerdo de cooperaci\u00f3n entre la Provincia, 15 municipios y c\u00e1maras del sector comercial. Surgi\u00f3 de la sinergia entre los sectores p\u00fablico y privado para generar un espacio comercial delimitado, ordenado, sustentable y competitivo. Se pretende mejorar las condiciones de habitabilidad urbanas y el fortalecimiento del comercio minorista. El gobernador [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25888,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/25887"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=25887"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/25887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/25888"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=25887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=25887"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=25887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}