{"id":27817,"date":"2022-12-29T22:27:09","date_gmt":"2022-12-29T22:27:09","guid":{"rendered":"https:\/\/www.ole.com.ar\/autos\/dakar-estanguet-problema-salud-baja-argentinos-arabia_0_PMf3Zaq8hf.html"},"modified":"2022-12-29T22:27:09","modified_gmt":"2022-12-29T22:27:09","slug":"antes-de-comenzar-el-dakar-se-quedo-sin-un-argentino","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2022\/12\/29\/antes-de-comenzar-el-dakar-se-quedo-sin-un-argentino\/","title":{"rendered":"Antes de comenzar, el Dakar se qued\u00f3 sin un argentino"},"content":{"rendered":"<div class=\"custom-text \" readability=\"42.76707530648\">\n<p>A dos d\u00edas del comienzo del <a href=\"https:\/\/www.ole.com.ar\/tema\/rally-dakar.html\" title=\"Rally Dakar\" alt=\"Rally Dakar\" class=\"slug\">Rally Dakar 2023<\/a>, el cual iniciar\u00e1 el <strong>s\u00e1bado en Yanbu, Arabia Saudita<\/strong>, se dio la<strong> primera baja de un piloto argentino<\/strong>, el cual temi\u00f3 por su salud y debi\u00f3 ser internado en el pa\u00eds \u00e1rabe. Ya desde el comienzo de su viaje, el cordob\u00e9s de 55 a\u00f1os, <strong>Julio C\u00e9sar Estanguet, <\/strong>sufri\u00f3 varios problemas con su equipaje, pero el mayor problemalresult\u00f3 cuando<strong> le detectaron una trombosis venosa, lo que hizo que se quede afuera de su despedida deportiva corriendo en cuatriciclo<\/strong> tras la recomendaci\u00f3n de reposo por los profesionales de la salud.<\/p>\n<\/div>\n<div class=\"sc-996041c8-0 kvfKM\"><img alt=\"Estanguet comunic\u00f3 que sus redes sociales que no disputar\u00e1 el Rally Dakar 2023. (instagram:julioestanguet) \" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/12\/antes-de-comenzar-el-dakar-se-quedo-sin-un-argentino.jpg\" width=\"720\" height=\"0\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span>Estanguet comunic\u00f3 que sus redes sociales que no disputar\u00e1 el Rally Dakar 2023. (instagram:julioestanguet) <\/span><\/div>\n<div class=\"custom-text \" readability=\"39\">\n<p>De la ilusi\u00f3n por<strong> cerrar una carrera deportiva de m\u00e1s de una d\u00e9cada sobre los quads<\/strong> en diferentes competencias, superando obst\u00e1culos y armando un equipo propio de gran nivel, a un presente dif\u00edcil de asimilar.<strong> As\u00ed se encontr\u00f3 Estanguet con la noticia de que una trombosis le llev\u00f3 a cambiar de planes y enfocarse en una recuperaci\u00f3n a distancia desde Arabia Saudita<\/strong>, replanteando el conjunto deportivo a su cargo para el regreso a Argentina. Coment\u00f3 el cordob\u00e9s en Campeones: <strong>\u00abEstoy muy triste, pas\u00e9 toda la noche llorando. Nunca me hubiera imaginado estar a punto de largar y no poder hacerlo\u00bb.<\/strong><\/p>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"7\">\n<section readability=\"4\"><picture><img class=\"img\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/12\/antes-de-comenzar-el-dakar-se-quedo-sin-un-argentino-1.jpg\" alt=\"Kevin Benavides: el bi en el Dakar, la cabeza, Messi y m\u00e1s \" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Kevin Benavides: el bi en el Dakar, la cabeza, Messi y m\u00e1s <\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"custom-text \" readability=\"35\">\n<p>\u00abDespu\u00e9s de cuatro d\u00edas de vuelos empec\u00e9 a sentir un dolor en la pantorrilla pensando que era un calambre.<strong> Se hizo insostenible y fui directo al hospital<\/strong>. Tras la revisi\u00f3n se <strong>me diagnostic\u00f3 trombosis en el gemelo a la altura de la rodilla\u00bb<\/strong>, detall\u00f3 desde Arabia el piloto argentino. <\/p>\n<\/div>\n<div class=\"sc-996041c8-0 kvfKM\"><img alt=\"El Dakar comenzar\u00e1 su primera jornada el 31 de diciembre y finalizar\u00e1n el domingo 15 de enero. (EFE)\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/12\/antes-de-comenzar-el-dakar-se-quedo-sin-un-argentino-2.jpg\" width=\"720\" height=\"0\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span>El Dakar comenzar\u00e1 su primera jornada el 31 de diciembre y finalizar\u00e1n el domingo 15 de enero. (EFE)<\/span><\/div>\n<div class=\"custom-text \" readability=\"39\">\n<p>La organizaci\u00f3n de la competencia<strong> eval\u00faa poder brindarle a Julio Estanguet y su equipo la posibilidad de acompa\u00f1ar a la caravana<\/strong> en los d\u00edas de competencia que resten luego de su alta m\u00e9dica. La r\u00e1pida evoluci\u00f3n de su inflamaci\u00f3n y la mejor\u00eda de estas horas alienta a que el piloto pueda al menos estar en los campamentos del Dakar durante su recuperaci\u00f3n y vivir de cerca esta edici\u00f3n de la carrera m\u00e1s dif\u00edcil del mundo, la cual ser\u00eda su despedida como piloto: <strong>\u00abFueron 15 a\u00f1os que le dediqu\u00e9 a esta actividad y quiero irme en un gran evento, como un Dakar. Por eso me inscrib\u00ed, para darle el adi\u00f3s a la competencia\u00bb,<\/strong> indic\u00f3.<\/p>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/12\/antes-de-comenzar-el-dakar-se-quedo-sin-un-argentino-3.jpg\" alt=\"La ACTC no autoriz\u00f3 a Facundo Chapur\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>La ACTC no autoriz\u00f3 a Facundo Chapur<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"custom-text \" readability=\"40\">\n<p><strong>\u00abAhora tengo que cuidar mi salud, no tengo ninguna posibilidad de correr\u00bb<\/strong>, asegur\u00f3 el argentino. \u00abTengo que pensar en recuperarme ac\u00e1 lo mejor posible para que me den una fecha y poder tomar un avi\u00f3n dentro de unas semanas\u00bb, detall\u00f3 desde el hospital en Arabia el cordob\u00e9s de R\u00edo Cuarto, quien sufri\u00f3 m\u00e1s inconvenientes en su traves\u00eda hasta all\u00e1. Cuando lleg\u00f3 a Yanbu uno de sus tres bolsos con su ropa de competencia no arrib\u00f3 a destino, aunque \u00e9ste fue un problema menor.<\/p>\n<\/div>\n<p><h2><strong>Ahora son 30 los argentinos<\/strong><\/h2>\n<\/p>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2022\/12\/antes-de-comenzar-el-dakar-se-quedo-sin-un-argentino-4.jpg\" alt=\"Un jugador de la NBA termin\u00f3 noqueado tras un golpe por la espalda\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Un jugador de la NBA termin\u00f3 noqueado tras un golpe por la espalda<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"custom-text \">\n<ul>\n<li>29 Diego Llanos &#8211; Motos<\/li>\n<li>37 Franco Caimi &#8211; Motos<\/li>\n<li>42 Stefano Caimi &#8211; Motos<\/li>\n<li>47 Kevin Benavides &#8211; Motos<\/li>\n<li>77 Luciano Benavides &#8211; Motos<\/li>\n<li>152 Manuel And\u00fajar &#8211; Cuatris<\/li>\n<li>154 Francisco Moreno &#8211; Cuatris<\/li>\n<li>158 Carlos Verza &#8211; Cuatris<\/li>\n<li>163 Pablo Copetti &#8211; Cuatris<\/li>\n<li>169 Alejandro Fantoni &#8211; Cuatris<\/li>\n<li>208 Orlando Terranova &#8211; Autos<\/li>\n<li>212 Sebasti\u00e1n Halpern &#8211; Autos<\/li>\n<li>220 &#8211; Juan Cruz Yacopini &#8211; Autos<\/li>\n<li>308 &#8211; Fernando \u00c1lvarez Castellano &#8211; Autos (UVT)<\/li>\n<li>328 &#8211; Augusto Sanz (N) &#8211; Autos (UVT)<\/li>\n<li>329 &#8211; David Zille &#8211; Autos (UVT)<\/li>\n<li>329 Sebasti\u00e1n Cesana (N) &#8211; Autos (UVT)<\/li>\n<li>335 Bruno Jacomy (N) &#8211; Autos (UVT)<\/li>\n<li>336 Eugenio Arrieta (N) &#8211; Autos (UVT)<\/li>\n<li>348 &#8211; Ariel Jat\u00f3n (N) &#8211; Autos (UVT)<\/li>\n<li>350 Rub\u00e9n Garc\u00eda (N) &#8211; Autos (UVT)<\/li>\n<li>411 Nicol\u00e1s Cavigliasso &#8211; Autos (UVT)<\/li>\n<li>411 Valentina Pertegarini (N) &#8211; Autos (UVT)<\/li>\n<li>412 Jerem\u00edas Gonz\u00e1lez Ferioli &#8211; Autos (UVT)<\/li>\n<li>412 Gonzalo Rinaldi (N) &#8211; Autos (UVT)<\/li>\n<li>350 Rub\u00e9n Garc\u00eda (N) &#8211; Autos (UVT)<\/li>\n<li>411 Nicol\u00e1s Cavigliasso &#8211; Autos (UVT)<\/li>\n<li>411 Valentina Pertegarini (N) &#8211; Autos (UVT)<\/li>\n<li>412 Jerem\u00edas Gonz\u00e1lez Ferioli &#8211; Autos (UVT)<\/li>\n<li>412 Gonzalo Rinaldi (N) &#8211; Autos (UVT)<\/li>\n<\/ul>\n<\/div>\n<div class=\"custom-text \" readability=\"34\">\n<p>En la categor\u00eda autos existen dos divisiones de veh\u00edculos livianos. Del N\u00b0 300 al 400 son Proto ligeros y desde el 400, son SSV. La (N) corresponde a navegante; el resto son pilotos.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A dos d\u00edas del comienzo del Rally Dakar 2023, el cual iniciar\u00e1 el s\u00e1bado en Yanbu, Arabia Saudita, se dio la primera baja de un piloto argentino, el cual temi\u00f3 por su salud y debi\u00f3 ser internado en el pa\u00eds \u00e1rabe. Ya desde el comienzo de su viaje, el cordob\u00e9s de 55 a\u00f1os, Julio C\u00e9sar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27818,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/27817"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=27817"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/27817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/27818"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=27817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=27817"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=27817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}