{"id":3002,"date":"2021-04-09T12:11:59","date_gmt":"2021-04-09T12:11:59","guid":{"rendered":"https:\/\/puntoapunto.com.ar\/?p=275882"},"modified":"2021-04-09T12:11:59","modified_gmt":"2021-04-09T12:11:59","slug":"indec-la-actividad-industrial-crecio-16-interanual-en-febrero","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/04\/09\/indec-la-actividad-industrial-crecio-16-interanual-en-febrero\/","title":{"rendered":"Indec: la actividad industrial creci\u00f3 1,6% interanual en febrero"},"content":{"rendered":"<p><!-- image --><\/p>\n<div class=\"td-post-featured-image\"><a href=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/04\/indec-la-actividad-industrial-crecio-16-interanual-en-febrero.jpg\" data-caption><img loading=\"lazy\" width=\"696\" height=\"392\" class=\"entry-thumb td-modal-image\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/04\/indec-la-actividad-industrial-crecio-16-interanual-en-febrero.jpg\" srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/04\/indec-la-actividad-industrial-crecio-16-interanual-en-febrero.jpg 1004w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/04\/indec-la-actividad-industrial-crecio-16-interanual-en-febrero-1.jpg 300w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/04\/indec-la-actividad-industrial-crecio-16-interanual-en-febrero-2.jpg 768w\" sizes=\"(max-width: 696px) 100vw, 696px\" alt title=\"industria\"><\/a><\/div>\n<p> <!-- content --><\/p>\n<div class=\"td-a-rec td-a-rec-id-content_top tdi_66_03c td_block_template_10\">\n<div class=\"g g-34\">\n<div class=\"g-single a-299\"><a class=\"gofollow\" data-track=\"Mjk5LDM0LDEsNjA=\" href=\"http:\/\/www.grupocanter.com.ar\/landing\/blanqueo\/pap\/?utm_source=Punto%20a%20Punto&amp;utm_medium=Banners&amp;utm_campaign=Blanqueo&amp;utm_term=950x187\"><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/04\/indec-la-actividad-industrial-crecio-16-interanual-en-febrero.gif\"><\/a><\/div>\n<\/div>\n<\/div>\n<p>El nivel de actividad industrial registr\u00f3 en febrero un<strong> incremento del 1,6% interanual<\/strong>, mientras <strong>la construcci\u00f3n subi\u00f3 el 22,7%<\/strong> en igual per\u00edodo, inform\u00f3 esta tarde el Instituto Nacional de Estad\u00edstica y Censos (Indec).<\/p>\n<p>En el caso de la construcci\u00f3n, la mejora de febrero es la cuarta consecutiva tras veintis\u00e9is meses en baja y la tercera consecutiva por encima del 20% interanual, en tanto que el \u00cdndice de Producci\u00f3n Industrial Manufacturero marc\u00f3 el cuarto aumento corrido.<\/p>\n<p>M\u00e1s all\u00e1 de la mejora registrada en el cotejo interanual, el informe del Indec dio <a href=\"https:\/\/puntoapunto.com.ar\/tag\/cuenta\/\" class=\"st_tag internal_tag\" rel=\"tag\" title=\"Posts tagged with cuenta\">cuenta<\/a> de que el nivel de actividad industrial result\u00f3 en febrero 1,6% inferior a la de enero pasado.<\/p>\n<p>En el caso de la construcci\u00f3n, el cotejo intermensual reflej\u00f3 una reducci\u00f3n de 3,9% frente al primer mes de 2021.<\/p>\n<p>En febrero crecieron en t\u00e9rminos interanuales los despachos de 11 de los 13 insumos relevados. Lideraron el crecimiento los despachos de Asfalto (67,1% interanual), Art\u00edculos sanitarios de cer\u00e1mica (60,1% interanual) y Hierro redondo y aceros para la construcci\u00f3n (56,4% interanual).<\/p>\n<p>Por el contrario, cayeron los despachos de Yeso (-0,2% interanual) y Resto (-9,6% interanual; comprende tubos sin costura, vidrio y grifer\u00eda).<\/p>\n<p>Casi a la par de la difusi\u00f3n por parte del Indec, el ministro de Desarrollo Productivo,&nbsp;<strong>Mat\u00edas Kulfas<\/strong>, -a trav\u00e9s de su cuenta en la red social Twitter- adelant\u00f3 que \u201c<strong>los primeros datos industriales de marzo son alentadores\u201d<\/strong>, tras conocerse los indicadores de la actividad de la construcci\u00f3n y la producci\u00f3n industrial de febrero, que mostraron una mejora interanual del 22,7% y 1,6%, respectivamente.<\/p>\n<p>De esta manera, el primer bimestre del a\u00f1o mostr\u00f3 una suba del 2,9% para el sector fabril y del 23 % para la construcci\u00f3n.<\/p>\n<p>En el sector manufacturero crecieron de forma interanual ocho de los 16 rubros relevados. Se destacaron las mejoras registradas en los rubros<strong>&nbsp;Otros equipos, aparatos e instrumentos, con un incremento de 18,5% interanual; seguido por <a href=\"https:\/\/puntoapunto.com.ar\/tag\/industrias\/\" class=\"st_tag internal_tag\" rel=\"tag\" title=\"Posts tagged with Industrias\">industrias<\/a> Met\u00e1licas b\u00e1sicas (16,4%); Maquinaria y Equipo (15,4%), y Minerales no met\u00e1licos (14,4%).<\/strong><\/p>\n<p>Por el contrario, las mayores ca\u00eddas en el nivel de producci\u00f3n se dieron en equipos de transporte, con una merma de 23,2% interanual; Refinaci\u00f3n de petr\u00f3leo, con una baja de 10,4%; Prendas de vestir, -6,7%; Veh\u00edculos automotores, -6,4%; y Qu\u00edmicos, -3,6%.<\/p>\n<p>En lo que respecta a los resultados del Indicador Sint\u00e9tico de la Actividad de la Construcci\u00f3n (ISAC), el Indec precis\u00f3 que&nbsp;<strong>el 30,8% de las empresas dedicadas a la actividad privada y el 40,8% de las dedicadas a la <a href=\"https:\/\/puntoapunto.com.ar\/tag\/obra\/\" class=\"st_tag internal_tag\" rel=\"tag\" title=\"Posts tagged with Obra\">obra<\/a> p\u00fablica proyectaron mejoras para el trimestre marzo-mayo.<\/strong><\/p>\n<p>No tags for this post. <!-- A generated by theme --> <!-- end A --> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El nivel de actividad industrial registr\u00f3 en febrero un incremento del 1,6% interanual, mientras la construcci\u00f3n subi\u00f3 el 22,7% en igual per\u00edodo, inform\u00f3 esta tarde el Instituto Nacional de Estad\u00edstica y Censos (Indec). En el caso de la construcci\u00f3n, la mejora de febrero es la cuarta consecutiva tras veintis\u00e9is meses en baja y la tercera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3003,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/3002"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=3002"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/3002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/3003"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=3002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=3002"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=3002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}