{"id":3357,"date":"2021-04-16T22:46:24","date_gmt":"2021-04-16T22:46:24","guid":{"rendered":"http:\/\/cordobanewsnet.wordpress.com\/?p=5326"},"modified":"2021-04-16T22:46:24","modified_gmt":"2021-04-16T22:46:24","slug":"denunciaron-a-macri-por-llamar-a-desobedecer-las-restricciones","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/04\/16\/denunciaron-a-macri-por-llamar-a-desobedecer-las-restricciones\/","title":{"rendered":"Denunciaron a Macri por llamar a desobedecer las restricciones"},"content":{"rendered":"<div><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/04\/denunciaron-a-macri-por-llamar-a-desobedecer-las-restricciones.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>La denuncia es por una publicaci\u00f3n en la red social&nbsp;<em>Twitter<\/em>, en la que exhort\u00f3 a los intendentes bonaerenses a asumir su \u201cliderazgo\u201d y resistir el DNU que suspendi\u00f3 por dos semanas las clases presenciales ante el crecimiento exponencial de los contagios de Covid-19.<\/p>\n<p>El fiscal Javier Ignacio Ba\u00f1os, a cargo de la Unidad Funcional de Juicio y Flagrancia n\u00famero uno del Departamento Judicial de Mor\u00f3n, consider\u00f3 que Macri \u201chabr\u00eda cometido conductas que presumiblemente encuadran en las figuras de violaci\u00f3n de medidas para impedir la propagaci\u00f3n de una epidemia\u201d, puesto que virtualmente llam\u00f3 a desobedecer el DNU firmado por Alberto Fern\u00e1ndez para suspender la presencialidad durante dos semanas y reemplazarlas por clases mediante videoconferencias por la plataforma&nbsp;<em>Zoom<\/em>.<\/p>\n<p>Mir\u00e1 tambi\u00e9n<\/p>\n<p>Segunda ola de coronavirus<\/p>\n<p>\u201cSolicito que se investigue la posible comisi\u00f3n de los injustos que se produzcan como consecuencia de los irresponsables actos realizados por el ex presidente de la Naci\u00f3n, en cualquiera de sus formas de participaci\u00f3n criminal (coautor\u00eda, complicidad, instigaci\u00f3n) o como encubrimiento de los hechos que aqu\u00ed se detallan\u201d, subray\u00f3 el fiscal, en un escrito presentado ante la fiscal general interina Karina Iuzzolino.<\/p>\n<p>La denuncia consign\u00f3 que Macri difundi\u00f3 a trav\u00e9s de su cuenta en&nbsp;<em>Twitter&nbsp;<\/em>en la v\u00edspera un mensaje en el que dec\u00eda: \u201cLos intendentes de PBA tienen la oportunidad de imponer su liderazgo para que las pocas escuelas que est\u00e1n abiertas contin\u00faen as\u00ed. Es fundamental preservar el v\u00ednculo entre los alumnos y la escuela y no apoyar fallidas decisiones improvisadas, basadas en la intuici\u00f3n o el miedo\u201d.<a href=\"https:\/\/platform.twitter.com\/embed\/Tweet.html?dnt=false&amp;embedId=twitter-widget-0&amp;features=eyJ0ZndfZXhwZXJpbWVudHNfY29va2llX2V4cGlyYXRpb24iOnsiYnVja2V0IjoxMjA5NjAwLCJ2ZXJzaW9uIjpudWxsfSwidGZ3X2hvcml6b25fdHdlZXRfZW1iZWRfOTU1NSI6eyJidWNrZXQiOiJodGUiLCJ2ZXJzaW9uIjpudWxsfX0%3D&amp;frame=false&amp;hideCard=false&amp;hideThread=false&amp;id=1382786290974916608&amp;lang=en&amp;origin=https%3A%2F%2Fwww.cadena3.com%2Fnoticia%2Fpolitica-y-economia%2Fdenunciaron-a-macri-por-llamar-a-no-acatar-las-restricciones_289298&amp;sessionId=a664b1dcdaa5b38c61407cb3b2785d4118b44ae7&amp;siteScreenName=Cadena3Com&amp;theme=light&amp;widgetsVersion=ff2e7cf%3A1618526400629&amp;width=550px\" rel=\"nofollow\">https:\/\/platform.twitter.com\/embed\/Tweet.html?dnt=false&amp;embedId=twitter-widget-0&amp;features=eyJ0ZndfZXhwZXJpbWVudHNfY29va2llX2V4cGlyYXRpb24iOnsiYnVja2V0IjoxMjA5NjAwLCJ2ZXJzaW9uIjpudWxsfSwidGZ3X2hvcml6b25fdHdlZXRfZW1iZWRfOTU1NSI6eyJidWNrZXQiOiJodGUiLCJ2ZXJzaW9uIjpudWxsfX0%3D&amp;frame=false&amp;hideCard=false&amp;hideThread=false&amp;id=1382786290974916608&amp;lang=en&amp;origin=https%3A%2F%2Fwww.cadena3.com%2Fnoticia%2Fpolitica-y-economia%2Fdenunciaron-a-macri-por-llamar-a-no-acatar-las-restricciones_289298&amp;sessionId=a664b1dcdaa5b38c61407cb3b2785d4118b44ae7&amp;siteScreenName=Cadena3Com&amp;theme=light&amp;widgetsVersion=ff2e7cf%3A1618526400629&amp;width=550px<\/a><\/p>\n<p>\u201cAs\u00ed, sucintamente, el ex Presidente de la Naci\u00f3n Argentina realiza a trav\u00e9s de la mentada red social un llamado p\u00fablico a los gobernantes municipales a que desobedezcan las decisiones adoptadas por el gobernador de la provincia de Buenos Aires\u201d, resumi\u00f3 el fiscal denunciante.<\/p>\n<p>\u201cEl derecho a la libre expresi\u00f3n no es absoluto en cuanto a las responsabilidades que el legislador puede determinar a ra\u00edz de los abusos producidos mediante su ejercicio, en particular, como en el caso, cuando los dichos emanan de un anterior primer mandatario y los mismos conllevan una gravedad institucional tal que invita al caos en el gobierno provincial\u201d, agreg\u00f3.<\/p>\n<p>Las figuras delictivas que se le imputan a Macri contemplan penas que llegan hasta los seis a\u00f1os de c\u00e1rcel.<\/p>\n<p>Fuente. Cadena3<\/p>\n<div id=\"jp-post-flair\" class=\"sharedaddy sd-like-enabled sd-sharing-enabled\">\n<div class=\"sharedaddy sd-sharing-enabled\">\n<div class=\"robots-nocontent sd-block sd-social sd-social-icon-text sd-sharing\">\n<h3 class=\"sd-title\">Share this:<\/h3>\n<\/div>\n<\/div>\n<div class=\"sharedaddy sd-block sd-like jetpack-likes-widget-wrapper jetpack-likes-widget-unloaded\" id=\"like-post-wrapper-143108178-5326-607ae4683cfa1\" data-src=\"\/\/widgets.wp.com\/likes\/index.html?ver=20210413#blog_id=143108178&amp;post_id=5326&amp;origin=cordobanewsnet.wordpress.com&amp;obj_id=143108178-5326-607ae4683cfa1\" data-name=\"like-post-frame-143108178-5326-607ae4683cfa1\">\n<h3 class=\"sd-title\">Me gusta esto:<\/h3>\n<p><span class=\"button\"><span>Me gusta<\/span><\/span> <span class=\"loading\">Cargando&#8230;<\/span><\/p>\n<p><span class=\"sd-text-color\"><\/span><\/div>\n<p><h3 class=\"jp-relatedposts-headline\"><em>Relacionado<\/em><\/h3>\n<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La denuncia es por una publicaci\u00f3n en la red social&nbsp;Twitter, en la que exhort\u00f3 a los intendentes bonaerenses a asumir su \u201cliderazgo\u201d y resistir el DNU que suspendi\u00f3 por dos semanas las clases presenciales ante el crecimiento exponencial de los contagios de Covid-19. El fiscal Javier Ignacio Ba\u00f1os, a cargo de la Unidad Funcional de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3358,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/3357"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=3357"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/3357\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/3358"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=3357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=3357"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=3357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}