{"id":34073,"date":"2023-07-06T09:36:04","date_gmt":"2023-07-06T09:36:04","guid":{"rendered":"https:\/\/www.bbc.com\/mundo\/articles\/cj7rm13eepxo"},"modified":"2023-07-06T09:36:04","modified_gmt":"2023-07-06T09:36:04","slug":"4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2023\/07\/06\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin\/","title":{"rendered":"4 claves para entender qu\u00e9 son las monedas digitales que reemplazan a los billetes de papel (y por qu\u00e9 no tienen nada que ver con el bitcoin)"},"content":{"rendered":"<p><time datetime=\"2023-07-06\" class=\"bbc-1dafq0j e1mklfmt0\">1 hora<\/time><\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>Cecilia Barr\u00eda<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">BBC News Mundo<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-172p16q ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-189y18v ebmt73l0\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\" readability=\"8\"><img loading=\"lazy\" sizes=\"(min-width: 1008px) 760px, 100vw\" srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-5.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-6.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-7.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-8.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-9.jpg 669w\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin.jpg\" alt=\"S\u00edmbolo del euro\" width=\"669\" height=\"377\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv ewbcsnk0\"><span class=\"bbc-m04vo2\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g ebmt73l0\" readability=\"6\"><figcaption dir=\"ltr\" class=\"bbc-rhuvwm e6i104o0\" readability=\"2\"><span class=\"bbc-m04vo2\">Pie de foto, <\/span><\/p>\n<p>La Comisi\u00f3n Europea propuso la creaci\u00f3n de un euro digital.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>Si alguien te habla de monedas digitales, es probable que lo primero que se te venga a la cabeza sean criptomonedas como el bitcoin.<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Sin embargo, hay otras monedas digitales, pr\u00e1cticamente desconocidas, que avanzan silenciosamente en los pasillos de las altas esferas de las finanzas con las que se quiere reemplazar a los billetes de papel y al dinero met\u00e1lico.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Son las monedas digitales emitidas por los bancos centrales (CBDC, por sus siglas en ingl\u00e9s).<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Se trata de la versi\u00f3n digital de las monedas tradicionales que las personas utilizan todos los d\u00edas, como el d\u00f3lar, el euro o el yuan.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">A finales de junio, la Comisi\u00f3n Europea present\u00f3 una propuesta para poner en marcha el euro digital.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Bajo ese esquema, la tradicional moneda de un euro tendr\u00eda un valor exactamente igual al de un euro digital.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Esta nueva divisa ser\u00eda emitida por el Banco Central Europeo (BCE), con <b>un estatus que la hace tan oficial como su equivalente f\u00edsico. <\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">En ese sentido, estas divisas digitales -que ya han sido implementadas en varios pa\u00edses- son la ant\u00edtesis de las criptomonedas.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">\u00bfPor qu\u00e9? porque las criptomonedas no son emitidas por ning\u00fan banco central y su valor cambia constantemente. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">En el mercado de las criptomonedas participan inversionistas que est\u00e1n dispuestos a correr riesgos, ya que los precios pueden dispararse un d\u00eda y caer estrepitosamente al otro. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">B\u00e1sicamente, nadie regula su valor y se mueven libremente a trav\u00e9s de una tecnolog\u00eda que se llama cadena de bloques (o blockchain), mientras que las monedas digitales \u00abp\u00fablicas\u00bb u \u00aboficiales\u00bb, funcionan igual que el dinero tradicional, solo que en un formato electr\u00f3nico.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">\u00abCon el euro digital, los ciudadanos podr\u00e1n pagar en dinero p\u00fablico\u201d, dijo Valdis Dombrovskis, vicepresidente ejecutivo de la Comisi\u00f3n Europea.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>\u00abTener un monedero digital en euros recargado en el tel\u00e9fono -u otro dispositivo- ser\u00e1 lo mismo que tener monedas y billetes en el bolsillo\u201d<\/b>, agreg\u00f3.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">La ley definitiva debe ser respaldada por los 27 Estados miembros de la Uni\u00f3n Europea. Si eso ocurre, se espera que el BCE d\u00e9 luz verde a un euro digital en los pr\u00f3ximos meses para que pueda lanzarse en 2027.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">A continuaci\u00f3n te contamos cuatro claves para entender c\u00f3mo funcionan las monedas digitales y qu\u00e9 ventajas y desventajas tienen.<\/p>\n<\/div>\n<p><h2 id=\"1-C\u00f3mo-funcionan-\" tabindex=\"-1\" class=\"bbc-1f03ibc eglt09e0\">1. C\u00f3mo funcionan <\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Las monedas digitales emitidas por los bancos centrales de cada pa\u00eds<b> son la versi\u00f3n electr\u00f3nica del dinero tradicional.<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">As\u00ed, en vez de imprimir billetes de papel o monedas met\u00e1licas, el banco central de un pa\u00eds emite su propio dinero en formato electr\u00f3nico.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-172p16q ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-189y18v ebmt73l0\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\" readability=\"8\"><noscript><img loading=\"lazy\" sizes=\"(min-width: 1008px) 760px, 100vw\" srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-10.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-11.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-12.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-13.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-14.jpg 656w\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-1.jpg\" alt=\"Im\u00e1genes de CBDC\" width=\"656\" height=\"369\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv ewbcsnk0\"><span class=\"bbc-m04vo2\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g ebmt73l0\" readability=\"6\"><figcaption dir=\"ltr\" class=\"bbc-rhuvwm e6i104o0\" readability=\"2\"><span class=\"bbc-m04vo2\">Pie de foto, <\/span><\/p>\n<p>Son la versi\u00f3n electr\u00f3nica del dinero tradicional.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Una de las diferencias esenciales con el sistema actual es que estas monedas <b>no requieren que un banco sea el intermediario para que se lleve a cabo la transacci\u00f3n. <\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Te\u00f3ricamente, podr\u00edas hacer transferencias electr\u00f3nicas como si le estuvieras pasando unos billetes en la mano a otra persona o a un negocio.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>Se espera que las monedas digitales bajen los costos asociados a las transacciones <\/b><b><i class=\"bbc-h1y5j7 eih42320\">online<\/i><\/b><b> hechas a trav\u00e9s de la banca comercial<\/b> y que favorezcan a las personas de ingresos m\u00e1s bajos y a los sectores de la poblaci\u00f3n que no est\u00e1n bancarizados.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Entre las distintas propuestas para implementar el sistema que est\u00e1 sobre la mesa, algunos expertos han planteado crear cuentas bancarias universales en los bancos centrales para todos los ciudadanos.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Pero lo cierto es que cada pa\u00eds o zona monetaria que decida emitir este tipo de monedas, fijar\u00e1 sus propias reglas.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Esa es la idea b\u00e1sica de una moneda digital oficial, aunque por ahora, hay muchas interrogantes sin responder, en la medida que las grandes econom\u00edas del mundo a\u00fan est\u00e1n analizando sus potenciales beneficios.<\/p>\n<\/div>\n<p><h2 id=\"2-En-qu\u00e9-pa\u00edses-existen\" tabindex=\"-1\" class=\"bbc-1f03ibc eglt09e0\">2. En qu\u00e9 pa\u00edses existen<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>China fue la primera gran econom\u00eda del mundo en lanzar una moneda digital en 2020 en algunas partes de su territorio. <\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Se calcula que el yuan digital es utilizado actualmente por unos 260 millones de personas y el plan del gobierno es hacerlo extensivo a todo el territorio.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Seg\u00fan el centro de estudios Atlantic Council, con sede en Washington DC, un total de 130 pa\u00edses est\u00e1n explorando versiones digitales de sus monedas, con casi la mitad de ellos en etapas m\u00e1s avanzadas de desarrollo, haciendo planes piloto o en proceso de lanzamiento.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-172p16q ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-189y18v ebmt73l0\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\" readability=\"8\"><noscript><img loading=\"lazy\" sizes=\"(min-width: 1008px) 760px, 100vw\" srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-15.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-16.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-17.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-18.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-19.jpg 665w\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-2.jpg\" alt=\"Imagen de bandera y yuanes chinos\" width=\"665\" height=\"374\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv ewbcsnk0\"><span class=\"bbc-m04vo2\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g ebmt73l0\" readability=\"6\"><figcaption dir=\"ltr\" class=\"bbc-rhuvwm e6i104o0\" readability=\"2\"><span class=\"bbc-m04vo2\">Pie de foto, <\/span><\/p>\n<p>China lleva la delantera.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Todos los pa\u00edses del Grupo de los 20 (G20), excepto Argentina, est\u00e1n en alguna de esas fases.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>Once pa\u00edses, incluidos varios en el Caribe y Nigeria, ya han lanzado monedas digitales emitidas por sus bancos centrales, <\/b>seg\u00fan el centro de estudios.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"14\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Bahamas, por ejemplo, un pa\u00eds peque\u00f1o de apenas 390.000 habitantes, se ha convertido en un gran laboratorio al crear el <b>d\u00f3lar de arena<\/b> (<i class=\"bbc-h1y5j7 eih42320\">sand dollar<\/i>, en ingl\u00e9s), la primera moneda digital del mundo emitida por un banco central.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">La iniciativa ha demorado en despegar porque la mayor\u00eda de la poblaci\u00f3n no lo utiliza, una dificultad con la que tambi\u00e9n se han encontrado otros pa\u00edses.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Otras dos grandes econom\u00edas emergentes, como India y Brasil, tienen planes para lanzar monedas digitales en los pr\u00f3ximos a\u00f1os.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">En medio de este panorama, el pa\u00eds con la moneda m\u00e1s fuerte del mundo, <b>Estados Unidos, est\u00e1 lejos de tener planes para crear un d\u00f3lar digital.<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Desde la Casa Blanca, el presidente Joe Biden orden\u00f3 a funcionarios del gobierno que evaluaran los riesgos y beneficios de crear un d\u00f3lar digital en marzo de 2022.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Pero el d\u00f3lar digital no forma parte de los temas que se discuten en la agenda econ\u00f3mica del pa\u00eds.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>Suecia contin\u00faa siendo uno de los pa\u00edses m\u00e1s avanzados de Europa con su programa piloto<\/b>, mientras que el Banco de Inglaterra sigue trabajando en una posible libra digital que podr\u00eda entrar en uso hacia finales de esta d\u00e9cada.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Australia, Tailandia, Corea del Sur y Rusia tienen la intenci\u00f3n de continuar con las pruebas piloto.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">A pesar del creciente inter\u00e9s en las monedas digitales oficiales, algunos pa\u00edses que las han lanzado, como Nigeria, se\u00f1alan que su aceptaci\u00f3n ha sido decepcionante, mientras que Senegal y Ecuador cancelaron sus planes de desarrollo de este tipo de divisas.<\/p>\n<\/div>\n<p><h2 id=\"3-Cu\u00e1les-son-sus-potenciales-ventajas\" tabindex=\"-1\" class=\"bbc-1f03ibc eglt09e0\">3. Cu\u00e1les son sus potenciales ventajas<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Los promotores de las monedas digitales dicen que ayudar\u00e1n a la inclusi\u00f3n financiera de quienes est\u00e1n fuera de la banca comercial y promover\u00e1n la innovaci\u00f3n tecnol\u00f3gica, la eficiencia en las transacciones y el desarrollo econ\u00f3mico.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-37mmq3 ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-189y18v ebmt73l0\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\" readability=\"8\"><noscript><img loading=\"lazy\" sizes=\"(min-width: 1008px) 760px, 100vw\" srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-20.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-21.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-22.jpg 416w\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-3.jpg\" alt=\"signo d\u00f3lar\" width=\"416\" height=\"416\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv ewbcsnk0\"><span class=\"bbc-m04vo2\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g ebmt73l0\" readability=\"6\"><figcaption dir=\"ltr\" class=\"bbc-rhuvwm e6i104o0\" readability=\"2\"><span class=\"bbc-m04vo2\">Pie de foto, <\/span><\/p>\n<p>El d\u00f3lar digital est\u00e1 reci\u00e9n en una etapa temprana de an\u00e1lisis.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">En teor\u00eda, el cambio contribuir\u00eda a una<b> reducci\u00f3n de costos<\/b> porque el sistema no depende de la banca comercial, ya que el medio de pago depende directamente de la banca central.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">De hecho, en el caso del euro digital, se supone que el Banco Central Europeo <b>no tendr\u00eda ning\u00fan inter\u00e9s comercial en almacenar, gestionar o monetizar los datos de los usuarios.<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Quienes apoyan el proyecto presentado por la Comisi\u00f3n Europea, sostienen que un euro digital permitir\u00eda pagar con \u201cuna forma de dinero p\u00fablico ampliamente <b>aceptada, barata y segura<\/b>\u201d.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Adem\u00e1s, se estima que el uso de divisas digitales podr\u00eda disuadir ciertas actividades criminales financieras, en la medida que ser\u00eda m\u00e1s f\u00e1cil determinar qui\u00e9n es el remitente y el receptor de las transferencias.<\/p>\n<\/div>\n<p><h2 id=\"4-Cu\u00e1les-son-sus-riesgos-\" tabindex=\"-1\" class=\"bbc-1f03ibc eglt09e0\">4. Cu\u00e1les son sus riesgos <\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">De crearse un euro digital en los pr\u00f3ximos a\u00f1os, se espera que el Banco Central Europeo no imponga comisiones a los usuarios.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>Pero eso no quiere decir que el uso de la divisa digital resulte completamente gratuito.<\/b> A\u00fan no est\u00e1 claro cu\u00e1l ser\u00e1 la funci\u00f3n y los costos de los posibles intermediarios que ofrecer\u00e1n servicios para que funcione el mercado de la divisa.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"7\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Tampoco se conoce c\u00f3mo ser\u00eda la relaci\u00f3n con la banca comercial.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa ebmt73l0\">\n<figure class=\"bbc-1qdcvv9 e1aczekt0\">\n<div dir=\"ltr\" class=\"bbc-172p16q ebmt73l0\">\n<div dir=\"ltr\" class=\"bbc-189y18v ebmt73l0\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-997y1y eihqrxw0\" readability=\"8\"><noscript><img loading=\"lazy\" sizes=\"(min-width: 1008px) 760px, 100vw\" srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-23.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-24.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-25.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-26.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-27.jpg 706w\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2023\/07\/4-claves-para-entender-que-son-las-monedas-digitales-que-reemplazan-a-los-billetes-de-papel-y-por-que-no-tienen-nada-que-ver-con-el-bitcoin-4.jpg\" alt=\"manos con tel\u00e9fonos\" width=\"706\" height=\"396\" class=\"e3vrtyk0 bbc-rb7xa0 e1mo64ex0\"><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv ewbcsnk0\"><span class=\"bbc-m04vo2\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g ebmt73l0\" readability=\"6\"><figcaption dir=\"ltr\" class=\"bbc-rhuvwm e6i104o0\" readability=\"2\"><span class=\"bbc-m04vo2\">Pie de foto, <\/span><\/p>\n<p>No est\u00e1 claro a\u00fan cu\u00e1l ser\u00eda el rol de la banca tradicional.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Adem\u00e1s, las voces cr\u00edticas desconf\u00edan de que los bancos centrales tengan la informaci\u00f3n detallada de todas las transacciones que hacen los usuarios en pa\u00edses donde no existe suficiente transparencia y<b> la informaci\u00f3n podr\u00eda ser utilizada con fines pol\u00edticos.<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">A la banca comercial le preocupa que eventualmente un gran n\u00famero de depositantes abandone el sistema bancario, un factor que podr\u00eda poner en riesgo una parte importante de su negocio y, en un caso extremo, provocar posibles corridas bancarias.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Sin embargo, los expertos han dicho que esa potencial fuga de dinero desde la banca comercial se puede controlar f\u00e1cilmente estableciendo l\u00edmites a la cantidad de divisas digitales que puede poseer un determinado cliente.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Otra de las cr\u00edticas que se han hecho al sistema, es que como todas las operaciones estar\u00edan centralizadas, existe el riesgo de que un determinado banco central tome decisiones arbitrarias dado que puede crear o eliminar dinero en un abrir y cerrar de ojos.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Desde otro punto de vista, tambi\u00e9n existe el riesgo de que una moneda digital extranjera bien gestionada pueda convertirse<b> en un sustituto de una determinada moneda local. <\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Finalmente, dicen los expertos, todo depender\u00e1 de c\u00f3mo se implemente el sistema de monedas digitales que emiten los bancos centrales de acuerdo al modelo que cada pa\u00eds defina.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><i class=\"bbc-h1y5j7 eih42320\">Ahora puedes recibir notificaciones de BBC Mundo. Descarga la nueva versi\u00f3n de nuestra app y act\u00edvalas para no perderte nuestro mejor contenido.<\/i><\/p>\n<\/div>\n<section dir=\"ltr\" role=\"region\" aria-label=\"Contenido relacionado\" class=\"bbc-1n4f7vm ebmt73l0\"><\/section>\n<section dir=\"ltr\" role=\"region\" aria-label=\"Contenido relacionado\" class=\"bbc-1n4f7vm ebmt73l0\"><\/section>\n<section dir=\"ltr\" role=\"region\" aria-label=\"Contenido relacionado\" class=\"bbc-1n4f7vm ebmt73l0\"><\/section>\n","protected":false},"excerpt":{"rendered":"<p>1 hora Cecilia Barr\u00eda BBC News Mundo Fuente de la imagen, Getty Images Pie de foto, La Comisi\u00f3n Europea propuso la creaci\u00f3n de un euro digital. Si alguien te habla de monedas digitales, es probable que lo primero que se te venga a la cabeza sean criptomonedas como el bitcoin. Sin embargo, hay otras monedas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34074,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/34073"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=34073"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/34073\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/34074"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=34073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=34073"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=34073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}