{"id":4612,"date":"2021-05-17T23:49:19","date_gmt":"2021-05-17T23:49:19","guid":{"rendered":"http:\/\/www.bbc.com\/mundo\/noticias-america-latina-57140964"},"modified":"2021-05-17T23:49:19","modified_gmt":"2021-05-17T23:49:19","slug":"elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/05\/17\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados\/","title":{"rendered":"Elecciones en Chile | \u00abSer\u00e1 un pa\u00eds distinto\u00bb: 5 claves para entender los in\u00e9ditos resultados"},"content":{"rendered":"<div dir=\"ltr\" class=\"e1j2237y6 bbc-q4ibpr e57qer20\">\n<div class=\"bbc-1atl7vu e1c9i7u14\">\n<ul role=\"list\" class=\"bbc-cdrraw e1c9i7u12\">\n<li role=\"listitem\" class=\"bbc-1a3w4ok e1c9i7u11\">Redacci\u00f3n <\/li>\n<li role=\"listitem\" class=\"bbc-1p92jtu e1c9i7u10\">BBC News Mundo<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p><time datetime=\"2021-05-17\" class=\"bbc-14xtggo e4zesg50\">7 horas<\/time><\/p>\n<div dir=\"ltr\" class=\"bbc-1ka88fa e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-172p16q e57qer20\">\n<div dir=\"ltr\" class=\"bbc-189y18v e57qer20\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-1k5hvrj e1whu0\" readability=\"8\"><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-9.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-10.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-11.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-12.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-13.jpg 800w\" alt=\"Mujer vota en Chile\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados.jpg\" width=\"976\" class=\"bbc-fat2bc e1enwo3v0\"><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv etq3yw90\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g e57qer20\" readability=\"7.5\"><figcaption dir=\"ltr\" class=\"bbc-1t9zlwf eede9f50\" readability=\"5\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Pie de foto, <\/span><\/p>\n<p>Este fin de semana los chilenos eligieron a los integrantes de la Convenci\u00f3n Constituyente, y a gobernadores, alcaldes y concejales.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\"><b>\u00abChile cambi\u00f3\u00bb.<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">La frase se repiti\u00f3 una y otra vez entre expertos y l\u00edderes pol\u00edticos mientras aparec\u00edan los resultados de las megaelecciones de este fin de semana en el pa\u00eds liderado por <b>Sebasti\u00e1n Pi\u00f1era.<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Los candidatos electos para la <b>Convenci\u00f3n Constituyente<\/b> \u2014que tendr\u00e1 la misi\u00f3n de redactar la nueva Carta Magna\u2014, y para los cargos de gobernadores, alcaldes y concejales, dan cuenta de un cambio importante en la postura ideol\u00f3gica de la sociedad chilena. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Postulantes independientes y ajenos a los partidos pol\u00edticos tradicionales fueron unos de los grandes triunfadores de la Convenci\u00f3n. Contrario a lo que se esperaba, la <b>derecha<\/b> no logr\u00f3 ni de cerca obtener los <b>52 esca\u00f1os <\/b>(o un tercio de la asamblea) que se necesita para influir en el contenido de nueva Carta Fundamental y vetar art\u00edculos. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"15\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Mientras que la centroizquierda, unida en la lista Apruebo \u2014que aglutina a buena parte de la <b>ex Concertaci\u00f3n<\/b>, que gobern\u00f3 Chile entre 1990 y 2010\u2014 ,obtuvo apenas 25 esca\u00f1os, por debajo del resultado de la lista de izquierda Apruebo Dignidad, que re\u00fane al <b>Partido Comunista y el Frente Amplio<\/b>.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"ek1plzs1 bbc-9m7iam e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-vx18wi e57qer20\">\n<div dir=\"ltr\" class=\"bbc-rprdln e57qer20\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-9damr9 e1whu0\"><noscript><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados.png 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados.png 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados.png 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados.png 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados.png 800w\" alt=\"conformaci\u00f3n pol\u00edtica convenci\u00f3n\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados.png\" width=\"900\" class=\"bbc-fat2bc e1enwo3v0\"><\/noscript><\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Los resultados han sido le\u00eddos por analistas como un <b>\u00abcastigo\u00bb <\/b>a las fuerzas pol\u00edticas tradicionales, y ya han aparecido los primeros <i class=\"bbc-h1y5j7 ewc4zcb0\">mea culpa<\/i> de varios de sus expositores. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"15\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\"><b>\u00abLa frase simb\u00f3lica que se instal\u00f3 en las protestas de 2019, de que no eran 30 pesos sino que 30 a\u00f1os de injusticias, se hace realidad luego de estas elecciones.<\/b> Chile cambi\u00f3 y probablemente ser\u00e1 un pa\u00eds distinto despu\u00e9s de este fin de semana\u00bb, dice a BBC Mundo <b>Roberto Isikson,<\/b> director de Cadem, una empresa de estudios de mercado y opini\u00f3n p\u00fablica chilena. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">A continuaci\u00f3n, te presentamos 5 claves para entender los resultados de esta in\u00e9dita elecci\u00f3n en Chile. <\/p>\n<\/div>\n<p><h2 id=\"1-Sorpresa-de-los-independientes\" tabindex=\"-1\" class=\"bbc-l3e97o e14hemmw0\">1. Sorpresa de los independientes<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Ninguna proyecci\u00f3n o encuesta chilena adelant\u00f3 la importancia que tendr\u00edan los independientes en la elecci\u00f3n de la Convenci\u00f3n Constituyente. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Todo lo contrario: analistas advert\u00edan de que el sistema electoral chileno beneficiar\u00eda a los candidatos afiliados a los partidos pol\u00edticos y, por tanto, podr\u00eda darse una suerte de \u00abdecepci\u00f3n\u00bb entre la gente que pidi\u00f3 una Constituci\u00f3n \u00abescrita por el pueblo\u00bb en caso de que no obtuvieran los resultados deseados. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Sin embargo, rostros nuevos y debutantes en el mundo de la pol\u00edtica se convirtieron en la primera fuerza de la asamblea, al obtener<b> 48 de los 155 esca\u00f1os. <\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"14\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Entre los independientes, llama la atenci\u00f3n el amplio apoyo a la <b>\u00abLista del Pueblo\u00bb,<\/b> que obtuvo 24 esca\u00f1os, y que se organiz\u00f3 a partir de las protestas en Plaza Italia, en el centro de Santiago, en el marco del estallido social. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abSomos quienes hemos vivido y crecido en la inequidad y la desigualdad, somos quienes nos levantamos un 18 de Octubre (de 2019) para decir basta\u00bb, dice en su declaraci\u00f3n de principios. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"ek1plzs1 bbc-9m7iam e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-vx18wi e57qer20\">\n<div dir=\"ltr\" class=\"bbc-rprdln e57qer20\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-i2qzc0 e1whu0\"><noscript><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-2.png 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-3.png 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-4.png 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-5.png 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-6.png 800w\" alt=\"L\u00ednea de tiempo del proceso constituyente en Chile\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-1.png\" width=\"900\" class=\"bbc-fat2bc e1enwo3v0\"><\/noscript><\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">La reconfiguraci\u00f3n del mapa pol\u00edtico se explica en gran parte por el fuerte estallido social que irrumpi\u00f3 en Chile en octubre de 2019, cuando la gente sali\u00f3 a las calles a protestar contra el sistema pol\u00edtico y econ\u00f3mico. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">En paralelo, el rechazo a las fuerzas tradicionales fue aumentando cada vez m\u00e1s y una primera se\u00f1al de aquello fue lo que sucedi\u00f3 en octubre del 2020 cuando casi el <b>80% de los votantes<\/b> decidi\u00f3 cambiar la Carta Magna a trav\u00e9s de una convenci\u00f3n que no incluir\u00eda a miembros del parlamento ni del gobierno. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abSe esperaba que los independientes iban a llegar al tercio pero esto supera con creces ese resultado. Y creo que de alguna manera es un reflejo de que la \u00e9lite, los medios de comunicaci\u00f3n, el sistema pol\u00edtico y las empresas no fuimos capaces de ver lo que estaba pasando\u00bb, dice Isikson.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abEs un rechazo al sistema pol\u00edtico actual, a toda la \u00e9lite tradicional\u00bb, agrega.<\/p>\n<\/div>\n<p><h2 id=\"2-Derrota-de-la-derecha-y-castigo-al-gobierno-de-Pi\u00f1era\" tabindex=\"-1\" class=\"bbc-l3e97o e14hemmw0\">2. Derrota de la derecha (y castigo al gobierno de Pi\u00f1era)<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Si hab\u00eda algo de lo que hab\u00eda que estar atento apenas comenzaran a aparecer los primeros resultados de las elecciones en Chile, era si la derecha \u2014que fue en una lista \u00fanica llamada \u00abVamos por Chile\u00bb\u2014 lograba obtener al menos <b>52 esca\u00f1os<\/b> (o un tercio) de la Convenci\u00f3n Constituyente.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Esto le abrir\u00eda las puertas para influir y negociar sobre las decisiones que se tomar\u00e1n respecto a las nuevas normas pues, para que sean aprobadas, deben contar con el apoyo de dos tercios de sus miembros.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Sin embargo, no lo logr\u00f3. Y, en cambio, obtuvo apenas 37 de los esca\u00f1os. Este es un duro golpe no solo para los l\u00edderes de este sector pol\u00edtico, sino tambi\u00e9n para el gobierno de <b>Sebasti\u00e1n Pi\u00f1era. <\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-172p16q e57qer20\">\n<div dir=\"ltr\" class=\"bbc-189y18v e57qer20\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-1k5hvrj e1whu0\" readability=\"8\"><noscript><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-14.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-15.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-16.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-17.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-18.jpg 800w\" alt=\"El presidente de Chile, Sebasti\u00e1n Pi\u00f1era.\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-1.jpg\" width=\"976\" class=\"bbc-fat2bc e1enwo3v0\"><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv etq3yw90\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g e57qer20\" readability=\"8\"><figcaption dir=\"ltr\" class=\"bbc-1t9zlwf eede9f50\" readability=\"6\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Pie de foto, <\/span><\/p>\n<p>\u00abLa ciudadan\u00eda nos ha enviado un claro y fuerte mensaje al Gobierno y tambi\u00e9n a todas las fuerzas pol\u00edticas tradicionales, no estamos sintonizando adecuadamente con la demandas y con los anhelos de la ciudadan\u00eda\u00bb, dijo Sebasti\u00e1n Pi\u00f1era.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abLa ciudadan\u00eda nos ha enviado un claro y fuerte mensaje al gobierno y tambi\u00e9n a todas las fuerzas pol\u00edticas tradicionales: <b>no estamos sintonizando adecuadamente con la demandas y con los anhelos de la ciudadan\u00eda<\/b> y estamos siendo interpelados por nuevas expresiones y por nuevos liderazgos\u00bb, dijo el mandatario luego de que los resultados se hicieran p\u00fablicos. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Por su parte, uno de los candidatos presidenciales de la derecha, <b>Mario Desbordes,<\/b> se\u00f1al\u00f3: \u00abNo hay duda que estamos viviendo una derrota transversalmente, una derrota que nos tiene que hacer reflexionar. No hemos sido capaces de interpretar a la mayor\u00eda ciudadana que est\u00e1 pidiendo cambios\u00bb.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">En la misma l\u00ednea,<b> Joaqu\u00edn Lav\u00edn, <\/b>tambi\u00e9n postulante presidencial de la derecha, indic\u00f3 que \u00abhay que tener claro que estamos ante un nuevo Chile y la Convenci\u00f3n que se est\u00e1 eligiendo es un mosaico de este Chile nuevo\u00bb.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">La posici\u00f3n de la derecha chilena es a\u00fan m\u00e1s compleja si se considera que la derrota tambi\u00e9n se traslad\u00f3 a las <b>elecciones de gobernadores, alcaldes y concejales. <\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"17\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Entre las p\u00e9rdidas m\u00e1s importantes, est\u00e1 la gobernaci\u00f3n de la regi\u00f3n Metropolitana, donde su candidata (Catalina Parot) no pas\u00f3 ni siquiera a segunda vuelta. Adem\u00e1s, el actual alcalde de Santiago, uno de los municipios m\u00e1s importantes del pa\u00eds, <b>Felipe Alessandri<\/b>, fue superado por la carta del Partido Comunista, <b>Irac\u00ed Hassler. <\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Tambi\u00e9n perdieron otras alcald\u00edas clave como Maip\u00fa, Vi\u00f1a del Mar, \u00d1u\u00f1oa y Estaci\u00f3n Central. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-172p16q e57qer20\">\n<div dir=\"ltr\" class=\"bbc-189y18v e57qer20\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-1k5hvrj e1whu0\" readability=\"8\"><noscript><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-19.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-20.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-21.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-22.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-23.jpg 800w\" alt=\"Joaqu\u00edn Lav\u00edn\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-2.jpg\" width=\"976\" class=\"bbc-fat2bc e1enwo3v0\"><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv etq3yw90\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g e57qer20\" readability=\"8\"><figcaption dir=\"ltr\" class=\"bbc-1t9zlwf eede9f50\" readability=\"6\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Pie de foto, <\/span><\/p>\n<p>\u00abHay que tener claro que estamos ante un nuevo Chile y la Convenci\u00f3n que se est\u00e1 eligiendo es un mosaico de este Chile nuevo\u00bb, dijo uno de los candidatos presidenciales de la derecha, Joaqu\u00edn Lav\u00edn.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\"><b>\u00abEs el peor resultado de la derecha en mucho tiempo\u00bb<\/b>, afirma Roberto Isikson.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abY el gobierno sin duda tiene mucha responsabilidad. Hay una alta correlaci\u00f3n entre la aprobaci\u00f3n presidencial, que se encuentra en un lugar muy bajo, y los resultados electorales\u00bb, agrega. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"14\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">De acuerdo con la \u00faltima encuesta del Centro de Estudios P\u00fablicos (CEP), publicada a fines de abril, el presidente Pi\u00f1era cuenta solo con un 9% de aprobaci\u00f3n entre los chilenos, el nivel m\u00e1s bajo durante su segundo mandato. La desaprobaci\u00f3n, en tanto, alcanza el 74%.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"14\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Isikson, experto en encuestas, explica que los factores determinantes en el rechazo a la administraci\u00f3n de Pi\u00f1era tienen que ver con c\u00f3mo manej\u00f3 el estallido social, su oposici\u00f3n al retiro de las pensiones (una iniciativa altamente popular) y la percepci\u00f3n de que el gobierno nunca lleg\u00f3 con la ayuda necesaria para enfrentar la pandemia de coronavirus, entre otras cosas. <\/p>\n<\/div>\n<p><h2 id=\"3-Decepci\u00f3n-de-la-ex-Concertaci\u00f3n-y-triunfo-de-la-izquierda-\" tabindex=\"-1\" class=\"bbc-l3e97o e14hemmw0\">3. Decepci\u00f3n de la ex Concertaci\u00f3n y triunfo de la izquierda <\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">La centroizquierda de Chile, que gobern\u00f3 el pa\u00eds entre 1990 y 2010 bajo el bloque denominado <b>Concertaci\u00f3n<\/b>, ten\u00eda un reto importante en estas elecciones pues medir\u00eda su fuerza con la del eje de izquierda conformado por el <b>Partido Comunista (PC) y el Frente Amplio (FA)<\/b>, una coalici\u00f3n que irrumpi\u00f3 hace un par de a\u00f1os y que ha venido a desafiar el poder de las fuerzas pol\u00edticas tradicionales.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">As\u00ed, el resultado que obtuvieran tanto en la Convenci\u00f3n Constituyente como en el resto de los cargos regionales generaba una fuerte expectativa en el sector. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Pero esta vez la preferencia de los chilenos de izquierdas no estuvo de su lado: no solo obtuvieron menos esca\u00f1os en la Convenci\u00f3n Constituyente que la lista Apruebo Dignidad (que suma al PC y el FA), sino que tambi\u00e9n fueron superados en importantes gobernaciones y municipios. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Al contrario, candidatos del Frente Amplio sorprendieron al triunfar en lugares como la Regi\u00f3n Metropolitana, o municipios como Valpara\u00edso y Vi\u00f1a del Mar, fortaleciendo la idea de que la izquierda m\u00e1s radical gana terreno por sobre el centro. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-172p16q e57qer20\">\n<div dir=\"ltr\" class=\"bbc-189y18v e57qer20\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-1k5hvrj e1whu0\" readability=\"8\"><noscript><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-24.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-25.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-26.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-27.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-28.jpg 800w\" alt=\"Protestas chile\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-3.jpg\" width=\"976\" class=\"bbc-fat2bc e1enwo3v0\"><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv etq3yw90\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g e57qer20\" readability=\"7\"><figcaption dir=\"ltr\" class=\"bbc-1t9zlwf eede9f50\" readability=\"4\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Pie de foto, <\/span><\/p>\n<p>Desde octubre de 2019, los chilenos salieron a las calles a protestar en contra del sistema pol\u00edtico y econ\u00f3mico del pa\u00eds.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Este escenario, dijeron los analistas, no estaba ni entre los peores c\u00e1lculos de la ex Concertaci\u00f3n. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abLa ex Concertaci\u00f3n muri\u00f3 y se enterr\u00f3 hace tiempo y eso ha quedado muy claro en esta elecci\u00f3n\u00bb, dijo <b>Heraldo Mu\u00f1oz<\/b>, uno de los candidatos presidenciales de la centroizquierda. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Para Isikson, \u00abla \u00fanica coalici\u00f3n que logr\u00f3 cumplir con sus expectativas es el Frente Amplio y el Partido Comunista\u00bb. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abNo mejor\u00f3 su resultado con respecto a la representaci\u00f3n parlamentaria pero, dado que fue la \u00fanica coalici\u00f3n que logr\u00f3 sostener su resultado, evidentemente es ganadora\u00bb, dice Isikson. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Los resultados de esta elecci\u00f3n tienen una consecuencia esperada: la definici\u00f3n de las <b>candidaturas presidenciales. <\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">En Chile, hist\u00f3ricamente las elecciones de alcaldes y concejales han sido una especie de \u00abterm\u00f3metro\u00bb para medir las preferencias pol\u00edticas del electorado de cara a los comicios presidenciales, que siempre se realizan poco tiempo despu\u00e9s.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-172p16q e57qer20\">\n<div dir=\"ltr\" class=\"bbc-189y18v e57qer20\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-1k5hvrj e1whu0\" readability=\"8\"><noscript><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-29.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-30.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-31.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-32.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-33.jpg 800w\" alt=\"Los ex presidentes Eduardo Frei y Ricardo Lagos, ambos l\u00edderes de la Concertaci\u00f3n.\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-4.jpg\" width=\"976\" class=\"bbc-fat2bc e1enwo3v0\"><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv etq3yw90\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g e57qer20\" readability=\"8\"><figcaption dir=\"ltr\" class=\"bbc-1t9zlwf eede9f50\" readability=\"6\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Pie de foto, <\/span><\/p>\n<p>La centroizquierda fue otra de las coaliciones que no obtuvo los resultados esperados en estas elecciones. En la foto, los ex presidentes Eduardo Frei y Ricardo Lagos, ambos l\u00edderes de la Concertaci\u00f3n.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">As\u00ed, a seis meses de que Chile elija al pr\u00f3ximo jefe de Estado en noviembre de 2021, las tendencias marcadas este fin de semana ser\u00e1n particularmente relevantes para quienes piensan postular a la presidencia.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">En el bloque de izquierda sali\u00f3 fortalecido el candidato del Partido Comunista, <b>Daniel Jadue<\/b>, mientras que en la centroizquierda est\u00e1n evaluando a qui\u00e9n van a apoyar pues las cartas que tienen hasta ahora no parecen sumar el apoyo necesario. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">En la derecha, en tanto, tienen varias cartas presidenciales posibles. Uno de los an\u00e1lisis post elecciones apunta a que deber\u00edan elegir a un candidato que est\u00e9 m\u00e1s conectado con el electorado de hoy y no a una figura encasillada en la derecha tradicional. <\/p>\n<\/div>\n<p><h2 id=\"4-Paridad-de-g\u00e9nero\" tabindex=\"-1\" class=\"bbc-l3e97o e14hemmw0\">4. Paridad de g\u00e9nero<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Chile se convertir\u00e1 en el primer pa\u00eds del mundo en crear una Constituci\u00f3n con <b>paridad de g\u00e9nero.<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Esto, gracias al sistema electoral aplicado para elegir a los 155 miembros de la Convenci\u00f3n Constitucional, que garantiz\u00f3 que estuviera conformada de manera igualitaria por hombres y por mujeres. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Para ello, se implementaron mecanismos de correci\u00f3n que evitaron la sobrerrepresentaci\u00f3n de un sexo. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-172p16q e57qer20\">\n<div dir=\"ltr\" class=\"bbc-189y18v e57qer20\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-1k5hvrj e1whu0\" readability=\"8\"><noscript><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-34.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-35.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-36.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-37.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-38.jpg 800w\" alt=\"Protesta feminista en Chile\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-5.jpg\" width=\"976\" class=\"bbc-fat2bc e1enwo3v0\"><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv etq3yw90\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g e57qer20\" readability=\"6\"><figcaption dir=\"ltr\" class=\"bbc-1t9zlwf eede9f50\" readability=\"2\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Pie de foto, <\/span><\/p>\n<p>El movimiento feminista ha crecido considerablemente en Chile.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Pero, al contrario de lo que se esperaba, hubo algunos casos en los que las mujeres tuvieron que cederle sus cupos a los hombres, pues obtuvieron mayores resultados. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"7\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Esto sorprendi\u00f3 ampliamente a analistas y expertos en Chile.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abLa paridad no solo instal\u00f3 la necesidad de tener una convenci\u00f3n paritaria, sino tambi\u00e9n impuls\u00f3 a los electores a preferir mujeres por sobre hombres y en muchos distritos fueron finalmente las mujeres que tuvieron que ceder sus cupos para los hombres\u00bb, dice Isikson. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">De esta manera, la nueva Constituci\u00f3n chilena podr\u00eda tocar temas que hist\u00f3ricamente han quedado pendientes como la igualdad de salario, la repartici\u00f3n de carga de los cuidados o el acceso igualitario de las mujeres al poder.<\/p>\n<\/div>\n<p><h2 id=\"5-Tibia-participaci\u00f3n\" tabindex=\"-1\" class=\"bbc-l3e97o e14hemmw0\">5. Tibia participaci\u00f3n<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Con un <b>43% de participaci\u00f3n<\/b>, seg\u00fan el Servicio Electoral del Chile (Servel), la convocatoria para estas elecciones estuvo lejos de ser alta. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Para el plebiscito realizado en octubre del 2020, donde los chilenos aprobaron por una amplia mayor\u00eda cambiar la actual Constituci\u00f3n, la participaci\u00f3n lleg\u00f3 a un <b>50,9%<\/b>. Este n\u00famero represent\u00f3 la mayor votaci\u00f3n desde 2012, cuando comenz\u00f3 a regir el voto voluntario en el pa\u00eds.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-172p16q e57qer20\">\n<div dir=\"ltr\" class=\"bbc-189y18v e57qer20\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-1k5hvrj e1whu0\" readability=\"8\"><noscript><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-39.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-40.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-41.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-42.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-43.jpg 800w\" alt=\"Participaci\u00f3n elecciones\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-6.jpg\" width=\"976\" class=\"bbc-fat2bc e1enwo3v0\"><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv etq3yw90\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g e57qer20\" readability=\"6\"><figcaption dir=\"ltr\" class=\"bbc-1t9zlwf eede9f50\" readability=\"2\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Pie de foto, <\/span><\/p>\n<p>La participaci\u00f3n en estas elecciones lleg\u00f3 solo al 43%.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">En las \u00faltimas dos elecciones presidenciales (2013 y 2017), la participaci\u00f3n en la segunda vuelta estuvo cerca del <b>49%.<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Las elecciones de alcaldes y concejales, sin embargo, siempre han tenido una menor votaci\u00f3n, alrededor del <b>34%. <\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Dada la importancia de estos comicios, donde se eleg\u00edan a quienes van a escribir la nueva Constituci\u00f3n, hab\u00eda expectativa que de que la convocatoria fuera mayor de lo que termin\u00f3 siendo. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Y muchos se preguntan d\u00f3nde qued\u00f3 el electorado que le dio el triunfo a Sebasti\u00e1n Pi\u00f1era por m\u00e1s de un 54% en 2017.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abEs evidente que el mundo que vot\u00f3 por Pi\u00f1era en 2017, en un porcentaje muy significativo, no fue a votar\u00bb, explica Isikson.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">As\u00ed, una vez m\u00e1s, en Chile queda sobre la mesa la discusi\u00f3n sobre revocar el voto voluntario y volver a instalar uno obligatorio. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-172p16q e57qer20\">\n<div dir=\"ltr\" class=\"bbc-189y18v e57qer20\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-1k5hvrj e1whu0\" readability=\"8\"><noscript><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-44.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-45.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-46.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-47.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-48.jpg 800w\" alt=\"Chile\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-7.jpg\" width=\"976\" class=\"bbc-fat2bc e1enwo3v0\"><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv etq3yw90\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g e57qer20\" readability=\"6\"><figcaption dir=\"ltr\" class=\"bbc-1t9zlwf eede9f50\" readability=\"2\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Pie de foto, <\/span><\/p>\n<p>Las protestas culminaron con el voto de este domingo.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-172p16q e57qer20\">\n<div dir=\"ltr\" class=\"bbc-189y18v e57qer20\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-uhmmqj e1whu0\"><noscript><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-7.png 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-49.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-50.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-51.jpg 624w\" alt=\"line\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/elecciones-en-chile-sera-un-pais-distinto-5-claves-para-entender-los-ineditos-resultados-8.jpg\" width=\"624\" class=\"bbc-fat2bc e1enwo3v0\"><\/noscript><\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\"><i class=\"bbc-h1y5j7 ewc4zcb0\">Ahora puedes recibir notificaciones de BBC Mundo. Descarga la nueva versi\u00f3n de nuestra app y act\u00edvalas para no perderte nuestro mejor contenido.<\/i><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n BBC News Mundo 7 horas Fuente de la imagen, Getty Images Pie de foto, Este fin de semana los chilenos eligieron a los integrantes de la Convenci\u00f3n Constituyente, y a gobernadores, alcaldes y concejales. \u00abChile cambi\u00f3\u00bb. La frase se repiti\u00f3 una y otra vez entre expertos y l\u00edderes pol\u00edticos mientras aparec\u00edan los resultados de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4613,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/4612"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=4612"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/4612\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/4613"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=4612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=4612"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=4612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}