{"id":5172,"date":"2021-05-31T17:42:15","date_gmt":"2021-05-31T17:42:15","guid":{"rendered":"http:\/\/nuevacordoba.net\/index.php\/2021\/05\/31\/federico-delbonis-paso-a-la-segunda-ronda-del-roland-garros\/"},"modified":"2021-05-31T17:42:15","modified_gmt":"2021-05-31T17:42:15","slug":"federico-delbonis-paso-a-la-segunda-ronda-del-roland-garros","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/05\/31\/federico-delbonis-paso-a-la-segunda-ronda-del-roland-garros\/","title":{"rendered":"Federico Delbonis pas\u00f3 a la segunda ronda del Roland Garros"},"content":{"rendered":"<div class=\"image\" id=\"image\" readability=\"10\"> <img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/federico-delbonis-paso-a-la-segunda-ronda-del-roland-garros.jpg\" alt=\"Federico Delbonis le gan\u00f3 al moldavo Radu Albot por 6-1, 2-6, 6-0 y 6-1 en la primera ronda de Roland Garros.\" title=\"Federico Delbonis le gan\u00f3 al moldavo Radu Albot por 6-1, 2-6, 6-0 y 6-1 en la primera ronda de Roland Garros.\"><\/p>\n<p>Federico Delbonis le gan\u00f3 al moldavo Radu Albot por 6-1, 2-6, 6-0 y 6-1 en la primera ronda de Roland Garros.<\/p>\n<\/div>\n<p>El tenista argentino <strong>Federico Delbonis <\/strong>le gan\u00f3 al moldavo <strong>Radu Albot<\/strong> por <strong>6-1, 2-6, 6-0 y 6-1 en la primera ronda de Roland Garros <\/strong>y jugar\u00e1 la siguiente instancia ante el espa\u00f1ol <strong>Pablo And\u00fajar<\/strong>, responsable de la primera sorpresa del torneo al eliminar al cuarto preclasificado, el austr\u00edaco <strong>Dominic Thiem<\/strong>.<\/p>\n<p>El azule\u00f1o, <strong>n\u00famero 51 del mundo<\/strong>, lleg\u00f3 por cuarta vez en nueve ediciones a la segunda ronda del torneo de Par\u00eds, instancia que este a\u00f1o intentar\u00e1 superar por primera ocasi\u00f3n.<\/p>\n<p>El espa\u00f1ol And\u00fajar, 68vo. del ranking ATP, aventaja al argentino 3-1 en el historial de enfrentamientos del circuito mayor y tambi\u00e9n gan\u00f3 las otras tres veces que se vieron las caras por Challengers, siempre sobre polvo de ladrillo.<\/p>\n<p>Delbonis, semifinalista este a\u00f1o en Santiago de Chile y Belgrado, le dio al tenis al argentino la segunda victoria en la edici\u00f3n actual de Roland Garros tras el debut con \u00e9xito de <strong>Guido Pella<\/strong>, el domingo.<\/p>\n<div class=\"image\" id=\"image\" readability=\"9\"> <img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/05\/federico-delbonis-paso-a-la-segunda-ronda-del-roland-garros-1.jpg\" alt=\"Delbonis le tocar\u00e1 jugar la siguiente instancia ante el espa\u00f1ol Pablo And\u00fajar, que viene de descalificar a Dominic Thiem. \" title=\"Delbonis le tocar\u00e1 jugar la siguiente instancia ante el espa\u00f1ol Pablo And\u00fajar, que viene de descalificar a Dominic Thiem. \"><\/p>\n<p>Delbonis le tocar\u00e1 jugar la siguiente instancia ante el espa\u00f1ol Pablo And\u00fajar, que viene de descalificar a Dominic Thiem. <\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Federico Delbonis le gan\u00f3 al moldavo Radu Albot por 6-1, 2-6, 6-0 y 6-1 en la primera ronda de Roland Garros. El tenista argentino Federico Delbonis le gan\u00f3 al moldavo Radu Albot por 6-1, 2-6, 6-0 y 6-1 en la primera ronda de Roland Garros y jugar\u00e1 la siguiente instancia ante el espa\u00f1ol Pablo And\u00fajar, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5173,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/5172"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=5172"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/5172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/5173"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=5172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=5172"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=5172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}