{"id":55961,"date":"2025-04-12T12:17:36","date_gmt":"2025-04-12T12:17:36","guid":{"rendered":"https:\/\/www.bbc.com\/mundo\/articles\/cze1l6pgl3po#1"},"modified":"2025-04-12T12:17:36","modified_gmt":"2025-04-12T12:17:36","slug":"para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2025\/04\/12\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana\/","title":{"rendered":"\u00abPara que hubiera una canci\u00f3n como &#8216;Suavemente&#8217;, hizo falta un Rubby P\u00e9rez\u00bb: Elvis Crespo habla con BBC Mundo sobre Jet Set, s\u00edmbolo del merengue en Rep\u00fablica Dominicana"},"content":{"rendered":"<figure class=\"bbc-1qn0xuy\" readability=\"1.5\">\n<div class=\"bbc-j1srjl\" readability=\"8\"><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana.webp\" srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-8.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-9.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-10.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-11.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-12.webp 800w\" sizes=\"(min-width: 1008px) 760px, 100vw\" alt=\"Elvis Crespo\" loading=\"eager\" width=\"1015\" height=\"571\" class=\"bbc-139onq\"><\/p>\n<p class=\"bbc-by8ykd\" role=\"text\"><span class=\"bbc-m04vo2\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/figure>\n<section role=\"region\" aria-labelledby=\"article-byline\" class=\"bbc-1vjaf6b\"><strong id=\"article-byline\" aria-hidden=\"true\" class=\"bbc-m04vo2\">Informaci\u00f3n del art\u00edculo<\/strong><\/p>\n<ul role=\"list\" class=\"bbc-1rvtlej\">\n<li><span role=\"text\"><span class=\"bbc-m04vo2\">Autor, <\/span><span class=\"bbc-1ypcc2\">Ronald \u00c1vila-Claudio <\/span><\/span><\/li>\n<li><span role=\"text\"><span class=\"bbc-m04vo2\">T\u00edtulo del autor, <!-- --> <\/span><span class=\"bbc-1y5sx98\">BBC News Mundo <\/span><\/span><\/li>\n<li class=\"bbc-v8pmqw\">\n<p><time datetime=\"2025-04-11\" class=\"bbc-1dafq0j e1mklfmt0\">11 abril 2025<\/time><\/p>\n<\/li>\n<\/ul>\n<\/section>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>La noticia del derrumbe lo devast\u00f3, dice a BBC Mundo Elvis Crespo, uno de los exponentes de merengue de mayor trascendencia internacional.<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Conoci\u00f3 por primera vez la m\u00fasica de Rubby P\u00e9rez a los 10 a\u00f1os, cuando escuchaba y ve\u00eda las presentaciones del artista dominicano junto a la legendaria orquesta de Wilfrido Vargas.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">No hay duda, a\u00f1ade el ganador del Grammy Latino, de que la voz del int\u00e9rprete de \u00abVolver\u00e9\u00bb, que considera fue una de las m\u00e1s potentes de la industria, influy\u00f3 en su inter\u00e9s por el g\u00e9nero tropical.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Para Crespo, adem\u00e1s, Jet Set, la discoteca que la madrugada del martes se desplom\u00f3 mientras cientos de personas disfrutaban de un concierto de Rubby en Rep\u00fablica Dominicana, fue un <i class=\"bbc-h1y5j7 eih42320\">venue <\/i>que catapult\u00f3 a muchos artistas locales e internacionales que hoy disfrutan de renombre.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">\u00c9l mismo, siendo puertorrique\u00f1o, tuvo all\u00ed la oportunidad de cantar y conectar con el p\u00fablico dominicano.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">El club nocturno fue fundamental para que el merengue -un g\u00e9nero que naci\u00f3 en el siglo XIX y que se populariz\u00f3 a principios del siglo pasado- se mantuviera vivo, pese a los cambios en la industria musical y el nacimiento de nuevos ritmos en Latinoam\u00e9rica, como el reguet\u00f3n.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">All\u00ed, todos los lunes en la noche, como pas\u00f3 esta semana antes de la tragedia que dej\u00f3 221 muertos y cientos de heridos, se reun\u00edan miles de personas a escuchar y bailar ese estilo de m\u00fasica que es tan distintivo y pegajoso gracias al acorde\u00f3n, la g\u00fcira y la tambora.<\/p>\n<\/div>\n<figure class=\"bbc-1qn0xuy\" readability=\"1.5\">\n<div class=\"bbc-j1srjl\" readability=\"8\"><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-1.webp\" srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-13.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-14.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-15.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-16.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-17.webp 800w\" sizes=\"(min-width: 1008px) 760px, 100vw\" alt=\"juan luis guerra en el velatorio de rubby p\u00e9rez en rep\u00fablica dominicana \" loading=\"lazy\" width=\"1024\" height=\"576\" class=\"bbc-139onq\"><\/p>\n<p class=\"bbc-by8ykd\" role=\"text\"><span class=\"bbc-m04vo2\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div><figcaption class=\"bbc-15f1ujd\" dir=\"ltr\"><span role=\"text\"><span class=\"bbc-m04vo2\">Pie de foto, <\/span><span data-testid=\"caption-paragraph\">El funeral de Rubby P\u00e9rez se realiz\u00f3 este jueves en Santo Domingo, capital de Rep\u00fablica Dominicana. Asistieron personalidades como Juan Luis Guerra y el presidente dominicano Luis Abinader. <\/span><\/span><\/figcaption><\/figure>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Crespo -conocido mundialmente por ser uno de los responsables de internacionalizar el merengue, gracias a \u00e9xitos como Suavemente, canci\u00f3n que ocup\u00f3 el tope de la lista Hot Latin Tracks de Billboard- habl\u00f3 con BBC Mundo del legado de Rubby.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">El boricua, que tiene 30 a\u00f1os de carrera y sigue vigente, con un nuevo tour y un reciente disco llamado \u00abPoeta Herio\u00bb que estrena en junio, nos habla de la importancia del merengue en la sociedad dominicana.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Y tambi\u00e9n de la capacidad de este g\u00e9nero de mutar y transformarse, como seguramente ocurrir\u00e1 luego de esta dolorosa semana.<\/p>\n<\/div>\n<figure class=\"bbc-1qn0xuy\" readability=\"1.5\">\n<div class=\"bbc-j1srjl\" readability=\"8\"><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-2.webp\" srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-18.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-19.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-20.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-21.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-22.webp 800w\" sizes=\"(min-width: 1008px) 760px, 100vw\" alt=\"l\u00ednea gris que separa el texto\" loading=\"lazy\" width=\"800\" height=\"100\" class=\"bbc-139onq\"><\/p>\n<p class=\"bbc-by8ykd\" role=\"text\"><span class=\"bbc-m04vo2\">Fuente de la imagen, <\/span><span lang=\"en-GB\">BBC Mundo<\/span><\/p>\n<\/div>\n<\/figure>\n<figure class=\"bbc-1qn0xuy\" readability=\"1.5\">\n<div class=\"bbc-j1srjl\" readability=\"8\"><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-3.webp\" srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-23.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-24.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-25.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-26.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-27.webp 800w\" sizes=\"(min-width: 1008px) 760px, 100vw\" alt=\"El cantante puertorrique\u00f1o elvis crespo \" loading=\"lazy\" width=\"1003\" height=\"564\" class=\"bbc-139onq\"><\/p>\n<p class=\"bbc-by8ykd\" role=\"text\"><span class=\"bbc-m04vo2\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div><figcaption class=\"bbc-15f1ujd\" dir=\"ltr\"><span role=\"text\"><span class=\"bbc-m04vo2\">Pie de foto, <\/span><span data-testid=\"caption-paragraph\">Elvis Crespo dice que Rubby P\u00e9rez, el cantante dominicano que muri\u00f3 el martes en la tragedia de Jet Set, fue uno de sus referentes musicales. <\/span><\/span><\/figcaption><\/figure>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"7\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>\u00bfCu\u00e1l es el impacto de Rubby P\u00e9rez en el g\u00e9nero del merengue?<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Cuando me levant\u00e9 y comenc\u00e9 a recibir los mensajes sobre la tragedia en Jet Set, me lleg\u00f3 una enorme tristeza, me cambi\u00f3 la energ\u00eda.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">No solo falleci\u00f3 Rubby, falleci\u00f3 Felito Music, un productor que conozco desde hace a\u00f1os. Tambi\u00e9n el jugador de b\u00e9isbol Octavio Dotel, y todos los dem\u00e1s asistentes que perecieron por el derrumbe.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Es una situaci\u00f3n que uno nunca visualiza y cuando ocurre, es inevitable cuestionar por qu\u00e9 sucedi\u00f3.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"14\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Conozco el talento de Rubby desde la d\u00e9cada de los 80. Cantaba en la orquesta de Wilfrido Vargas. All\u00ed compart\u00eda con Sandy Reyes, otro genio dominicano y con un puertorrique\u00f1o que se llama Willie Berr\u00edos, que, de hecho, es de mi pueblo Guaynabo, mi vecino.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Comienzo a seguir el trabajo de Willie, y ah\u00ed conoc\u00ed el trabajo de Rubby P\u00e9rez. Luego emprende como solista y yo consum\u00eda su m\u00fasica.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Me atrever\u00eda a decir que est\u00e1 entre los mejores cinco cantantes del g\u00e9nero. Ten\u00eda una voz extraordinaria, potente.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">En Puerto Rico, que tambi\u00e9n ha dado enormes cantantes de merengue, en t\u00e9rminos de su voz, solo puede acercarse a la potencia de Rubby el cantante Joseph Fonseca.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Es duro como se nos fue Rubby, falleci\u00f3 haciendo lo que le apasiona, cantando sobre un escenario, algo que hago yo todo el tiempo.<\/p>\n<\/div>\n<figure class=\"bbc-1qn0xuy\" readability=\"1.5\">\n<div class=\"bbc-j1srjl\" readability=\"8\"><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-4.webp\" srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-28.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-29.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-30.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-31.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-32.webp 800w\" sizes=\"(min-width: 1008px) 760px, 100vw\" alt=\"escombros de la discoteca jet set luego del derrumbe del martes\" loading=\"lazy\" width=\"1024\" height=\"576\" class=\"bbc-139onq\"><\/p>\n<p class=\"bbc-by8ykd\" role=\"text\"><span class=\"bbc-m04vo2\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div><figcaption class=\"bbc-15f1ujd\" dir=\"ltr\"><span role=\"text\"><span class=\"bbc-m04vo2\">Pie de foto, <\/span><span data-testid=\"caption-paragraph\">221 personas murieron luego de que el martes de madrugada se derrumb\u00f3 la discoteca Jet Set. <\/span><\/span><\/figcaption><\/figure>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"7\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>Si fueras a describir su legado\u2026<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Calidad vocal. Un hombre que siempre hizo las cosas bien. No quiero criticar a los int\u00e9rpretes de este tiempo, porque sus manifestaciones art\u00edsticas son diferentes, muchos comienzan como <i class=\"bbc-h1y5j7 eih42320\">influencers<\/i>, pero un cantante como Rubby, no lo encontramos ahora.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"7\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Su calidad era universal.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"7\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>\u00bfQu\u00e9 signific\u00f3 la discoteca Jet Set para la m\u00fasica tropical y el merengue?<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Hasta el lunes, esta discoteca ten\u00eda 52 a 53 a\u00f1os operando de forma ininterrumpida. Sirvi\u00f3 de plataforma para int\u00e9rpretes y m\u00fasicos.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Mantuvo la m\u00fasica tropical viva inclusive a comienzos de siglo, cuando los movimientos musicales fueron cambiando a otros ritmos. Jet Set tambi\u00e9n se mantuvo fiel a realizar <i class=\"bbc-h1y5j7 eih42320\">shows <\/i>en vivo, no solo con cantantes, sino tambi\u00e9n con orquestas, instrumentos&#8230;<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Se convirti\u00f3 en una plataforma importante para los artistas dominicanos, pero tambi\u00e9n internacionales.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Yo cant\u00e9 en este lugar, tambi\u00e9n exponentes como Gilberto Santa Rosa, V\u00edctor Manuel, Tito Nieves y el Grupo Niche.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Una discoteca muy particular. Celebraba fiestas enormes los lunes. \u00bfPor qu\u00e9 un lunes? Porque hacer una fiesta los lunes no tiene sentido, pero mantener ese d\u00eda vivo durante toda la trayectoria del lugar la hizo \u00fanica e independiente.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Yo he viajado el mundo, y esa particularidad de realizar bailables los lunes, en 30 a\u00f1os de carrera, no la he visto en ning\u00fan lado.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"14\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Creo que se llenaba porque era el comienzo de la semana. Y siempre iban muchos medios, porque al ser tan emblem\u00e1tico, y estar tan vinculado a la cultura e idiosincrasia dominicana, iban muchos peloteros (jugadores de b\u00e9isbol), pol\u00edticos, m\u00fasicos y artistas en general.<\/p>\n<\/div>\n<figure class=\"bbc-1qn0xuy\" readability=\"1.5\">\n<div class=\"bbc-j1srjl\" readability=\"8\"><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-5.webp\" srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-33.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-34.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-35.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-36.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-37.webp 800w\" sizes=\"(min-width: 1008px) 760px, 100vw\" alt=\"foto promocional del nuevo disco de elvis crespo &quot;poeta herio&quot;\" loading=\"lazy\" width=\"2048\" height=\"1536\" class=\"bbc-139onq\"><\/p>\n<p class=\"bbc-by8ykd\" role=\"text\"><span class=\"bbc-m04vo2\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Suministrada<\/span><\/p>\n<\/div><figcaption class=\"bbc-15f1ujd\" dir=\"ltr\"><span role=\"text\"><span class=\"bbc-m04vo2\">Pie de foto, <\/span><span data-testid=\"caption-paragraph\">Con 30 a\u00f1os de carrera, Elvis Crespo contin\u00faa haciendo m\u00fasica, muestra de que el merengue es un g\u00e9nero con capacidad de transformarse.<\/span><\/span><\/figcaption><\/figure>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"7\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>\u00bfQu\u00e9 recuerdo bonito tienes de Jet Set?<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"7\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Tengo un gran recuerdo que incluso creo que est\u00e1 publicado en YouTube.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">En una de mis presentaciones en Jet Set, mientras cantaba una canci\u00f3n, me entregaron una nota y me dijeron que en la discoteca estaba Pedro Mart\u00ednez, el jugador de Grandes Ligas de B\u00e9isbol. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Yo soy fan\u00e1tico del b\u00e9isbol. As\u00ed que ped\u00ed que bajaran el volumen de la m\u00fasica, y dije que quer\u00eda conocerlo.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Baj\u00e9 del escenario, me pase\u00e9 por el p\u00fablico mientras todos gritaban, y pude saludarlo.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"7\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>Y con Rubby tienes alg\u00fan recuerdo\u2026<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Para que existiera una canci\u00f3n como Suavemente, para que existiera un Elvis Crespo, tuvo que haber antes un Rubby P\u00e9rez.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Los palos (temas musicales) que peg\u00f3 Rubby fueron universales. Desde canciones como \u00abEl Africano\u00bb\u2026 (canta<i class=\"bbc-h1y5j7 eih42320\"> Mami el negro est\u00e1 rabioso quiere pelear conmigo dec\u00edselo a mi pap\u00e1)<\/i> hasta temas como Volver\u00e9 son parte de su impresionante repertorio.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Estoy escuchando su m\u00fasica y su arte desde los 10 a\u00f1os, cuando comenc\u00e9 a encontrarme como artista.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Recuerdo que una vez estuve con \u00e9l en la casa de don Johnny Ventura, quien hab\u00eda grabado un \u00e1lbum de Navidad y est\u00e1bamos filmando el contenido visual.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Estuve all\u00ed compartiendo con \u00e9l y con Rafa Rosario. Un gran ser humano, como el pueblo dominicano, todos son buena gente.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>C\u00f3mo y por qu\u00e9 el merengue se ha convertido en un g\u00e9nero tan importante para la sociedad dominicana y para el mundo, de forma tal que a\u00fan ocurre un bailable un martes en la madrugada y repleto de gente.<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"14\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Porque est\u00e1 enormemente vinculado a toda la historia dominicana. De hecho, fue el dictador Rafael Le\u00f3nidas Trujillo, quien estuvo en el poder desde los a\u00f1os 30 hasta el 61, quien lo hizo popular. Lo incorpor\u00f3 en todos sus asuntos de campa\u00f1a, en una \u00e9poca en que se conceb\u00eda como un g\u00e9nero de poca reputaci\u00f3n.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"7\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Y ahora es parte del ADN dominicano.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Es un g\u00e9nero que tiene \u00e9xitos universales desde los a\u00f1os 30. Parecer\u00eda inmortal. Demasiado sabroso, que es muy f\u00e1cil de bailar y que se adapta a cualquier otro g\u00e9nero. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"14\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Y las letras son diversas. Hay merengue rom\u00e1ntico, las escuchamos en el cat\u00e1logo de Rubby, de Alex Bueno, que tienes canciones que son joyas. Pero tambi\u00e9n m\u00fasica chabacana como \u00abEl hoyo\u00bb, de Kinito M\u00e9ndez, \u00abLa Faldita\u00bb de la Cocoband. \u00abLa Vaca\u00bb de Mala Fe y el \u00abKulikitaka\u00bb de To\u00f1o Rosario.<\/p>\n<\/div>\n<figure class=\"bbc-1qn0xuy\" readability=\"1.5\">\n<div class=\"bbc-j1srjl\" readability=\"8\"><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-6.webp\" srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-38.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-39.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-40.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-41.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-42.webp 645w\" sizes=\"(min-width: 1008px) 760px, 100vw\" alt=\"elvis crespo cantando sobre un escenario \" loading=\"lazy\" width=\"645\" height=\"1024\" class=\"bbc-139onq\"><\/p>\n<p class=\"bbc-by8ykd\" role=\"text\"><span class=\"bbc-m04vo2\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div><figcaption class=\"bbc-15f1ujd\" dir=\"ltr\"><span role=\"text\"><span class=\"bbc-m04vo2\">Pie de foto, <\/span><span data-testid=\"caption-paragraph\">\u00abSuavemente\u00bb es uno de los \u00e9xitos de Elvis Crespo que ayudaron a internacionalizar el merengue. <\/span><\/span><\/figcaption><\/figure>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Incluso artistas que no nacimos en Rep\u00fablica Dominicana, lo interpretamos bien, porque despierta nuestro lado art\u00edstico.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Hoy ves a Karol G grabando merengue, a Manuel Turizo, porque tienen buenos resultados con el merengue. Es un g\u00e9nero que trasciende.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Alguna vez escuch\u00e9 a Bonny Cepeda, hace como cinco o seis a\u00f1os, decir en una entrevista que el merengue es un g\u00e9nero sabio, que se adapta a los tiempos.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"7\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><b>Gracias por hablar con nosotros. \u00bfHay algo que quieras agregar?<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\">Dile por favor al pueblo dominicano que yo tambi\u00e9n lo siento mucho, los tengo en mis oraciones. Su dolor me toca.<\/p>\n<\/div>\n<figure class=\"bbc-1qn0xuy\">\n<div class=\"bbc-j1srjl\"><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-7.webp\" srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-43.webp 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-44.webp 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-45.webp 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-46.webp 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2025\/04\/para-que-hubiera-una-cancion-como-suavemente-hizo-falta-un-rubby-perez-elvis-crespo-habla-con-bbc-mundo-sobre-jet-set-simbolo-del-merengue-en-republica-dominicana-47.webp 800w\" sizes=\"(min-width: 1008px) 760px, 100vw\" alt=\"l\u00ednea gris que separa el texto \" loading=\"lazy\" width=\"800\" height=\"100\" class=\"bbc-139onq\"><\/div>\n<\/figure>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"6.9206349206349\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><a href=\"https:\/\/www.bbc.com\/mundo\/send\/u184973209\" class=\"focusIndicatorReducedWidth bbc-n8oauk e1p3sufg0\"><i class=\"bbc-h1y5j7 eih42320\">Suscr\u00edbete aqu\u00ed<\/i><\/a><i class=\"bbc-h1y5j7 eih42320\"> a nuestro nuevo newsletter para recibir cada viernes una selecci\u00f3n de nuestro mejor contenido de la semana.<\/i><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr ebmt73l0\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-hhl7in e17g058b0\"><i class=\"bbc-h1y5j7 eih42320\">Y recuerda que puedes recibir notificaciones en nuestra app. Descarga la \u00faltima versi\u00f3n y act\u00edvalas.<\/i><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fuente de la imagen, Getty Images Informaci\u00f3n del art\u00edculo Autor, Ronald \u00c1vila-Claudio T\u00edtulo del autor, BBC News Mundo 11 abril 2025 La noticia del derrumbe lo devast\u00f3, dice a BBC Mundo Elvis Crespo, uno de los exponentes de merengue de mayor trascendencia internacional. Conoci\u00f3 por primera vez la m\u00fasica de Rubby P\u00e9rez a los 10 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/55961"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=55961"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/55961\/revisions"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=55961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=55961"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=55961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}