{"id":5636,"date":"2021-06-11T03:17:55","date_gmt":"2021-06-11T03:17:55","guid":{"rendered":"http:\/\/estaciontrip.com.ar\/?p=5790"},"modified":"2021-06-11T03:17:55","modified_gmt":"2021-06-11T03:17:55","slug":"el-turismo-en-el-mundo-cayo-un-83-en-tres-meses-aunque-mejora-la-confianza","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/06\/11\/el-turismo-en-el-mundo-cayo-un-83-en-tres-meses-aunque-mejora-la-confianza\/","title":{"rendered":"El turismo en el mundo cay\u00f3 un 83% en tres meses, aunque mejora la confianza"},"content":{"rendered":"<div><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/el-turismo-en-el-mundo-cayo-un-83-en-tres-meses-aunque-mejora-la-confianza.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p><em>Entre enero y marzo de 2021, los destinos del mundo recibieron 180 millones menos de turistas que el a\u00f1o anterior; en 2020 las p\u00e9rdidas fueron por US$900 mil millones.<\/em><\/p>\n<p>Las llegadas de turistas internacionales en el primer trimestre de 2021 han sido un 83% inferior, al haberse mantenido de forma generalizada las restricciones a los viajes, seg\u00fan informa mediante un comunicado La Organizaci\u00f3n Mundial del Turismo (OMT).<\/p>\n<p>No obstante, el \u00cdndice de Confianza de la OMT da se\u00f1ales de un lento repunte de la confianza.<\/p>\n<p>Entre enero y marzo de 2021, los destinos del mundo recibieron 180 millones menos de llegadas de turistas internacionales en comparaci\u00f3n con el primer trimestre del pasado a\u00f1o.<\/p>\n<p>Asia y el Pac\u00edfico mostraron los niveles m\u00e1s bajos de actividad, con una ca\u00edda del 94% de las llegadas internacionales durante el trimestre. Europa registr\u00f3 la segunda mayor ca\u00edda (-83%), seguida de \u00c1frica (-81%), oriente Medio (-78%) y las Am\u00e9ricas (-71%).<\/p>\n<p>Son cifras que dan continuaci\u00f3n a un descenso del 73% de las llegadas de turistas internacionales en el mundo en 2020, el peor a\u00f1o que ha registrado el sector.<\/p>\n<p><strong>La falta de coordinaci\u00f3n dificulta<\/strong><\/p>\n<p>El secretario general de la OMT, Zurab Pololikashvili, dijo que \u201cexiste una significativa demanda acumulada y <strong>vemos que la confianza se va restableciendo lentamente. Las vacunas ser\u00e1n la clave para la recuperaci\u00f3n<\/strong>, pero si queremos ver un repunte en la temporada de verano del hemisferio Norte, debemos mejorar la coordinaci\u00f3n y la comunicaci\u00f3n, y lograr a la vez que las pruebas sean m\u00e1s f\u00e1ciles y asequibles\u201d.<\/p>\n<p>La \u00faltima encuesta del grupo de expertos en turismo de la OMT mejora ligeramente las expectativas para el periodo mayo-agosto. Adem\u00e1s, el ritmo de vacunaci\u00f3n en algunos mercados emisores clave, as\u00ed como las pol\u00edticas para reiniciar el turismo con seguridad, especialmente mediante el certificado digital verde la UE, han creado nuevas esperanzas en algunos de estos mercados.<\/p>\n<p>En general, el 60% cree que el repunte del turismo internacional no llegar\u00e1 hasta 2022, frente al 50% en la encuesta de enero de 2021. El 40% restante ve un posible repunte en 2021, un porcentaje ligeramente inferior al de enero. Casi la mitad de los expertos no prev\u00e9n una vuelta a los niveles de turismo internacional de 2019 antes de 2024 o m\u00e1s tarde, mientras que el porcentaje de encuestados que indica una vuelta a los niveles anteriores a la pandemia en 2023 ha disminuido ligeramente (37%), en comparaci\u00f3n con la encuesta de enero.&nbsp;<\/p>\n<p>Los expertos en turismo se\u00f1alan la continua imposici\u00f3n de restricciones a los viajes y la falta de coordinaci\u00f3n en los protocolos de viaje y salud como el principal obst\u00e1culo para la recuperaci\u00f3n del sector.<\/p>\n<p>El Bar\u00f3metro del Turismo Mundial de la OMT tambi\u00e9n muestra el coste econ\u00f3mico de la pandemia. Los ingresos del turismo internacional en 2020 se redujeron un 64% en t\u00e9rminos reales (monedas locales, precios constantes), lo que equivale a una ca\u00edda de m\u00e1s de 900.000 millones de d\u00f3lares, recortando el valor global de las exportaciones mundiales en m\u00e1s de un 4% en 2020.<\/p>\n<p>La p\u00e9rdida total de ingresos por exportaciones del turismo internacional (incluido el transporte de pasajeros) asciende a casi 1,1 billones de d\u00f3lares. Asia y el Pac\u00edfico (-70% en t\u00e9rminos reales) y Oriente Medio (-69%) registraron las mayores ca\u00eddas de ingresos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre enero y marzo de 2021, los destinos del mundo recibieron 180 millones menos de turistas que el a\u00f1o anterior; en 2020 las p\u00e9rdidas fueron por US$900 mil millones. Las llegadas de turistas internacionales en el primer trimestre de 2021 han sido un 83% inferior, al haberse mantenido de forma generalizada las restricciones a los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5637,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[11],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/5636"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=5636"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/5636\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/5637"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=5636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=5636"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=5636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}