{"id":5726,"date":"2021-06-11T03:01:38","date_gmt":"2021-06-11T03:01:38","guid":{"rendered":"https:\/\/puntoapunto.com.ar\/?p=279394"},"modified":"2021-06-11T03:01:38","modified_gmt":"2021-06-11T03:01:38","slug":"incubacor-se-desarrolla-la-quinta-edicion-con-18-proyectos-seleccionados","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/06\/11\/incubacor-se-desarrolla-la-quinta-edicion-con-18-proyectos-seleccionados\/","title":{"rendered":"Incubacor: se desarrolla la quinta edici\u00f3n con 18 proyectos seleccionados"},"content":{"rendered":"<p><!-- image --><\/p>\n<div class=\"td-post-featured-image\"><a href=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/incubacor-se-desarrolla-la-quinta-edicion-con-18-proyectos-seleccionados-5.jpg\" data-caption><img loading=\"lazy\" width=\"696\" height=\"463\" class=\"entry-thumb td-modal-image\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/incubacor-se-desarrolla-la-quinta-edicion-con-18-proyectos-seleccionados.jpg\" srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/incubacor-se-desarrolla-la-quinta-edicion-con-18-proyectos-seleccionados.jpg 696w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/incubacor-se-desarrolla-la-quinta-edicion-con-18-proyectos-seleccionados-1.jpg 300w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/incubacor-se-desarrolla-la-quinta-edicion-con-18-proyectos-seleccionados-2.jpg 768w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/incubacor-se-desarrolla-la-quinta-edicion-con-18-proyectos-seleccionados-3.jpg 150w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/incubacor-se-desarrolla-la-quinta-edicion-con-18-proyectos-seleccionados-4.jpg 632w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/incubacor-se-desarrolla-la-quinta-edicion-con-18-proyectos-seleccionados-5.jpg 993w\" sizes=\"(max-width: 696px) 100vw, 696px\" alt title=\"Incubacor\"><\/a><\/div>\n<p> <!-- content --><\/p>\n<div class=\"td-a-rec td-a-rec-id-content_top tdi_73_ed2 td_block_template_10\">\n<div class=\"g g-34\">\n<div class=\"g-single a-299\"><a class=\"gofollow\" data-track=\"Mjk5LDM0LDEsNjA=\" href=\"http:\/\/www.grupocanter.com.ar\/landing\/pap\/?utm_source=Punto%20a%20Punto&amp;utm_medium=Banner&amp;utm_campaign=Departamentos&amp;utm_term=Banner%20Pie%20de%20Nota\"><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/incubacor-se-desarrolla-la-quinta-edicion-con-18-proyectos-seleccionados.gif\"><\/a><\/div>\n<\/div>\n<\/div>\n<p>Comenz\u00f3 la quinta cohorte del programa Incubacor con la presentaci\u00f3n de <strong>18 proyectos seleccionados<\/strong>, que durante seis meses transitar\u00e1n el <strong>proceso de preincubaci\u00f3n para la validaci\u00f3n t\u00e9cnica y comercial de las respectivas ideas de negocio<\/strong>.<\/p>\n<p>A trav\u00e9s del programa, emprendedoras y emprendedores tienen la oportunidad de <strong>desarrollar proyectos tecnol\u00f3gicos, productivos, de servicio, audiovisuales, deportivos , salud, agro-tech, g\u00e9nero, sociales<\/strong>, entre otros.<\/p>\n<p>Los proyectos reciben asesor\u00eda, capacitaci\u00f3n, asistencia y mentor\u00eda personalizada de profesionales calificados en distintas especialidades para que puedan llegar a un concepto definido sobre la viabilidad y puesta en marcha de sus emprendimientos hasta su ejecuci\u00f3n<\/p>\n<p>En esta edici\u00f3n, de los 18 proyectos elegidos,&nbsp;<strong>10 (56%) provienen de ciudad de C\u00f3rdoba<\/strong>; los&nbsp;<strong>ocho restantes (44%) son del interior<\/strong>&nbsp;Los&nbsp;<strong>proyectos liderados por mujeres<\/strong>&nbsp;este a\u00f1o aumentaron: se presentaron&nbsp;<strong>10 (56% del total<\/strong>), cuando en las cohortes anteriores llegaron a 10% y 15%. Este incremento se debe al <a href=\"https:\/\/puntoapunto.com.ar\/tag\/trabajo\/\" class=\"st_tag internal_tag\" rel=\"tag\" title=\"Posts tagged with trabajo\">trabajo<\/a> transversal entre Incubacor y el Espacio de Mujeres de la C\u00f3rdoba Productiva.<\/p>\n<h5><strong>Proyectos seleccionados<\/strong><\/h5>\n<ol type=\"1\">\n<li><strong>ArteHa,<\/strong> de <a href=\"https:\/\/puntoapunto.com.ar\/tag\/rio\/\" class=\"st_tag internal_tag\" rel=\"tag\" title=\"Posts tagged with Rio\">Rio<\/a> Ceballos<\/li>\n<li><strong>S.P Mangueras de silicona,<\/strong>&nbsp;de C\u00f3rdoba<\/li>\n<li><strong>Equilibrate&nbsp;<\/strong>(deportes), de C\u00f3rdoba<\/li>\n<li><strong>Reality Team,<\/strong>&nbsp;de Villa Mar\u00eda<\/li>\n<li><strong>Lumbre,&nbsp;<\/strong>de R\u00edo Ceballos<\/li>\n<li><strong>R\u00e9sugique,&nbsp;<\/strong>de C\u00f3rdoba<\/li>\n<li><strong>Pilot .AR Agro,&nbsp;<\/strong>de C\u00f3rdoba<\/li>\n<li><strong>FS Life,<\/strong>&nbsp;de C\u00f3rdoba.<\/li>\n<li><strong>Berna, (Hidromiel),<\/strong>&nbsp;de Los Reartes<\/li>\n<li><strong>Loca Mala<\/strong>, de Malague\u00f1o<\/li>\n<li><strong>Rindo Online (deportes),<\/strong>&nbsp;de C\u00f3rdoba<\/li>\n<li><strong>Maricon Latinx,<\/strong>&nbsp;de C\u00f3rdoba<\/li>\n<li><strong>Santa Lucia,<\/strong>&nbsp;de Villa Mar\u00eda<\/li>\n<li><strong>Hidro Green<\/strong>, de Del Campillo<\/li>\n<li><strong>Ninfa (deportes),&nbsp;<\/strong>de C\u00f3rdoba<\/li>\n<li><strong>Bienvenides<\/strong>, de C\u00f3rdoba<\/li>\n<li><strong>We Keep,<\/strong>&nbsp;de San Francisco<\/li>\n<li><strong>Motus,&nbsp;<\/strong>de C\u00f3rdoba<\/li>\n<\/ol>\n<p>En la apertura, el ministro Eduardo&nbsp;Accastello inst\u00f3 a que en los pr\u00f3ximos meses <strong>\u201cse realice un encuentro para que Incubacor se muestre a nivel nacional y se conozca lo que hacemos en C\u00f3rdoba\u201d&nbsp;<\/strong>y que adem\u00e1s esta instancia sea para generar un espacio de integraci\u00f3n y articulaci\u00f3n de acciones colaborativas entre los participantes de las diferentes cohortes<strong>.<\/strong><\/p>\n<p><strong>Mar\u00eda Victoria Puig<\/strong>, emprendedora de la III Cohorte, coment\u00f3 su experiencia de su paso por Incubacor, con su <a href=\"https:\/\/puntoapunto.com.ar\/tag\/proyecto\/\" class=\"st_tag internal_tag\" rel=\"tag\" title=\"Posts tagged with Proyecto\">proyecto<\/a> de la Escuela Multidimensional de Espalda \u2013EME-, proyecto que devino en una <a href=\"https:\/\/puntoapunto.com.ar\/tag\/pyme\/\" class=\"st_tag internal_tag\" rel=\"tag\" title=\"Posts tagged with pyme\">pyme<\/a> y ahora est\u00e1 iniciando el camino de internacionalizaci\u00f3n.<\/p>\n<p>El programa Incubacor es&nbsp;una instancia en donde las emprendedoras y&nbsp; emprendedores tienen la oportunidad de <strong>desarrollar proyectos de diferentes verticales. <\/strong>Durante la etapa de gestaci\u00f3n (pre-incubaci\u00f3n), es donde validan t\u00e9cnica y comercialmente sus ideas de negocios.<\/p>\n<p>Los proyectos incubados reciben asesor\u00eda, capacitaci\u00f3n, asistencia y mentor\u00eda personalizada de profesionales calificados en distintas especialidades para que puedan llegar a un concepto definido sobre la viabilidad y puesta en marcha de sus emprendimientos hasta su ejecuci\u00f3n.<\/p>\n<p> <!-- A generated by theme --> <!-- end A --> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comenz\u00f3 la quinta cohorte del programa Incubacor con la presentaci\u00f3n de 18 proyectos seleccionados, que durante seis meses transitar\u00e1n el proceso de preincubaci\u00f3n para la validaci\u00f3n t\u00e9cnica y comercial de las respectivas ideas de negocio. A trav\u00e9s del programa, emprendedoras y emprendedores tienen la oportunidad de desarrollar proyectos tecnol\u00f3gicos, productivos, de servicio, audiovisuales, deportivos , [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5727,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/5726"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=5726"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/5726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/5727"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=5726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=5726"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=5726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}