{"id":5970,"date":"2021-06-18T00:18:18","date_gmt":"2021-06-18T00:18:18","guid":{"rendered":"https:\/\/www.ole.com.ar\/temperley\/temperley-almirante-brown_0_3EBaP3Rt1.html"},"modified":"2021-06-18T00:18:18","modified_gmt":"2021-06-18T00:18:18","slug":"almirante-le-dio-vuelta-un-partidazo-a-temperley","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/06\/18\/almirante-le-dio-vuelta-un-partidazo-a-temperley\/","title":{"rendered":"Almirante le dio vuelta un partidazo a Temperley"},"content":{"rendered":"<div><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/almirante-le-dio-vuelta-un-partidazo-a-temperley.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>Le entraba agua por todos los costados. De a poco se iba hundiendo y las ilusiones por salvar el partido cada vez estaban m\u00e1s lejos. Como si fuera poco, el 0-2 en apenas algunos minutos del primer tiempo no auguraban un buen destino. Pero La Fragata se aferr\u00f3 a la \u00faltima esperanza que ten\u00eda y, contra viento y marea, sac\u00f3 a flojo un encuentro que parec\u00eda perdido. S\u00ed, levant\u00f3 un partidazo frente a Temperley y cosech\u00f3 tres puntos important\u00edsimos para quedar ah\u00ed nom\u00e1s de los puestos de Reducido.<\/p>\n<p>El primer tiempo tuvo de todo: intensidad, cuchillo entre los dientes y tres goles. Pese a la local\u00eda, el Gasolero aprovech\u00f3 el envi\u00f3n de las victorias ante Chacarita y frente a Chicago para pisar fuerte fuera de su casa. As\u00ed, abri\u00f3 el marcador a trav\u00e9s de un buen centro de Facundo Pumpido para la aparici\u00f3n goleadora de Franco D\u00edaz y estir\u00f3 la diferencia poco despu\u00e9s con un cabezazo de Gaspar Vega. Sin embargo, no se pudo relajar. \u00bfPor qu\u00e9? Almirante alcanz\u00f3 a descontar por medio de un remate del Gur\u00ed Garc\u00eda que se desvi\u00f3 en un defensor de la visita.<\/p>\n<p>En el complemento, Fabi\u00e1n Nardozza quem\u00f3 las naves: meti\u00f3 todo lo que ten\u00eda en el banco y enderez\u00f3 el rumbo a partir de la determinaci\u00f3n y el car\u00e1cter que demostr\u00f3. Pese a su estatura, Pomelo Vera se hizo gigante en el \u00e1rea para poner el empate. Y m\u00e1s all\u00e1 de la roja a Dattola, el mirasol lo gan\u00f3 con un testazo de \u00c1lvaro L\u00f3pez: 3-2 y fiesta.<\/p>\n<p> <opta-widget sport=\"football\" widget=\"timeline\" competition=\"627\" season=\"2021\" match=\"2193272\" template=\"normal\" live=\"true\" orientation=\"horizontal\" vertical_timebar_height=\"260\" show_match_header=\"true\" show_score=\"true\" show_crests=\"true\" show_assists=\"all\" show_team_formation=\"true\" show_clock=\"true\" show_period_dividers=\"true\" show_halftime_score=\"false\" show_date=\"true\" date_format=\"dddd D MMMM YYYY\" show_attendance=\"true\" show_images=\"true\" show_referee=\"true\" show_venue=\"true\" show_cards=\"all\" show_goals=\"true\" show_penalties_missed=\"true\" show_subs=\"false\" show_goals_combined=\"false\" show_shootouts=\"false\" show_competition_name=\"true\" competition_naming=\"full\" team_naming=\"full\" player_naming=\"full\" show_live=\"true\" show_logo=\"false\" show_title=\"true\" breakpoints=\"400, 700\"><\/opta-widget><opta-widget sport=\"football\" widget=\"matchstats\" competition=\"627\" season=\"2021\" match=\"2193272\" template=\"lineups\" live=\"true\" side=\"both\" column_count=\"1\" side_by_side=\"true\" show_match_header=\"true\" show_score=\"true\" show_halftime_score=\"false\" show_crests=\"false\" show_team_formation=\"true\" show_competition_name=\"true\" show_date=\"false\" date_format=\"dddd D MMMM YYYY\" order_by=\"position\" group_by_position=\"false\" show_position=\"true\" show_images=\"false\" show_key=\"false\" show_starters=\"true\" show_goalkeepers=\"true\" show_defenders=\"true\" show_midfielders=\"true\" show_forwards=\"true\" show_subs=\"true\" show_unused_subs=\"false\" show_managers=\"true\" show_captain=\"false\" show_match_events=\"true\" competition_naming=\"full\" team_naming=\"full\" player_naming=\"full\" show_live=\"false\" show_logo=\"false\" show_title=\"true\" breakpoints=\"400, 700\"><\/opta-widget><opta-widget widget=\"commentary\" competition=\"627\" season=\"2021\" match=\"2193272\" template=\"normal\" live=\"true\" data_type=\"auto\" order_by=\"time_descending\" show_event_icons=\"true\" show_minor_events=\"true\" fixed_height_comments=\"300\" show_live=\"true\" show_logo=\"false\" show_title=\"true\" breakpoints=\"400\" sport=\"football\"><\/opta-widget><opta-widget sport=\"football\" widget=\"heatmap\" competition=\"627\" season=\"2021\" match=\"2193272\" preselected_player template=\"normal\" live=\"true\" show_maps=\"all\" orientation=\"horizontal\" side=\"both\" dimension=\"2D\" one_direction=\"false\" show_match_header=\"true\" show_score=\"true\" show_halftime_score=\"false\" show_crests=\"false\" show_team_formation=\"true\" show_competition_name=\"true\" show_date=\"true\" date_format=\"dddd D MMMM YYYY\" show_team_sheets=\"true\" show_subs=\"true\" show_position=\"true\" show_timecontrols=\"true\" show_timecontrols_buttons=\"true\" show_timecontrols_bar=\"true\" show_tooltips=\"false\" competition_naming=\"full\" team_naming=\"full\" player_naming=\"full\" show_logo=\"false\" show_title=\"true\" breakpoints=\"400, 700\"><\/opta-widget><opta-widget sport=\"football\" widget=\"standings\" competition=\"627\" season=\"2021\" match=\"2193272\" team template=\"normal\" live=\"true\" default_nav=\"1\" side=\"combined\" data_detail=\"default\" show_key=\"false\" show_crests=\"false\" points_in_first_column=\"false\" lose_before_draw=\"false\" show_form=\"0\" competition_naming=\"full\" team_naming=\"full\" date_format=\"dddd D MMMM YYYY\" sorting=\"true\" show_live=\"false\" show_relegation_average=\"true\" show_logo=\"false\" show_title=\"true\" breakpoints=\"400\"><\/opta-widget> <\/p>\n<div class=\"entry-tags\">\n<h2>TEMAS QUE APARECEN EN ESTA NOTA<\/h2>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le entraba agua por todos los costados. De a poco se iba hundiendo y las ilusiones por salvar el partido cada vez estaban m\u00e1s lejos. Como si fuera poco, el 0-2 en apenas algunos minutos del primer tiempo no auguraban un buen destino. Pero La Fragata se aferr\u00f3 a la \u00faltima esperanza que ten\u00eda y, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5971,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/5970"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=5970"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/5970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/5971"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=5970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=5970"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=5970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}