{"id":6360,"date":"2021-06-28T12:05:03","date_gmt":"2021-06-28T12:05:03","guid":{"rendered":"http:\/\/nuevacordoba.net\/index.php\/2021\/06\/28\/la-variante-delta-obliga-a-una-parte-del-mundo-a-aplicar-nuevas-restricciones\/"},"modified":"2021-06-28T12:05:03","modified_gmt":"2021-06-28T12:05:03","slug":"la-variante-delta-obliga-a-una-parte-del-mundo-a-aplicar-nuevas-restricciones","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/06\/28\/la-variante-delta-obliga-a-una-parte-del-mundo-a-aplicar-nuevas-restricciones\/","title":{"rendered":"La variante Delta obliga a una parte del mundo a aplicar nuevas restricciones"},"content":{"rendered":"<div class=\"image\" id=\"image\" readability=\"7\"> <img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/la-variante-delta-obliga-a-una-parte-del-mundo-a-aplicar-nuevas-restricciones.jpg\" alt=\"La OMS viene advirtiendo a los paises sobre tomar m\u00e1s recaudos contra esta variante \" title=\"La OMS viene advirtiendo a los paises sobre tomar m\u00e1s recaudos contra esta variante \"><\/p>\n<p>La OMS viene advirtiendo a los paises sobre tomar m\u00e1s recaudos contra esta variante <\/p>\n<\/div>\n<p>El <strong>Reino Unido<\/strong> inform\u00f3 este domingo18.270 casos de la Covid-19 en las \u00faltimas 24 horas y 23 decesos, casi el doble que el d\u00eda anterior, en medio de un <strong><a href=\"https:\/\/www.telam.com.ar\/notas\/202106\/559224-reino-unido-nuevos-contagios.html\" target=\"_blank\" rel=\"noopener\">nuevo repunte por la aparici\u00f3n de la variante Delta<\/a><\/strong>, que golpea a instituciones educativas.<\/p>\n<p>Entre el 13 y 20 de este mes, los contagios en las escuelas primarias se incrementaron un 70% y en la tercera semana de este mes m\u00e1s de 16.000 alumnos no asistieron a clases por sospechas de infecci\u00f3n, seg\u00fan inform\u00f3 el diario Times replicado por la agencia de noticias ANSA.<\/p>\n<p>Esa misma semana, <strong>el n\u00famero de brotes en escuelas y universidades salt\u00f3 de 96 a 148, un aumento del 54%<\/strong>, cifra que marc\u00f3 el n\u00famero semanal m\u00e1s alto de brotes reportados al servicio de Salud P\u00fablica de Inglaterra desde diciembre.<\/p>\n<p>Desde el inicio de la pandemia, el pa\u00eds acumul\u00f3 4,7 millones de casos y 128.083 muertes por la enfermedad, seg\u00fan los datos del Ministerio de Salud, al tiempo que 44 millones de los 66,65 millones de habitantes recibieron al menos una dosis del f\u00e1rmaco y 32 millones, las dos.<\/p>\n<p>La pandemia de la Covid-19 rozaba los 181 millones de infecciones acumuladas y los cuatro millones de fallecimientos en todo el mundo, aunque las campa\u00f1as de vacunaci\u00f3n permiten reducir el n\u00famero de contagios, especialmente en pa\u00edses desarrollados como Estados Unidos y los de la Uni\u00f3n Europea, que est\u00e1n levantando restricciones.<\/p>\n<p>No obstante,<strong> en Espa\u00f1a<\/strong> m\u00e1s de 850 j\u00f3venes de ocho comunidades aut\u00f3nomas se contagiaron coronavirus durante recientes viajes de egresados a Mallorca.<\/p>\n<div class=\"image\" id=\"image\" readability=\"7\"> <img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/la-variante-delta-obliga-a-una-parte-del-mundo-a-aplicar-nuevas-restricciones-1.jpg\" alt=\"En Reino Unido sigue avanzando la campa\u00f1a de vacunaci\u00f3n\" title=\"En Reino Unido sigue avanzando la campa\u00f1a de vacunaci\u00f3n\"><\/p>\n<p>En Reino Unido sigue avanzando la campa\u00f1a de vacunaci\u00f3n<\/p>\n<\/div>\n<p><strong>La variante Delta del virus, que est\u00e1 presente en al menos 85 pa\u00edses, seg\u00fan la Organizaci\u00f3n Mundial de la Salud (OMS), <\/strong>y la renuencia a la vacunaci\u00f3n en algunos, amenazan esta mejor\u00eda.<\/p>\n<p>Por ejemplo, el gobierno de Palestina report\u00f3 la aparici\u00f3n en Cisjordania de los dos primeros casos de la cepa Delta en j\u00f3venes residentes en las ciudades de Kalkilia y Safit que hab\u00edan regresado de Emiratos \u00c1rabes Unidos en los \u00faltimos d\u00edas, seg\u00fan la agencia noticiosa estatal Wafa.<\/p>\n<p>Por su parte, <strong><a href=\"https:\/\/www.telam.com.ar\/notas\/202106\/559240-record-muertes-coronavirus-moscu.html\" target=\"_blank\" rel=\"noopener\">Mosc\u00fa vivi\u00f3 el d\u00eda m\u00e1s mort\u00edfero desde el comienzo de la pandemia<\/a>, con 144 muertes en las \u00faltimas 24 horas<\/strong>, como consecuencia de la expansi\u00f3n de la cepa Delta que se halla desde junio en Rusia, el sexto pa\u00eds con m\u00e1s muertes por la Covid-19 tras Estados Unidos, Brasil, India, M\u00e9xico y Per\u00fa.<\/p>\n<p>Los efectos de esta variante del virus, especialmente contagiosa entre personas no inmunizadas, hacen redoblar los esfuerzos de las autoridades rusas para convencer a sus esc\u00e9pticos ciudadanos de vacunarse.<\/p>\n<p><strong>\u00abPara frenar la pandemia se necesitan vacunaciones r\u00e1pidas y a gran escala. Nadie ha inventado otra soluci\u00f3n\u00bb, asegur\u00f3 el alcalde de Mosc\u00fa, Serguei Sobianin.<\/strong><\/p>\n<p>En paralelo, nuevos brotes de coronavirus golpean a pa\u00edses del sudeste asi\u00e1tico y Australia, que parec\u00eda haber dejado atr\u00e1s la pandemia con su pol\u00edtica de cierre de fronteras y m\u00e1xima prevenci\u00f3n ante el virus.<\/p>\n<p><strong><a href=\"https:\/\/www.telam.com.ar\/notas\/202106\/559225-nuevos-casos-coronavirus-sydney-cierre-total.html\" target=\"_blank\" rel=\"noopener\">M\u00e1s de cinco millones de residentes de S\u00eddney empezaron dos semanas de estricto confinamiento<\/a><\/strong>, con cierre de restaurantes y bares, tras la detecci\u00f3n de m\u00e1s de 110 casos de Covid-19 vinculados a la tripulaci\u00f3n de un vuelo internacional.<\/p>\n<div class=\"image\" id=\"image\" readability=\"7\"> <img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/la-variante-delta-obliga-a-una-parte-del-mundo-a-aplicar-nuevas-restricciones-2.jpg\" alt=\"Brasil sigue estando entre los m\u00e1s afectados por el Covid-19\" title=\"Brasil sigue estando entre los m\u00e1s afectados por el Covid-19\"><\/p>\n<p>Brasil sigue estando entre los m\u00e1s afectados por el Covid-19<\/p>\n<\/div>\n<p>Medidas similares se tomaron en pa\u00edses del sudeste asi\u00e1tico, como Tailandia, que reinstaurar\u00e1 ma\u00f1ana restricciones en los sectores gastron\u00f3mico y de la construcci\u00f3n, y reducir\u00e1 las reuniones sociales en Bangkok, mientras Malasia anunci\u00f3 la pr\u00f3rroga del confinamiento decretado hace un mes.<\/p>\n<p>En tanto, en <strong>Bangladesh comenzar\u00e1 el lunes un severo confinamiento<\/strong> para evitar \u00abuna situaci\u00f3n parecida a la de India\u00bb, seg\u00fan el vocero del Ministerio de Salud, Robed Amin citado por la agencia AFP.<\/p>\n<p><strong>En Indonesia<\/strong>, el pa\u00eds actualmente m\u00e1s afectado por la enfermedad, que registr\u00f3 un nuevo r\u00e9cord con m\u00e1s de 21.000 casos en un d\u00eda y donde los hospitales rozan una situaci\u00f3n l\u00edmite, se prev\u00e9 que el pico de contagios se experimente en dos semanas, seg\u00fan anticip\u00f3 la vocera del equipo de la lucha contra la Covid-19, Siti Nadia Tarmizi.<\/p>\n<p>Aun as\u00ed, la regi\u00f3n m\u00e1s afectada del mundo sigue siendo Am\u00e9rica latina y el Caribe.<\/p>\n<p><strong>Brasil, sede de la Copa Am\u00e9rica de f\u00fatbol, es el pa\u00eds con m\u00e1s muertes en las \u00faltimas 24 horas, con 1.593, seguido de India, con 1.258, y Colombia, con 693.<\/strong><\/p>\n<p>En el gigante sudamericano, los estadios donde juegan estrellas como Lionel Messi y Neymar sirvieron antes como hospitales de campa\u00f1a para tratar de absorber la marea de pacientes con Covid-19.<\/p>\n<p>Toda estrategia sirve ante el virus, incluso afinar el olfato de los perros para detectar precozmente la infecci\u00f3n, como hacen en Ecuador.<\/p>\n<p>En el hospital Pablo Arturo Su\u00e1rez de Quito, bomberos franceses adiestran a 15 perros, expertos en localizaci\u00f3n de personas, explosivos y drogas, y gu\u00edas humanos para rastrear bolas de algod\u00f3n impregnadas del sudor de contagiados de Covid-19.<\/p>\n<p>\u00abEl objetivo es que puedan reconocer la presencia de la Covid-19 sobre todo en pacientes asintom\u00e1ticos y en sitios de concentraci\u00f3n masiva\u00bb, explic\u00f3 Denis Maigua, del Servicio de Gesti\u00f3n de Riesgos de Ecuador. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La OMS viene advirtiendo a los paises sobre tomar m\u00e1s recaudos contra esta variante El Reino Unido inform\u00f3 este domingo18.270 casos de la Covid-19 en las \u00faltimas 24 horas y 23 decesos, casi el doble que el d\u00eda anterior, en medio de un nuevo repunte por la aparici\u00f3n de la variante Delta, que golpea a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6361,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/6360"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=6360"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/6360\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/6361"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=6360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=6360"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=6360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}