{"id":6442,"date":"2021-06-30T06:57:22","date_gmt":"2021-06-30T06:57:22","guid":{"rendered":"http:\/\/nuevacordoba.net\/index.php\/2021\/06\/30\/un-viaje-por-el-tiempo-al-pekin-de-1963-y-la-revolucion-cultural\/"},"modified":"2021-06-30T06:57:22","modified_gmt":"2021-06-30T06:57:22","slug":"un-viaje-por-el-tiempo-al-pekin-de-1963-y-la-revolucion-cultural","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/06\/30\/un-viaje-por-el-tiempo-al-pekin-de-1963-y-la-revolucion-cultural\/","title":{"rendered":"Un viaje por el tiempo, al Pek\u00edn de 1963 y la Revoluci\u00f3n Cultural"},"content":{"rendered":"<div class=\"image\" id=\"image\" readability=\"8\"> <img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/un-viaje-por-el-tiempo-al-pekin-de-1963-y-la-revolucion-cultural.jpg\" alt=\"Doudchizky en su estudio de Congreso, ahora prepara un documental sobre transplantes\" title=\"Doudchizky en su estudio de Congreso, ahora prepara un documental sobre transplantes\"><\/p>\n<p>Doudchizky en su estudio de Congreso, ahora prepara un documental sobre transplantes<\/p>\n<\/div>\n<p>En su documental <strong>\u00abEl Hotel de la Amistad\u00bb<\/strong>, el cineasta <strong>Pablo Doudchitzky,<\/strong> intenta y logra recuperar una de esas historias que los adultos recuerdan de sus infancias seguramente desafiando la traici\u00f3n de la memoria.<\/p>\n<p>Doudchitzky retrocede m\u00e1s de medio siglo, <strong>cuando en 1963 y siendo un ni\u00f1o del preescolar, viaj\u00f3 con sus padres militantes del Partido Comunista, rumbo a la China conducida por Mao Tse-Tung<\/strong>, en el amanecer de la que se conoci\u00f3 como Revoluci\u00f3n Cultural.<\/p>\n<div class=\"image\" id=\"image\" readability=\"8\"> <img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/un-viaje-por-el-tiempo-al-pekin-de-1963-y-la-revolucion-cultural-1.jpg\" alt=\"&quot;Como no contar esa historia...! Es muy cinematogr\u00e1fica e interesante&quot;, dice Doudchizky\" title=\"&quot;Como no contar esa historia...! Es muy cinematogr\u00e1fica e interesante&quot;, dice Doudchizky\"><\/p>\n<p>\u00abComo no contar esa historia&#8230;! Es muy cinematogr\u00e1fica e interesante\u00bb, dice Doudchizky<\/p>\n<\/div>\n<p>Su padre, tambi\u00e9n Pablo, cansado de la burocracia que ve\u00eda en la c\u00fapula del su grupo pol\u00edtico en el R\u00edo de la Plata, march\u00f3 con rumbo a Pekin, donde fueron alojados en el conocido como <strong>Hotel de la Amistad.<\/strong><\/p>\n<p>Tanto Pablo hijo como su hermano comenzaron su escolaridad, momentos particularmente complicados, y pol\u00e9micos tambi\u00e9n para los mismos intelectuales que impulsaron al l\u00edder popular vuelto al poder luego de la crisis del llamado Gran Salto Adelante, y de la irrupci\u00f3n del famoso Libro Rojo, en medio de aguas turbulentas, esas mismas que que pusieron en jaque a la cultura (y a muchos de sus protagonistas) que proclamaba la revoluci\u00f3n de 1966.<\/p>\n<p><strong>Doudchitzky intenta aproximarse a ese mundo tan afectado por el paso del tiempo como las fotograf\u00edas en papel y sus negativos<\/strong> y lo hace recurriendo a protagonistas de aquel episodio clave de la historia china y del mismo PC que lo ayudan a recuperar las caras de aquellos retratos que trata de identificar y poner en el lugar correcto de ese inmenso puzzle.<\/p>\n<p>Doudchizky termina su relato recordando una frase que los chinos suelen dedicar a sus enemigos: \u00abOjal\u00e1 te toquen vivir tiempos interesantes\u00bb, mientras que como fondo de im\u00e1genes muy coloridas y danzadas se escucha aquel himno que insiste una y otra vez que \u00abEl Partido Comunista es como el sol&#8230; Sale por el Este y es rojo\u00bb.<\/p>\n<p>Su pel\u00edcula, que luego de su estreno recibi\u00f3 aplausos y tuvo recorrido festivalero, se puede ver en YouTube y en pocos d\u00edas se repondr\u00e1 en la pantalla de la plataforma Cine.ar.<\/p>\n<p><strong>-Pablo, es dif\u00edcil tener recuerdos muy confiables de entre los 4 y los 9 a\u00f1os, porque la memoria es traidora. Con esa perspectiva \u00bfqu\u00e9 record\u00e1s de aquella China camino a la Revoluci\u00f3n Cultural?<\/strong><\/p>\n<p>-Despu\u00e9s de tantos a\u00f1os se mezclan algunos recuerdos con algunas cr\u00f3nicas y cosas y contaba mi viejo que me sucedieron, parte del anecdotario familiar pero tengo muy frescas algunas im\u00e1genes, la ma\u00f1ana de invierno camino de la escuela que queda enfrente del Hotel de la Amistad, con ni\u00f1os pobres que van a una escuela pobre con piso de tierra.<\/p>\n<p>Cerca del hotel hab\u00eda gente que ten\u00eda huertas. En esa escuela aprend\u00ed a hablar chino y tambi\u00e9n conoc\u00ed a chinos que me miraban como un extraterrestre. Recuerdo los recreos, yo como un soldado norteamericano y ellos como valientes vietnamitas antiimperialistas. Yo me la pasaba en el piso muerto una y otra vez por los resistentes vietnamitas. Tambi\u00e9n recuerdo que hac\u00eda mucho fr\u00edo&#8230; Cada tanto, con pap\u00e1 \u00edbamos al zool\u00f3gico y mientras nosotros mir\u00e1bamos con curiosidad a los animales los chicos nos miraban a nosotros y nos llamaban \u00abthapizaa\u00bb es decir narices largas. En esa \u00e9poca a\u00fan era muy poco habitual ver un occidental.<\/p>\n<p> <iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/lKkmCgN_ZAk?wmode=transparent&amp;showinfo=0&amp;autohide=1&amp;rel=0\" frameborder=\"0\" allowfullscreen>[embedded content]<\/iframe> <\/p>\n<p>Trailer \u00abHotel de la amistad\u00bb<\/p>\n<p><strong>-\u00bfQu\u00e9 an\u00e9cdota o an\u00e9cdotas respecto a la singularidad del lugar y del momento pol\u00edtico pod\u00e9s destacar como m\u00e1s significativas?<\/strong><\/p>\n<p>-Todav\u00eda se trataba de un pa\u00eds muy pobre que reci\u00e9n pasaba del feudalismo al comunismo, porque ni siquiera pas\u00f3 por la etapa del capitalismo. En verdad la Revoluci\u00f3n Cultural fue un proceso que se fue dando dentro del Partido Comunista Chino. Mao hab\u00eda perdido poder por ciertas consignas que hab\u00eda lanzado para la industrializaci\u00f3n del pa\u00eds, el \u00abgran salto adelante\u00bb, qu\u00e9 gener\u00f3 una hambruna tremenda, y un poco para recuperar la m\u00edstica y su espacio, organiz\u00f3 con los j\u00f3venes lo que fue los Guardias Rojos, que se transform\u00f3 en una fuerza violenta y fan\u00e1tica y por cierto peligrosa, que muchos a\u00f1os despu\u00e9s, y entre ellos la esposa del mismo Mao, fueron juzgados como la banda de Los cuatro, una revision un poco la revoluci\u00f3n cultural, pero sin demasiado compromiso porque hay l\u00edderes del PC involucrados en ese episodio.<\/p>\n<p><strong>-\u00bfC\u00f3mo naci\u00f3 la idea del documental?<\/strong><\/p>\n<p>-C\u00f3mo no contar esa historia&#8230;! Primero que es muy cinematogr\u00e1fica y m\u00e1s all\u00e1 de eso es muy interesante; ten\u00eda mucha documentaci\u00f3n y en mi trabajo como cineasta siempre cuento episodios de mi vida porque es de lo que uno m\u00e1s sabe. Ahora estoy haciendo una pel\u00edcula sobre mi trasplante, porque soy trasplantado hep\u00e1tico y sobre otros casos similares, algo que me parece interesante contar y tambi\u00e9n acerca de la donaci\u00f3n de \u00f3rganos.<\/p>\n<div class=\"image\" id=\"image\" readability=\"7\"> <img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/un-viaje-por-el-tiempo-al-pekin-de-1963-y-la-revolucion-cultural-2.jpg\" alt=\"El autor de &quot;El Hotel de la Amistad&quot;.\" title=\"El autor de &quot;El Hotel de la Amistad&quot;.\"><\/p>\n<p>El autor de \u00abEl Hotel de la Amistad\u00bb.<\/p>\n<\/div>\n<p><strong>-\u00bfQu\u00e9 diferencias buenas o malas descubriste al reencontrarte con ese lugar medio siglo despu\u00e9s? \u00bfQu\u00e9 es lo que realmente fue que permiti\u00f3 pegar el postergado salto hacia adelante?<\/strong><\/p>\n<p>-La China de hoy no tiene nada que ver con la que yo conoc\u00ed. Hoy va camino a ser una superpotencia. Salieron de la pobreza y se sumergieron en un sistema capitalista b\u00e1sico, una gran sociedad de consumo: todos los chinos est\u00e1n endeudados, tienen toda clase de aparatos y tecnolog\u00eda, trabajan 16 horas d\u00eda y viven alienados, corriendo de aqu\u00ed para all\u00e1 en un aparente confort que no ten\u00edan. Ahora los edificios tienen ascensores y los subterr\u00e1neos son los m\u00e1s modernos del mundo.<\/p>\n<p>La situaci\u00f3n de los chinos ha cambiado radicalmente. No hay que olvidar que antes de la revoluci\u00f3n se mor\u00edan de a millones por hambre. No hay m\u00e1s hambre, pero hay un poco de alienaci\u00f3n y p\u00e9rdida de cierta perspectiva que le hab\u00eda dado el socialismo, sobre todo en lo que tiene que ver con los lazos solidarios entre los ciudadanos y otras cosas importantes que deber\u00edamos reivindicar. En el Hotel de la Amistad nosotros est\u00e1bamos muy cuidados. All\u00ed viv\u00edamos casi todos los extranjeros que fueron a trabajar a Pekin; \u00e9ramos tratados con muchos privilegios, muy delicadamente y pagaban buenos sueldos. No hab\u00eda queja ninguna y todo lo que necesit\u00e1bamos lo ten\u00edamos. Ese per\u00edodo de cuatro a\u00f1os fue de mucho bienestar para m\u00ed y mi familia, y nosotros and\u00e1bamos por ah\u00ed, correteando con ni\u00f1os de otras nacionalidades.<\/p>\n<div class=\"image\" id=\"image\" readability=\"8\"> <img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/06\/un-viaje-por-el-tiempo-al-pekin-de-1963-y-la-revolucion-cultural-3.jpg\" alt=\"&quot;En China viv\u00ed una experiencia \u00fanica&quot;, afirma el cineasta.\" title=\"&quot;En China viv\u00ed una experiencia \u00fanica&quot;, afirma el cineasta.\"><\/p>\n<p>\u00abEn China viv\u00ed una experiencia \u00fanica\u00bb, afirma el cineasta.<\/p>\n<\/div>\n<p><strong>-Cuando tomaste conciencia del significado pol\u00edtico de aquella experiencia&#8230; \u00bfqu\u00e9 reflexi\u00f3n hiciste?<\/strong><\/p>\n<p>-La toma de conciencia de eso se fue dando a trav\u00e9s de los a\u00f1os. La verdad que viv\u00ed una experiencia \u00fanica. Yo no puedo llamarme comunista porque el comunismo desde alg\u00fan punto defraud\u00f3 muchas expectativas. Sin embargo para China marco una evoluci\u00f3n y una democratizaci\u00f3n, aunque se trate de un partido autoritario qu\u00e9 bas\u00f3 toda su construcci\u00f3n en el endiosamiento de la figura de Mao, con una rigidez como la que alguna vez propuso Lenin en esa idea de la \u00abdictadura del proletariado\u00bb. Mi reflexi\u00f3n es haber vivido un momento de la historia muy impresionante.<\/p>\n<p><strong>-\u00bfQu\u00e9 pas\u00f3 cu\u00e1ndo tu pap\u00e1 -que era docente- vio claramente qu\u00e9 pasaba con el \u00e1mbito al que pertenec\u00eda en esa coyuntura?<\/strong><\/p>\n<p>-Mi padre era hijo de comunistas bolcheviques rusos y \u00e9l fue comunista toda su infancia. A su edad adulta, fue expulsado de la Universidad de Buenos Aires por agitador comunista y se le prohibi\u00f3 el ingreso a cualquier centro de estudios nacional por lo que tuvo que irse a vivir al Uruguay donde sigui\u00f3 militando. Cuando Stalin y Mao rompen, \u00e9l y un grupo de amigos optan por el mao\u00edsmo y se vinculan con la embajada china. A ra\u00edz de eso son invitados a participar all\u00e1 de una nueva carrera de lenguas extranjeras , porque se pensaba que en alg\u00fan momento se deber\u00edan integrar al mundo y se quer\u00edan empezar a preparar. Los tiempos de los chinos son muy distintos a los nuestros: ellos piensan 50 a\u00f1os adelante, y aquello que planearon entonces lo estamos viendo en la actualidad.<\/p>\n<p> <iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/Kx3pE4pfCXY?wmode=transparent&amp;showinfo=0&amp;autohide=1&amp;rel=0\" frameborder=\"0\" allowfullscreen>[embedded content]<\/iframe> <\/p>\n<p>Documental \u00abHotel de la amistad\u00bb<\/p>\n<p><strong>-\u00bfC\u00f3mo naci\u00f3 tu idea de viajar nuevamente y encontrarte con algunos de los supervivientes de aquella experiencia?<\/strong><\/p>\n<p>-He quedado vinculado con algunos que vivieron la experiencia del comunismo, amigos colombianos y brasile\u00f1os, suecos chilenos, muchos uruguayos, y tenemos un sitio en com\u00fan donde a veces comentamos historias, sin embargo el v\u00ednculo que tengo con Sergio Cabrera -y con su hermana Mar\u00edanella-, un cineasta colombiano muy interesante, autor de \u00abLa estrategia del caracol\u00bb es mucho m\u00e1s importante.<\/p>\n<p><strong>-M\u00e1s all\u00e1 de este festejo redondo, el de los 100 a\u00f1os del Partido Comunista Chino, y a pesar de la distancia, \u00bfcu\u00e1l pens\u00e1s es el rol que China hoy ocupa en el mundo?<\/strong><\/p>\n<p>-Insisto, para los chinos 100 a\u00f1os no es nada. Seg\u00fan los criterios de sus tiempos, es un partido que reci\u00e9n se est\u00e1 fundando. Nada que ver con lo que era China antes de la revoluci\u00f3n. Y va a seguir creciendo, y va a terminar siendo una potencia mundial. Espero que sea una potencia justa, que de alg\u00fan modo le sea \u00fatil a la humanidad. Es inevitable que eso suceda: estamos en los albores de eso mismo, de una China potencia mundial y referente del futuro. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Doudchizky en su estudio de Congreso, ahora prepara un documental sobre transplantes En su documental \u00abEl Hotel de la Amistad\u00bb, el cineasta Pablo Doudchitzky, intenta y logra recuperar una de esas historias que los adultos recuerdan de sus infancias seguramente desafiando la traici\u00f3n de la memoria. Doudchitzky retrocede m\u00e1s de medio siglo, cuando en 1963 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6443,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/6442"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=6442"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/6442\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/6443"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=6442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=6442"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=6442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}