{"id":7246,"date":"2021-07-20T03:29:55","date_gmt":"2021-07-20T03:29:55","guid":{"rendered":"http:\/\/nuevacordoba.net\/index.php\/2021\/07\/20\/preocupacion-internacional-por-espionaje-sobre-politicos-periodistas-y-activistas\/"},"modified":"2021-07-20T03:29:55","modified_gmt":"2021-07-20T03:29:55","slug":"preocupacion-internacional-por-espionaje-sobre-politicos-periodistas-y-activistas","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/07\/20\/preocupacion-internacional-por-espionaje-sobre-politicos-periodistas-y-activistas\/","title":{"rendered":"Preocupaci\u00f3n internacional por espionaje sobre pol\u00edticos, periodistas y activistas"},"content":{"rendered":"<div class=\"image\" id=\"image\" readability=\"8\"> <img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/preocupacion-internacional-por-espionaje-sobre-politicos-periodistas-y-activistas.jpg\" alt=\"El programa Pegasus de la empresa israel\u00ed NSO constituye un sistema muy sofisticado que explota las vulnerabilidades de los tel\u00e9fonos m\u00f3viles inteligentes \" title=\"El programa Pegasus de la empresa israel\u00ed NSO constituye un sistema muy sofisticado que explota las vulnerabilidades de los tel\u00e9fonos m\u00f3viles inteligentes \"><\/p>\n<p>El programa Pegasus de la empresa israel\u00ed NSO constituye un sistema muy sofisticado que explota las vulnerabilidades de los tel\u00e9fonos m\u00f3viles inteligentes <\/p>\n<\/div>\n<p>La difusi\u00f3n de que casi 200 periodistas, 600 dirigentes y militantes de derechos humanos y empresarios fueron espiados a trav\u00e9s del programa inform\u00e1tico Pegasus, de una empresa israel\u00ed, gener\u00f3 indignaci\u00f3n en varios gobiernos, sorpresa en otros, y el rechazo a cualquier vinculaci\u00f3n con ese espionaje de parte de varios Ejecutivos se\u00f1alados como relacionados con el esc\u00e1ndalo, revelado por un consorcio de medios de investigaci\u00f3n.<\/p>\n<p><strong>Instalado en un tel\u00e9fono m\u00f3vil, el programa permite recuperar mensajes de texto, fotograf\u00edas, contactos y hasta escuchar conversaciones de su propietario, y la investigaci\u00f3n period\u00edstica publicada por 17 medios <\/strong>de todo el mundo detect\u00f3 50.000 n\u00fameros seleccionados por clientes de la empresa israel\u00ed NSO, desde 2016.<\/p>\n<p>El trabajo est\u00e1 basado en una lista que lograron el colectivo de periodistas France Forbidden Stories (Historias prohibidas) y Amnist\u00eda Internacional.<\/p>\n<p><strong>La n\u00f3mina incluye los n\u00fameros de 180 periodistas, 600 pol\u00edticos, 85 defensores de los derechos humanos y 65 empresarios,<\/strong> seg\u00fan la investigaci\u00f3n del diario franc\u00e9s Le Monde, el brit\u00e1nico The Guardian, el estadounidense The Washington Post y los medios mexicanos Proceso y Aristegui Noticias, entre otros.<\/p>\n<p>Estos medios localizaron buena parte de los n\u00fameros espiados en Marruecos, Arabia Saudita y M\u00e9xico.<\/p>\n<p><strong>\u00abNo hablamos solo de algunos Estados delincuentes, sino del uso masivo de un programa de espionaje por al menos 10 pa\u00edses\u00bb,<\/strong> explic\u00f3 la secretaria general de Amnist\u00eda Internacional, Agn\u00e8s Callamard, en declaraciones a la BBC.<\/p>\n<p>La presidenta de la Comisi\u00f3n Europea, <strong>Ursula von der Leyen, afirm\u00f3 que resulta \u201ccompletamente inaceptable\u201d ese espionaje<\/strong>, m\u00e1s all\u00e1 de que aclar\u00f3 que la cuesti\u00f3n \u201ca\u00fan tiene que comprobarse\u201d.<\/p>\n<p>De visita en Praga, Von der Leyen denunci\u00f3 en particular el presunto espionaje contra periodistas. \u00abLa libertad de prensa es uno de los valores fundamentales de la Uni\u00f3n Europea\u00bb, remarc\u00f3, tras reunirse con el primer ministro checo Andrej Babi.<\/p>\n<p>A su turno, la Alta Comisionada de Naciones Unidas para los Derechos Humanos, la expresidenta chilena <strong>Michelle Bachelet, afirm\u00f3 que si las revelaciones sobre el espionaje a trav\u00e9s del software Pegasus son ciertas, se habr\u00e1 superado una \u00abl\u00ednea roja\u00bb<\/strong>.<\/p>\n<div class=\"image\" id=\"image\" readability=\"7\"> <img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/preocupacion-internacional-por-espionaje-sobre-politicos-periodistas-y-activistas-1.jpg\" alt=\"Unos 10 gobiernos son sindicados de haber usado Pegasus\" title=\"Unos 10 gobiernos son sindicados de haber usado Pegasus\"><\/p>\n<p>Unos 10 gobiernos son sindicados de haber usado Pegasus<\/p>\n<\/div>\n<p><br open> \u00abMe gustar\u00eda recordar a todos los Estados que las medidas de vigilancia solo pueden justificarse en circunstancias bien definidas, con un objetivo leg\u00edtimo, y deben ser tanto necesarios como proporcionales a ese objetivo\u00bb, afirm\u00f3 Bachelet en un comunicado.<\/p>\n<p>La funcionaria de la ONU advirti\u00f3 que \u201csi las recientes acusaciones sobre el uso de Pegasus tambi\u00e9n son ciertas solo en parte, entonces esa l\u00ednea roja fue superada una y otra vez con total impunidad\u00bb.<\/p>\n<p>Tambi\u00e9n <strong>Francia elev\u00f3 su queja<\/strong>, a trav\u00e9s del vocero del Gobierno, Gabriel Attal, que juzg\u00f3 que \u00abse trata de unos hechos muy chocantes, que, si se comprueba que son ciertos, resultan extremamente graves\u00bb.<\/p>\n<p><strong>El gobierno de Israel asegur\u00f3 esta tarde que \u201cno tiene acceso a la informaci\u00f3n recopilada por los clientes del grupo NSO\u201d y que \u00fanicamente permite la exportaci\u00f3n de productos de seguridad inform\u00e1tica \u201ca gobierno y solo para fines legales, para evitar e investigar delitos y combatir el terrorismo\u201d.<\/strong><\/p>\n<p>Subray\u00f3 en un comunicado del Ministerio de Defensa que cada una de esas ventas \u201cdepende del compromiso sobre el uso final del pa\u00eds comprador, que debe cumplir esas condiciones\u201d.<\/p>\n<p>No obstante, <strong>\u201csi se demuestra que se utilizaron de forma contraria a las condiciones de la licencia o incumpliendo las declaraciones de los pa\u00edses compradores, tomaremos las medidas apropiadas\u201d<\/strong>, prometi\u00f3 la nota.<\/p>\n<p><strong>La firma NSO, creada en 2011, fue acusada con alguna insistencia de colaborar con reg\u00edmenes autoritarios<\/strong>, sobre todo desde que en 2016 Ahmed Mansoor, un opositor de Emiratos \u00c1rabes Unidos, denunci\u00f3 estas pr\u00e1cticas, pero la empresa rechaz\u00f3 las versiones, que atribuy\u00f3 a \u201csuposiciones err\u00f3neas y teor\u00edas no corroboradas\u00bb.<\/p>\n<p>El sitio digital franc\u00e9s Mediapart y el semanario de investigaci\u00f3n Le Canard Encha\u00een\u00e9 presentaron una denuncia en Par\u00eds, despu\u00e9s de que se conociera que varios de sus periodistas fueron espiados por los servicios secretos marroqu\u00edes a trav\u00e9s de Pegasus.<\/p>\n<p>Tambi\u00e9n integran esta lista corresponsales de grandes medios internacionales, como The Wall Street Journal, CNN, France 24, El Pa\u00eds y la agencia AFP.<\/p>\n<p>Otros n\u00fameros pertenec\u00edan a mujeres del entorno del periodista saudita Jamal Khashoggi, asesinado en 2018 en el consulado de su pa\u00eds en Estambul por un comando formado por agentes venidos de Arabia Saudita.<\/p>\n<p><strong>Tambi\u00e9n familiares y colaboradores del presidente de M\u00e9xico, Andr\u00e9s L\u00f3pez Obrador, habr\u00edan sido espiados telef\u00f3nicamente entre 2016 y 2017<\/strong>, cuando el ahora mandatario era el l\u00edder de la oposici\u00f3n a Enrique Pe\u00f1a Nieto (2012-18).<\/p>\n<p>Entre las personas cuyos tel\u00e9fonos fueron intervenidos figuran Beatriz Guti\u00e9rrez, esposa de L\u00f3pez Obrador, hijos, hermanos y hasta el cardi\u00f3logo del gobernante de centroizquierda.<\/p>\n<p>Tambi\u00e9n fueron espiados la alcaldesa de la Ciudad de M\u00e9xico, Claudia Sheinbaum, ministros y otros funcionarios del actual gobierno.<\/p>\n<p><strong>El espionaje en M\u00e9xico tambi\u00e9n tuvo como blanco a por lo menos 25 periodista<\/strong>s, uno de los cuales, Cecilio Pineda, fue asesinado en marzo de 2017 tras denunciar supuestos v\u00ednculos entre pol\u00edticos y criminales en el estado sure\u00f1o de Guerrero, de acuerdo con el consorcio de medios.<\/p>\n<p>En la lista tambi\u00e9n aparecen n\u00fameros de pol\u00edticos, entre ellos dos jefes de gobierno europeos, cuyos nombres se anunciar\u00e1n en los pr\u00f3ximos d\u00edas, seg\u00fan los periodistas que revelaron el caso, adelant\u00f3 AFP.<\/p>\n<p>Mientras, <strong>el Gobierno de Hungr\u00eda neg\u00f3 el uso por parte de sus servicios secretos del software de NSO, y afirm\u00f3 que act\u00faa \u201cconforme a la ley\u201d.<\/strong><\/p>\n<p>\u00abEl director general [de los servicios secretos] me inform\u00f3 que no se estableci\u00f3 ninguna cooperaci\u00f3n con los servicios de inteligencia israel\u00edes\u00bb, asegur\u00f3 el ministro de Relaciones Exteriores h\u00fangaro, Peter Szijjarto, en una conferencia.<\/p>\n<p><strong>Tambi\u00e9n Marruecos, uno de los pa\u00edses que presuntamente m\u00e1s utiliz\u00f3 Pegasus<\/strong> seg\u00fan la investigaci\u00f3n, neg\u00f3 categ\u00f3ricamente el uso por parte de sus servicios de seguridad del software israel\u00ed, y calific\u00f3 de \u201cfalsas\u00bb estas informaciones.<\/p>\n<p><strong>El programa Pegasus de la empresa israel\u00ed NSO constituye un sistema muy sofisticado que explota las vulnerabilidades de los tel\u00e9fonos m\u00f3viles inteligentes y, una vez que el aparato, exporta los datos del usuario <\/strong>(correos electr\u00f3nicos, mensajer\u00eda, fotograf\u00edas) hacia p\u00e1ginas de internet creadas por la empresa, que se renuevan constantemente para evitar ser detectadas.<\/p>\n<p>La investigaci\u00f3n se hizo en base a m\u00f3viles Apple, porque es muy dif\u00edcil encontrar pruebas de este espionaje en los tel\u00e9fonos Android.<\/p>\n<p>Si antes se necesitaba que el usuario cliqueara en un enlace para piratear el tel\u00e9fono, ahora ya ni siquiera hace falta ese paso. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El programa Pegasus de la empresa israel\u00ed NSO constituye un sistema muy sofisticado que explota las vulnerabilidades de los tel\u00e9fonos m\u00f3viles inteligentes La difusi\u00f3n de que casi 200 periodistas, 600 dirigentes y militantes de derechos humanos y empresarios fueron espiados a trav\u00e9s del programa inform\u00e1tico Pegasus, de una empresa israel\u00ed, gener\u00f3 indignaci\u00f3n en varios gobiernos, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7247,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/7246"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=7246"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/7246\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/7247"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=7246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=7246"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=7246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}