{"id":745,"date":"2021-02-07T23:29:46","date_gmt":"2021-02-07T23:29:46","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-ascenso\/belgrano-orfila-dt-mauro-obolo_0_9e-LVwQ7D.html"},"modified":"2021-02-07T23:29:46","modified_gmt":"2021-02-07T23:29:46","slug":"orfila-se-hizo-cargo-de-belgrano","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/02\/07\/orfila-se-hizo-cargo-de-belgrano\/","title":{"rendered":"Orfila se hizo cargo de Belgrano"},"content":{"rendered":"<div><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/02\/orfila-se-hizo-cargo-de-belgrano.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>La temporada pasada ya qued\u00f3 atr\u00e1s para Belgrano. Las pol\u00e9micas. Los gritos y las recriminaciones. Por eso,&nbsp;tras la salida compleja de Caruso Lombardi, la Comisi\u00f3n Directiva tuvo que salir a buscar entrenador. Y encontr\u00f3 uno que tiene mucha experiencia en el Ascenso: Alejandro Orfila. El uruguayo, que subi\u00f3 con Atlanta a la B Nacional, ven\u00eda de dirigir en su pa\u00eds natal a Defensor Sporting.<\/p>\n<p>Chano ya fue presentado ayer y avis\u00f3 que su equipo ir\u00e1 \u201ca cada pelota como si fuera la \u00faltima\u201d y que \u00abno va a regalar nada\u00bb. Los hinchas se ilusionan de cara a un dur\u00edsimo campeonato en la Primera Nacional. El sue\u00f1o: volver a lo m\u00e1s alto.&nbsp;Adem\u00e1s, Mauro \u00d3bolo ser\u00e1 parte del Directorio Deportivo del Pirata.<\/p>\n<div class=\"entry-tags\">\n<h2>TEMAS QUE APARECEN EN ESTA NOTA<\/h2>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La temporada pasada ya qued\u00f3 atr\u00e1s para Belgrano. Las pol\u00e9micas. Los gritos y las recriminaciones. Por eso,&nbsp;tras la salida compleja de Caruso Lombardi, la Comisi\u00f3n Directiva tuvo que salir a buscar entrenador. Y encontr\u00f3 uno que tiene mucha experiencia en el Ascenso: Alejandro Orfila. El uruguayo, que subi\u00f3 con Atlanta a la B Nacional, ven\u00eda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":746,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/745"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=745"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/745\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/746"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=745"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}