{"id":7566,"date":"2021-07-28T23:37:37","date_gmt":"2021-07-28T23:37:37","guid":{"rendered":"http:\/\/nuevacordoba.net\/index.php\/2021\/07\/28\/shakira-al-borde-de-juicio-por-fraude-fiscal-de-145-millones\/"},"modified":"2021-07-28T23:37:37","modified_gmt":"2021-07-28T23:37:37","slug":"shakira-al-borde-de-juicio-por-fraude-fiscal-de-145-millones","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/07\/28\/shakira-al-borde-de-juicio-por-fraude-fiscal-de-145-millones\/","title":{"rendered":"Shakira, al borde de juicio por fraude fiscal de 14,5 millones"},"content":{"rendered":"<div class=\"image\" id=\"image\" readability=\"7\"> <img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/shakira-al-borde-de-juicio-por-fraude-fiscal-de-145-millones.jpg\" alt=\"Shakira contra las cuerdas en Espa\u00f1a por temas impositivos\" title=\"Shakira contra las cuerdas en Espa\u00f1a por temas impositivos\"><\/p>\n<p>Shakira contra las cuerdas en Espa\u00f1a por temas impositivos<\/p>\n<\/div>\n<p>Un juez catal\u00e1n hall\u00f3 \u00abindicios suficientes\u00bb de que la artista colombiana <strong>Shakira<\/strong> defraud\u00f3 en <strong>14,5 millones de euros<\/strong> a Hacienda espa\u00f1ola simulando no residir en Espa\u00f1a y ocultando su renta mediante un entramado societario con sede en para\u00edsos fiscales,<strong> entre 2012 y 2014.<\/strong><\/p>\n<p>El titular del Juzgado de instrucci\u00f3n n\u00famero 2 de Barcelona consider\u00f3 que, pese a que las tesis de Hacienda y de la defensa son \u00abdiametralmente opuestas\u00bb en cuanto a la interpretaci\u00f3n tributaria a aplicar, <strong>hay \u00abindicios suficientes de criminalidad\u00bb<\/strong> para continuar con el procedimiento contra ella y que el caso se dirima en el juicio.<\/p>\n<p>El juez sostuvo que la cantante <strong>habr\u00eda dejado de tributar en Espa\u00f1a durante esos tres a\u00f1os \u00abpese a tener la obligaci\u00f3n de hacerlo por tener aqu\u00ed su residencia fiscal\u00bb.<\/strong><\/p>\n<p>Los peritos designados por la defensa de Shakira mantienen que la cantante dispon\u00eda de un certificado de residencia permanente en Bahamas y que, hasta 2015, su presencia en Espa\u00f1a no super\u00f3 los 183 d\u00edas anuales que la obligaban a tributar en este pa\u00eds.<\/p>\n<p>Adem\u00e1s, sostienen que los d\u00edas en que permaneci\u00f3 fuera de Espa\u00f1a -con motivo de sus giras de conciertos o su participaci\u00f3n en el \u201creality\u201d televisivo \u00abThe Voice\u00bb en Estados Unidos- no deben contabilizarse como tiempo de residencia en el pa\u00eds. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shakira contra las cuerdas en Espa\u00f1a por temas impositivos Un juez catal\u00e1n hall\u00f3 \u00abindicios suficientes\u00bb de que la artista colombiana Shakira defraud\u00f3 en 14,5 millones de euros a Hacienda espa\u00f1ola simulando no residir en Espa\u00f1a y ocultando su renta mediante un entramado societario con sede en para\u00edsos fiscales, entre 2012 y 2014. El titular del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7567,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/7566"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=7566"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/7566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/7567"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=7566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=7566"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=7566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}