{"id":7587,"date":"2021-07-29T04:38:55","date_gmt":"2021-07-29T04:38:55","guid":{"rendered":"https:\/\/www.bbc.com\/mundo\/noticias-america-latina-58004404"},"modified":"2021-07-29T04:38:55","modified_gmt":"2021-07-29T04:38:55","slug":"pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/07\/29\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru\/","title":{"rendered":"Pedro Castillo | \u201cEs la primera vez que el pa\u00eds ser\u00e1 gobernado por un campesino\u201d: los mensajes clave del discurso de investidura del nuevo presidente de Per\u00fa"},"content":{"rendered":"<div dir=\"ltr\" class=\"e1j2237y5 bbc-q4ibpr e57qer20\">\n<div class=\"bbc-1atl7vu e1c9i7u14\">\n<ul role=\"list\" class=\"bbc-cdrraw e1c9i7u12\">\n<li role=\"listitem\" class=\"bbc-1a3w4ok e1c9i7u11\">Redacci\u00f3n <\/li>\n<li role=\"listitem\" class=\"bbc-1p92jtu e1c9i7u10\">BBC News Mundo<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"e1j2237y6 bbc-q4ibpr e57qer20\"><time datetime=\"2021-07-28\" class=\"bbc-14xtggo e4zesg50\">28 julio 2021<\/time><\/p>\n<p><time datetime=\"2021-07-28\" class=\"bbc-14xtggo e4zesg50\">Actualizado 5 horas<\/time><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-172p16q e57qer20\">\n<div dir=\"ltr\" class=\"bbc-189y18v e57qer20\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-1k5hvrj e1whu0\"><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-6.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-7.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-8.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-9.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-10.jpg 800w\" alt=\"Pedro Castillo\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru.jpg\" width=\"976\" class=\"bbc-fat2bc e1enwo3v0\"><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv etq3yw90\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">EPA<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g e57qer20\" readability=\"6\"><figcaption dir=\"ltr\" class=\"bbc-1t9zlwf eede9f50\" readability=\"2\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Pie de foto, <\/span><\/p>\n<p>Pedro Castillo jurament\u00f3 con su tradicional sombrero.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\"><b>Vistiendo un traje azul oscuro bordado y su ya tradicional sombrero, Pedro Castillo lleg\u00f3 este mi\u00e9rcoles al Congreso de Per\u00fa para asumir la presidencia del pa\u00eds.<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"23\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abJuro por dios, por mi familia, por mis hermanos y hermanas, campesinos, ronderos, pescadores, docentes, profesionales, ni\u00f1os, j\u00f3venes y mujeres, que ejercer\u00e9 el cargo de presidente en el periodo constitucional 2021-2026. Juro por los pueblos del Per\u00fa, por un pa\u00eds sin corrupci\u00f3n y por una nueva constituci\u00f3n\u00bb, dijo Castillo al asumir el cargo, con la mano derecha sobre la Biblia. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Luego, la presidenta del Congreso, Mar\u00eda del Carmen Alva, le entreg\u00f3 la banda presidencial.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Minutos despu\u00e9s, Castillo dio su primer mensaje presidencial con su sombrero puesto.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abEste Gobierno ha llegado <b>para gobernar con el pueblo y para construir desde abajo<\/b>. Es la primera vez que nuestro pa\u00eds ser\u00e1 gobernado por un campesino. (&#8230;) Yo tambi\u00e9n soy hijo de este pa\u00eds fundado sobre el sudor de mis antepasados\u00bb, subray\u00f3 Castillo en presencia de sus ancianos padres que lo observaban desde las gradas del Congreso.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Fue un discurso largo y sobrio, plagado de reivindicaciones hist\u00f3ricas, promesas de mejoras sociales y propuestas de reforma econ\u00f3mica, pero sin exabruptos, amenazas ni rupturas radicales.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Aqu\u00ed te contamos algunos de los mensajes clave del discurso con el que arranca la era Castillo en Per\u00fa, que adem\u00e1s empez\u00f3 el mismo d\u00eda que Per\u00fa celebra el bicentenario de su independencia.<\/p>\n<\/div>\n<p><h2 id=\"1-Plan-de-cambiar-la-Constituci\u00f3n\" tabindex=\"-1\" class=\"bbc-l3e97o e14hemmw0\">1. Plan de cambiar la Constituci\u00f3n<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">La carta magna vigente en Per\u00fa fue promulgada en 1993, durante el gobierno de Alberto Fujimori, meses despu\u00e9s de que este mandatario disolviera el Congreso en el episodio conocido como el \u00abautogolpe\u00bb.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\"><b>Una de las principales propuestas de Pedro Castillo durante su campa\u00f1a presidencial fue cambiar esa <\/b><b>C<\/b><b>onstituci\u00f3n<\/b> y la ha vuelto a reiterar este mi\u00e9rcoles.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abUna de nuestras principales banderas pol\u00edticas, convertida ahora en bandera de la mayor\u00eda del pueblo, es la convocatoria de una Asamblea Constituyente\u00bb, dijo Castillo durante su primer mensaje a la naci\u00f3n.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-172p16q e57qer20\">\n<div dir=\"ltr\" class=\"bbc-189y18v e57qer20\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-1k5hvrj e1whu0\" readability=\"8\"><noscript><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-11.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-12.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-13.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-14.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-15.jpg 800w\" alt=\"Alberto Fujimori\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-1.jpg\" width=\"976\" class=\"bbc-fat2bc e1enwo3v0\"><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv etq3yw90\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g e57qer20\" readability=\"6.5\"><figcaption dir=\"ltr\" class=\"bbc-1t9zlwf eede9f50\" readability=\"3\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Pie de foto, <\/span><\/p>\n<p>La actual Constituci\u00f3n se promulg\u00f3 en 1993, durante el gobierno de Alberto Fujimori.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Pero la actual Constituci\u00f3n peruana no prev\u00e9 un mecanismo para convocar dicha asamblea, por lo que primero habr\u00eda que reformarla y aprobar esa reforma mediante un referendo. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abInsistiremos en esta propuesta pero siempre dentro del marco de la ley (&#8230;) Anuncio que presentaremos ante el Congreso, respetando escrupulosamente el proceso, un proyecto de ley para reformarla\u00bb, anunci\u00f3 Castillo. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Si prosperara la idea de reformar la Constituci\u00f3n para convocar a una Asamblea Constituyente, Castillo anunci\u00f3 que este \u00f3rgano deber\u00e1 ser <b>\u00abplurinacional, popular y con paridad de g\u00e9nero\u00bb<\/b>.<\/p>\n<\/div>\n<p><h2 id=\"2-Respeto-de-los-ahorros-y-la-propiedad-privada\" tabindex=\"-1\" class=\"bbc-l3e97o e14hemmw0\">2. Respeto de los ahorros y la propiedad privada<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Durante la campa\u00f1a presidencial, uno de los temores de los cr\u00edticos de Castillo -que postul\u00f3 por Per\u00fa Libre, un partido que se define como marxista leninista- era que no respetar\u00eda los ahorros ni la propiedad privada de los peruanos. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-172p16q e57qer20\">\n<div dir=\"ltr\" class=\"bbc-189y18v e57qer20\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-1k5hvrj e1whu0\" readability=\"8\"><noscript><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-16.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-17.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-18.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-19.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-20.jpg 800w\" alt=\"Pedro Castillo y Lilia Paredes, la primera dama\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-2.jpg\" width=\"976\" class=\"bbc-fat2bc e1enwo3v0\"><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv etq3yw90\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">En su mensaje de este mi\u00e9rcoles, Castillo se refiri\u00f3 al \u00abcuento de que queremos expropiar los ahorros\u00bb y dijo que es \u00abtotalmente falso\u00bb. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abNo haremos nada de eso. Queremos que la econom\u00eda mantenga orden y predictibilidad, que son la base de las inversi\u00f3n. La propiedad de las personas obtenida con esfuerzo est\u00e1 garantizada por la legalidad (&#8230;)\u00bb, dijo el nuevo presidente. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Tambi\u00e9n descart\u00f3 estatizar empresas y otras pol\u00edticas: \u00abNo pretendemos ni remotamente estatizar la econom\u00eda ni hacer una pol\u00edtica de control de cambios\u00bb, dijo.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Sin embargo, <b>manifest\u00f3 sus intenciones de realizar cambios al modelo econ\u00f3mico.<\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abLa pandemia visibiliz\u00f3 que las cr\u00edticas al modelo eran leg\u00edtimas y v\u00e1lidas. Hoy la poblaci\u00f3n pide cambios y no est\u00e1 dispuesta a renunciar. \u00bfEs cierto que esos cambios implican poner en riesgo los logros de las \u00faltimas d\u00e9cadas? No. S\u00ed es posible realizar estos cambios con responsabilidad y respetando la propiedad privada, pero poniendo por delante los intereses de la naci\u00f3n\u00bb, se\u00f1al\u00f3.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abQueremos que se acaben los abusos de los monopolios, de los consorcios que cobran sumas elevadas por servicios b\u00e1sicos como el gas y las medicinas\u00bb, dijo tambi\u00e9n.<\/p>\n<\/div>\n<p><h2 id=\"3-Cambio-de-la-sede-de-gobierno\" tabindex=\"-1\" class=\"bbc-l3e97o e14hemmw0\">3. Cambio de la sede de gobierno<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Castillo anunci\u00f3 que no cumplir\u00e1 sus funciones de presidente desde el Palacio de Gobierno, la sede donde tradicionalmente ha funcionado el Poder Ejecutivo durante la vida republicana de Per\u00fa, y que tambi\u00e9n aloj\u00f3 a los virreyes durante la colonia.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-172p16q e57qer20\">\n<div dir=\"ltr\" class=\"bbc-189y18v e57qer20\" readability=\"6.5\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-1k5hvrj e1whu0\" readability=\"8\"><noscript><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-21.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-22.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-23.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-24.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-25.jpg 800w\" alt=\"Palacio de Gobierno\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-3.jpg\" width=\"976\" class=\"bbc-fat2bc e1enwo3v0\"><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv etq3yw90\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g e57qer20\" readability=\"6.5\"><figcaption dir=\"ltr\" class=\"bbc-1t9zlwf eede9f50\" readability=\"3\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Pie de foto, <\/span><\/p>\n<p>Pedro Castillo dijo que no gobernar\u00e1 desde este lugar, la \u00abcasa de Pizarro\u00bb.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abNo gobernar\u00e9 desde la casa de Pizarro\u00bb, dijo el nuevo mandatario, en referencia al nombre con el que se suele designar al Palacio de Gobierno en Per\u00fa, en honor a Francisco Pizarro, el conquistador espa\u00f1ol.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abDebemos romper con los s\u00edmbolos coloniales. Cederemos este palacio al Ministerio de las Culturas para que sea usado como un museo\u00bb, agreg\u00f3 frente al rey Felipe VI de Espa\u00f1a, que estaba entre los invitados a la toma de mando.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abLos tres siglos en los que este territorio perteneci\u00f3 a la corona espa\u00f1ola le permitieron explotar los minerales que sostuvieron el desarrollo de Europa, en gran parte con la mano de obra de los abuelos de muchos de nosotros\u00bb, dijo tambi\u00e9n.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Hasta la tarde de este mi\u00e9rcoles, Castillo no hab\u00eda anunciado desde d\u00f3nde gobernar\u00eda.<\/p>\n<\/div>\n<p><h2 id=\"4-Expansi\u00f3n-de-las-rondas-campesinas\" tabindex=\"-1\" class=\"bbc-l3e97o e14hemmw0\">4. Expansi\u00f3n de las rondas campesinas<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"13\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Uno de los aspectos m\u00e1s conocidos de Castillo es su pasado como rondero, o miembro de las rondas campesinas, unas organizaciones comunales de defensa que funcionan en las regiones de Per\u00fa desde los a\u00f1os 70 y que se dedican a garantizar la seguridad, administrar justicia y resolver todo tipo de problemas en sus jurisdicciones.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">El gobernante habl\u00f3 este mi\u00e9rcoles de estos grupos, en relaci\u00f3n precisamente con la seguridad ciudadana, que es uno de los problemas que m\u00e1s preocupa a los peruanos.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abDebemos expandir el sistema de las rondas en Per\u00fa, que no es otra cosa que la poblaci\u00f3n organizada. Nos comprometemos a formarlas donde no existen y a incluirlas al sistema de seguridad ciudadana\u00bb, dijo Castillo.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-172p16q e57qer20\">\n<div dir=\"ltr\" class=\"bbc-189y18v e57qer20\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-1k5hvrj e1whu0\"><noscript><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-26.jpg 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-27.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-28.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-29.jpg 624w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-30.jpg 800w\" alt=\"Pedro Castillo y Felipe VI\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-4.jpg\" width=\"976\" class=\"bbc-fat2bc e1enwo3v0\"><\/noscript><\/p>\n<p role=\"text\" class=\"bbc-1s1cxbv etq3yw90\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">EPA<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-3edg7g e57qer20\" readability=\"7\"><figcaption dir=\"ltr\" class=\"bbc-1t9zlwf eede9f50\" readability=\"4\"><span class=\"bbc-1gnhmg2 e1yt7oin0\">Pie de foto, <\/span><\/p>\n<p>El rey de Espa\u00f1a, Felipe VI, estuvo entre los invitados a la toma de mando.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abAsignaremos un presupuesto para dotarlas de log\u00edstica necesaria. Asimismo, promoveremos su participaci\u00f3n en la fiscalizaci\u00f3n a las autoridades en la ejecuci\u00f3n de la inversi\u00f3n p\u00fablica en sus comunidades\u00bb, a\u00f1adi\u00f3.<\/p>\n<\/div>\n<p><h2 id=\"5-Expulsi\u00f3n-de-delincuentes\" tabindex=\"-1\" class=\"bbc-l3e97o e14hemmw0\">5. Expulsi\u00f3n de delincuentes<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Continuando con sus propuestas sobre seguridad ciudadana, Castillo dijo tambi\u00e9n que \u00ablos delincuentes extranjeros tendr\u00e1n <b>72 horas para salir del pa\u00eds<\/b>\u00ab, aunque no se refiri\u00f3 a ninguna nacionalidad espec\u00edfica.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">Durante su campa\u00f1a presidencial, ya hab\u00eda propuesto esta medida. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">En una entrevista con la cadena peruana Exitosa, en marzo, dijo: \u00abNo podemos seguir avanzando mientras no pechamos tambi\u00e9n al grave problema que existe hoy de la delincuencia\u00bb. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"12\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\">\u00abNosotros, el 28 de julio, asumiremos en el acto un decreto supremo d\u00e1ndole una tregua de 72 horas a ciudadanos que han venido de otros pa\u00edses que han venido a delinquir y faltarle el respeto a la familia\u00bb, anunci\u00f3 tambi\u00e9n en ese momento. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-1ka88fa e57qer20\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div dir=\"ltr\" class=\"bbc-172p16q e57qer20\">\n<div dir=\"ltr\" class=\"bbc-189y18v e57qer20\">\n<div data-e2e=\"image-placeholder\" class=\"bbc-uhmmqj e1whu0\"><noscript><img srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru.png 240w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-31.jpg 320w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-32.jpg 480w, http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-33.jpg 624w\" alt=\"line\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/07\/pedro-castillo-es-la-primera-vez-que-el-pais-sera-gobernado-por-un-campesino-los-mensajes-clave-del-discurso-de-investidura-del-nuevo-presidente-de-peru-5.jpg\" width=\"624\" class=\"bbc-fat2bc e1enwo3v0\"><\/noscript><\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"bbc-19j92fr e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"bbc-bm53ic e1cc2ql70\"><i class=\"bbc-h1y5j7 ewc4zcb0\">Ahora puedes recibir notificaciones de BBC Mundo. Descarga la nueva versi\u00f3n de nuestra app y act\u00edvalas para no perderte nuestro mejor contenido.<\/i><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n BBC News Mundo 28 julio 2021 Actualizado 5 horas Fuente de la imagen, EPA Pie de foto, Pedro Castillo jurament\u00f3 con su tradicional sombrero. Vistiendo un traje azul oscuro bordado y su ya tradicional sombrero, Pedro Castillo lleg\u00f3 este mi\u00e9rcoles al Congreso de Per\u00fa para asumir la presidencia del pa\u00eds. \u00abJuro por dios, por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7588,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/7587"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=7587"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/7587\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/7588"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=7587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=7587"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=7587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}