{"id":77431,"date":"2026-01-26T19:28:12","date_gmt":"2026-01-26T19:28:12","guid":{"rendered":"https:\/\/www.ole.com.ar\/autos\/franco-colapinto-pierre-gasly-alpine-formula-barcelona-test-jueguitos-futbol_0_trtuq9IXoL.html"},"modified":"2026-01-26T19:28:12","modified_gmt":"2026-01-26T19:28:12","slug":"video-franco-colapinto-y-pierre-gasly-a-puro-jueguito-con-la-n-5-antes-de-los-test-de-formula-1","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2026\/01\/26\/video-franco-colapinto-y-pierre-gasly-a-puro-jueguito-con-la-n-5-antes-de-los-test-de-formula-1\/","title":{"rendered":"Video: Franco Colapinto y Pierre Gasly a puro jueguito con la N\u00b0 5 antes de los test de F\u00f3rmula 1"},"content":{"rendered":"<p><span class=\"createDate\">26\/01\/2026 16:28hs.<\/span><time class=\"modificatedDate\" datetime=\"2026-01-26T16:35:41-03:00\"> Actualizado al 26\/01\/2026 16:35hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div id=\"element-body-0\" class=\"sc-136cd478-0 ekTCfV\" readability=\"33.887640449438\">\n<p><strong><a href=\"https:\/\/www.ole.com.ar\/tema\/franco-colapinto.html\" title=\"Franco Colapinto\" alt=\"Franco Colapinto\" class=\"slug\">Franco Colapinto<\/a> y <a href=\"https:\/\/www.ole.com.ar\/tema\/pierre-gasly.html\" title=\"Pierre Gasly\" alt=\"Pierre Gasly\" class=\"slug\">Pierre Gasly<\/a> se encuentran en Barcelona por los test de pretemporada, <\/strong>antes del inicio del torneo 2026 el 8 de marzo en Australia. Sin embargo, antes de acelerar, el hincha de <a href=\"https:\/\/www.ole.com.ar\/tema\/boca-juniors.html\" title=\"Boca Juniors\" alt=\"Boca Juniors\" class=\"slug\">Boca<\/a> y su compa\u00f1ero, seguidor del <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/psg.html\" title=\"PSG\" alt=\"PSG\" class=\"slug\">PSG<\/a>, se entretuvieron con la redonda.<\/strong><\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-1\"><img alt=\"Franco Colapinto, Flavio Briatore y Pierre Gasly posaron en el escenario con el nuevo Alpine durante la presentaci\u00f3n oficial de la temporada. (AFP)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2026\/01\/video-franco-colapinto-y-pierre-gasly-a-puro-jueguito-con-la-n-5-antes-de-los-test-de-formula-1.jpg\"><span class=\"epigraphe\">Franco Colapinto, Flavio Briatore y Pierre Gasly posaron en el escenario con el nuevo Alpine durante la presentaci\u00f3n oficial de la temporada. (AFP)<\/span><\/div>\n<div id=\"element-body-2\" class=\"sc-136cd478-0 ekTCfV\" readability=\"38\">\n<p><strong>Entre las actividades se destac\u00f3 una sesi\u00f3n de fotos, y la casualidad quiso que hubiera una pelota de f\u00fatbol dando vueltas.<\/strong> Ambos pilotos ya hab\u00edan confesado su pasi\u00f3n por este deporte e incluso protagonizaron chicanas p\u00fablicas en las redes de Alpine, con <strong>Franco cargando a Pierre por la \u00faltima final del Mundial.<\/strong> As\u00ed, no les qued\u00f3 otra opci\u00f3n que ponerse a jugar.<\/p>\n<\/div>\n<div id=\"element-body-3\" class=\"sc-136cd478-0 ekTCfV\" readability=\"37\">\n<p>En las im\u00e1genes se los ve a los dos pilotos con la ropa del 2026 frente a un fondo con los colores caracter\u00edsticos del equipo franc\u00e9s: azul, rosa y blanco. En el video, <strong>Colapinto y Gasly se pasan la pelota sin que toque el piso, haciendo jueguitos con total naturalidad.<\/strong><\/p>\n<\/div>\n<p><h2>\u00a1Mir\u00e1 el video!<\/h2>\n<\/p>\n<div id=\"element-body-5\" class=\"sc-3c5a76cc-1 idjLTd\">\n<div class=\"JWvideoNota_title\">\n<p>@CarburandoTV<\/p>\n<\/div>\n<\/div>\n<p><h2>As\u00ed fue el primer d\u00eda de Franco Colapinto en los test de Barcelona <\/h2>\n<\/p>\n<div id=\"element-body-7\" class=\"sc-136cd478-0 ekTCfV\" readability=\"33.745019920319\">\n<p>Este lunes comenz\u00f3 la primera tanda de ensayos de la <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/formula-1.html\" title=\"F\u00f3rmula 1\" alt=\"F\u00f3rmula 1\" class=\"slug\">F\u00f3rmula<\/a><a href=\"https:\/\/www.ole.com.ar\/tema\/formula-1.html\" title=\"F\u00f3rmula 1\" alt=\"F\u00f3rmula 1\" class=\"slug\">1<\/a>.<\/strong> En el circuito de Montmel\u00f3 <strong>giraron siete escuder\u00edas durante las ocho horas de actividad<\/strong> previstas para la jornada inaugural, dentro de un total de cinco d\u00edas programados en Barcelona.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-8\"><img alt=\"El Alpine de Franco Colapinto en Montmel\u00f3.\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2026\/01\/video-franco-colapinto-y-pierre-gasly-a-puro-jueguito-con-la-n-5-antes-de-los-test-de-formula-1-1.jpg\"><span class=\"epigraphe\">El Alpine de Franco Colapinto en Montmel\u00f3.<\/span><\/div>\n<div id=\"element-body-9\" class=\"sc-136cd478-0 ekTCfV\" readability=\"41\">\n<p><strong>Haas, Mercedes, Red Bull, Racing Bulls, Cadillac, Audi y Alpine fueron los equipos que salieron a pista. <\/strong>En cuanto a los tiempos, Colapinto dej\u00f3 una muy buena impresi\u00f3n: pese a un inconveniente que lo oblig\u00f3 a detener el auto en una curva, <strong>marc\u00f3 1m20s189 y se meti\u00f3 tercero.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-10\" class=\"sc-136cd478-0 ekTCfV\" readability=\"37\">\n<p>El pilarense qued\u00f3 por detr\u00e1s de Isack Hadjar (1m18s452) y George Russell (1m18s696), pero <strong>super\u00f3 a nombres fuertes como Antonelli, Lawson, Ocon y Bottas.<\/strong> El Alpine complet\u00f3 28 vueltas por la ma\u00f1ana y 42 por la tarde.<\/p>\n<\/div>\n<div id=\"element-body-11\" class=\"sc-a7166897-0 eoLsBE\" readability=\"32\">\n<section readability=\"4\"><picture><img alt=\"Video: Franco Colapinto, protagonista del detr\u00e1s de escena del nuevo Alpine con la bandera argentina\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2026\/01\/video-franco-colapinto-y-pierre-gasly-a-puro-jueguito-con-la-n-5-antes-de-los-test-de-formula-1-2.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Video: Franco Colapinto, protagonista del detr\u00e1s de escena del nuevo Alpine con la bandera argentina<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-12\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31.5\">\n<section readability=\"3\"><picture><img alt=\"Flavio Briatore y un gui\u00f1o a Colapinto: \u00bfle asegur\u00f3 el lugar en Alpine para todo el a\u00f1o?\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2026\/01\/video-franco-colapinto-y-pierre-gasly-a-puro-jueguito-con-la-n-5-antes-de-los-test-de-formula-1-3.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Flavio Briatore y un gui\u00f1o a Colapinto: \u00bfle asegur\u00f3 el lugar en Alpine para todo el a\u00f1o?<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-13\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31.5\">\n<section readability=\"3\"><picture><img alt=\"A lo Scaloneta: el particular apodo de Franco Colapinto al nuevo Alpine tras su presentaci\u00f3n\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2026\/01\/video-franco-colapinto-y-pierre-gasly-a-puro-jueguito-con-la-n-5-antes-de-los-test-de-formula-1-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>A lo Scaloneta: el particular apodo de Franco Colapinto al nuevo Alpine tras su presentaci\u00f3n<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>26\/01\/2026 16:28hs. Actualizado al 26\/01\/2026 16:35hs. Franco Colapinto y Pierre Gasly se encuentran en Barcelona por los test de pretemporada, antes del inicio del torneo 2026 el 8 de marzo en Australia. Sin embargo, antes de acelerar, el hincha de Boca y su compa\u00f1ero, seguidor del PSG, se entretuvieron con la redonda. Franco Colapinto, Flavio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":77432,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/77431"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=77431"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/77431\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/77432"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=77431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=77431"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=77431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}