{"id":8082,"date":"2021-08-09T05:48:16","date_gmt":"2021-08-09T05:48:16","guid":{"rendered":"http:\/\/estaciontrip.com.ar\/?p=6028"},"modified":"2021-08-09T05:48:16","modified_gmt":"2021-08-09T05:48:16","slug":"villa-la-angostura-del-paisaje-al-plato","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/08\/09\/villa-la-angostura-del-paisaje-al-plato\/","title":{"rendered":"Villa La Angostura: del paisaje al plato"},"content":{"rendered":"<p><em>La localidad cordillerana de la Patagonia Argentina, ba\u00f1ada por el lago Nahuel Huapi, present\u00f3 su marca gastron\u00f3mica \u00abCocina de Monta\u00f1a\u00bb.<\/em><\/p>\n<p>Villa La Angostura -una perla patag\u00f3nica enmarcada por la Cordillera de los Andes en la provincia de Neuqu\u00e9n- incorpora el paisaje a su gastronom\u00eda, como ingrediente que la atraviesa.<\/p>\n<p>Es as\u00ed que surgi\u00f3 la marca \u00abCocina de Monta\u00f1a\u00bb, en la que ya queda claro el concepto desde su isologotipo: un cuchar\u00f3n \u00ablevanta\u00bb las monta\u00f1as, el elemento central del paisaje local, representadas con las l\u00edneas de la marca VLA y sus colores, entrelazadas con el nombre con el que sale a ganar identidad.<\/p>\n<p>Hoteleros, gastron\u00f3micos, productores, acad\u00e9micos, comerciantes respondieron a la invitaci\u00f3n de la Secretar\u00eda de Turismo local, a cargo de Marina Gonz\u00e1lez, y se pusieron a trabajar en conjunto para impulsar a VLA como destino de turismo gastron\u00f3mico a trav\u00e9s de una planificaci\u00f3n. <\/p>\n<div id=\"envira-gallery-wrap-6036\" class=\"envira-gallery-wrap envira-gallery-theme-base envira-lightbox-theme-base\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\">\n<div data-row-height data-gallery-theme id=\"envira-gallery-6036\" class=\"envira-gallery-public envira-gallery-1-columns envira-clear enviratope envira-gallery-css-animations\" data-envira-columns=\"1\">\n<div id=\"envira-gallery-item-6037\" class=\"envira-gallery-item enviratope-item envira-gallery-item-1 envira-lazy-load\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n<div class=\"envira-gallery-item-inner\"><a href=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/08\/villa-la-angostura-del-paisaje-al-plato-1.jpg\" class=\"envira-gallery-6036 envira-gallery-link\" rel=\"enviragallery6036\" title=\"VLA_1627587392\" data-envira-caption=\"VLA_1627587392\" data-envira-retina data-thumbnail itemprop=\"contentUrl\"><\/p>\n<div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\"><img id=\"envira-gallery-image-6037\" class=\"envira-gallery-image envira-gallery-image-1\" data-envira-index=\"1\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/08\/villa-la-angostura-del-paisaje-al-plato.jpg\" data-envira-src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/08\/villa-la-angostura-del-paisaje-al-plato.jpg\" data-envira-gallery-id=\"6036\" data-envira-item-id=\"6037\" data-envira-caption=\"VLA_1627587392\" alt title=\"VLA_1627587392\" itemprop=\"thumbnailUrl\" data-envira-srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/08\/villa-la-angostura-del-paisaje-al-plato.jpg 400w,http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/08\/villa-la-angostura-del-paisaje-al-plato.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\"><\/div>\n<p><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><noscript><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/08\/villa-la-angostura-del-paisaje-al-plato-1.jpg\" alt><\/noscript> <\/p>\n<p>\u00abNos llev\u00f3 tres meses de trabajo sobre la identidad de la gastronom\u00eda de Villa La Angostura. Interpretamos todo: pese a que hay materias primas, platos representativos que tienen identificaci\u00f3n con los frutos finos, el chocolate, la trucha o los ahumados, la marca se vincula directamente con el paisaje, la tradici\u00f3n y lo que representa Villa La Angostura. Es decir, es una cocina incorporada al paisaje. Por eso, el logo tiene una monta\u00f1a como elemento principal y a partir de eso se desarrolla el resto\u00bb, explica Mari\u00e1ngeles Samam\u00e9, de la consultoria Philia, encargada de coordinar el proyecto,<\/p>\n<p>\u00abEl nacimiento de esta marca es el hito como equipo de trabajo. A partir de esto se empezar\u00e1 a construir el desarrollo de la oferta de la gastronom\u00eda con identidad de Villa La Angostura y las capacitaciones necesarias\u00bb, adelanta Samam\u00e9.<\/p>\n<div id=\"envira-gallery-wrap-6038\" class=\"envira-gallery-wrap envira-gallery-theme-base envira-lightbox-theme-base\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\">\n<div data-row-height data-gallery-theme id=\"envira-gallery-6038\" class=\"envira-gallery-public envira-gallery-1-columns envira-clear enviratope envira-gallery-css-animations\" data-envira-columns=\"1\">\n<div id=\"envira-gallery-item-6039\" class=\"envira-gallery-item enviratope-item envira-gallery-item-1 envira-lazy-load\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n<div class=\"envira-gallery-item-inner\"><a href=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/08\/villa-la-angostura-del-paisaje-al-plato-3.jpg\" class=\"envira-gallery-6038 envira-gallery-link\" rel=\"enviragallery6038\" title=\"20210808_185941\" data-envira-caption=\"20210808_185941\" data-envira-retina data-thumbnail itemprop=\"contentUrl\"><\/p>\n<div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\"><img id=\"envira-gallery-image-6039\" class=\"envira-gallery-image envira-gallery-image-1\" data-envira-index=\"1\" src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/08\/villa-la-angostura-del-paisaje-al-plato-2.jpg\" data-envira-src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/08\/villa-la-angostura-del-paisaje-al-plato-2.jpg\" data-envira-gallery-id=\"6038\" data-envira-item-id=\"6039\" data-envira-caption=\"20210808_185941\" alt title=\"20210808_185941\" itemprop=\"thumbnailUrl\" data-envira-srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/08\/villa-la-angostura-del-paisaje-al-plato-2.jpg 400w,http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/08\/villa-la-angostura-del-paisaje-al-plato-2.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\"><\/div>\n<p><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><noscript><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/08\/villa-la-angostura-del-paisaje-al-plato-3.jpg\" alt><\/noscript> <\/p>\n<p><strong>Antecedentes<\/strong><\/p>\n<p>La iniciativa de desarrollar una marca gastron\u00f3mica se enmarca en una tendencia que no para de crecer a nivel mundial. Seg\u00fan la Organizaci\u00f3n Mundial de Turismo \u201cun tipo de actividad tur\u00edstica que se caracteriza en que el viajero experimenta durante su viaje diversas actividades y productos relacionados con la gastronom\u00eda del lugar. Adem\u00e1s de las experiencias culinarias aut\u00e9nticas, tradicionales o innovadoras, el turismo gastron\u00f3mico tambi\u00e9n puede incluir otro tipo de actividades, como visitar productores locales, participar en festivales gastron\u00f3micos o asistir a clases de cocina\u201c. Esta propuesta, adem\u00e1s de satisfacer a los viajeros, plantea una posibilidad de desarrollo que abarca a todos los actores de la extensa cadena de valor del turismo y la gastronom\u00eda en una estrategia de desarrollo sostenible y desestacionalizada.&nbsp;<\/p>\n<p>Todo esto fue tenido en cuenta como puntapi\u00e9 para reunir a un grupo diverso durante tres meses de trabajo a la distancia por la pandemia.<\/p>\n<p>Finalmente, hubo consenso y el resultado del trabajo sali\u00f3 a la luz. <\/p>\n<p>El paso siguiente ser\u00e1 la elaboraci\u00f3n del producto tur\u00edstico como estrategia para el desarrollo de la localidad y como propuesta que de impulso como factor de atracci\u00f3n tur\u00edstica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La localidad cordillerana de la Patagonia Argentina, ba\u00f1ada por el lago Nahuel Huapi, present\u00f3 su marca gastron\u00f3mica \u00abCocina de Monta\u00f1a\u00bb. Villa La Angostura -una perla patag\u00f3nica enmarcada por la Cordillera de los Andes en la provincia de Neuqu\u00e9n- incorpora el paisaje a su gastronom\u00eda, como ingrediente que la atraviesa. Es as\u00ed que surgi\u00f3 la marca [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8083,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[11],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/8082"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=8082"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/8082\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/8083"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=8082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=8082"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=8082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}