{"id":8406,"date":"2021-08-16T04:48:24","date_gmt":"2021-08-16T04:48:24","guid":{"rendered":"http:\/\/estaciontrip.com.ar\/?p=6064"},"modified":"2021-08-16T04:48:24","modified_gmt":"2021-08-16T04:48:24","slug":"previaje-nacion-relanzo-el-programa-de-compra-con-beneficios-en-turismo","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/08\/16\/previaje-nacion-relanzo-el-programa-de-compra-con-beneficios-en-turismo\/","title":{"rendered":"PreViaje: Naci\u00f3n relanz\u00f3 el programa de compra con beneficios en turismo"},"content":{"rendered":"<div><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/08\/previaje-nacion-relanzo-el-programa-de-compra-con-beneficios-en-turismo.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p><em>Por la compra anticipada de servicios tur\u00edsticos, se otorga un cr\u00e9dito para usar entre noviembre de 2021 y diciembre de 2022.<\/em><\/p>\n<p>Se la lanz\u00f3 la segunda edici\u00f3n del programa PreViaje, que busca impulsar la compra anticipada de servicios tur\u00edsticos nacionales mediante el otorgamiento de un cr\u00e9dito del 50% del gasto realizado.<\/p>\n<p>El escenario para la puesta en vigencia fueron las Cataratas del Iguaz\u00fa, en la provincia de Misiones.<\/p>\n<p>All\u00ed fue presentado por presidente Alberto Fern\u00e1ndez; acompa\u00f1ado por el ministro de Turismo y Deportes, Mat\u00edas Lammens, y el gobernador de la provincia de Misiones, Oscar Herrera Ahuad.<\/p>\n<p>Acerca de la modalidad, se explic\u00f3 que el per\u00edodo para hacer las compras anticipadas se inicia este mes de agosto y se extender\u00e1 hasta diciembre de este a\u00f1o.<\/p>\n<p>Los cr\u00e9ditos podr\u00e1n utilizarse desde noviembre de 2020 hasta diciembre de 2022; incluir\u00e1n la devoluci\u00f3n por la mitad de los gastos realizados en agencias de viaje, alojamientos, transporte, y otros servicios tur\u00edsticos como centros de ski, bodegas y espect\u00e1culos art\u00edsticos, adem\u00e1s del alquiler de veh\u00edculos.<\/p>\n<p>Para conocer m\u00e1s, ingresar en <a rel=\"noreferrer noopener\" href=\"https:\/\/t.co\/gVYjWXAwkS?amp=1\" target=\"_blank\">http:\/\/previaje.gob.ar<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por la compra anticipada de servicios tur\u00edsticos, se otorga un cr\u00e9dito para usar entre noviembre de 2021 y diciembre de 2022. Se la lanz\u00f3 la segunda edici\u00f3n del programa PreViaje, que busca impulsar la compra anticipada de servicios tur\u00edsticos nacionales mediante el otorgamiento de un cr\u00e9dito del 50% del gasto realizado. El escenario para la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8407,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[11],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/8406"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=8406"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/8406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/8407"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=8406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=8406"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=8406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}