{"id":9179,"date":"2021-09-02T13:46:23","date_gmt":"2021-09-02T13:46:23","guid":{"rendered":"http:\/\/estaciontrip.com.ar\/?p=6158"},"modified":"2021-09-02T13:46:23","modified_gmt":"2021-09-02T13:46:23","slug":"aerolineas-confirmo-el-regreso-de-las-operaciones-con-uruguay-desde-buenos-aires","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/09\/02\/aerolineas-confirmo-el-regreso-de-las-operaciones-con-uruguay-desde-buenos-aires\/","title":{"rendered":"Aerol\u00edneas confirm\u00f3 el regreso de las operaciones con Uruguay desde Buenos Aires"},"content":{"rendered":"<div><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/09\/aerolineas-confirmo-el-regreso-de-las-operaciones-con-uruguay-desde-buenos-aires.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p><em>A partir de la segunda quincena de septiembre regresan los vuelos hacia y desde Montevideo y Punta del Este.&nbsp;<\/em><\/p>\n<p><strong>Aerol\u00edneas Argentinas confirm\u00f3 el regreso de sus operaciones hacia y desde la Rep\u00fablica Oriental del Uruguay<\/strong>, <strong>conectando desde Buenos Aires.<\/strong><\/p>\n<p>A partir del 14 de septiembre -inicialmente los martes y viernes- el vuelo hacia y desde Montevideo se encuentra programado para las 8.45 partiendo de Buenos Aires con regreso para las 10.30.<\/p>\n<p>Mientras que la ruta con Punta del Este, operar\u00e1 los d\u00edas jueves y domingo desde el 16 de septiembre. Los jueves operar\u00e1 partiendo a las 11.40 desde Buenos Aires y regresando a las 13.25. En tanto que los domingos, ser\u00e1 a las 15.40 su salida y regreso para las 17.30.<\/p>\n<p>\u201cRestablecer la conectividad a\u00e9rea con Uruguay es muy importante tanto para el segmento corporativo como el vacacional. Hay mucha expectativa en ambas orillas del Rio de Plata de cara a la temporada de verano\u201d, expres\u00f3 Pablo Ceriani, presidente de Aerol\u00edneas Argentinas.<\/p>\n<p>Como es habitual, la compa\u00f1\u00eda publicar\u00e1 en su p\u00e1gina web los requisitos y la documentaci\u00f3n necesaria para poder realizar el embarque tanto en Argentina como en Uruguay.<\/p>\n<p>Aerol\u00edneas Argentinas no opera vuelos regulares a Uruguay desde marzo de 2020 cuando se cerraron las fronteras debido a la pandemia de coronavirus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de la segunda quincena de septiembre regresan los vuelos hacia y desde Montevideo y Punta del Este.&nbsp; Aerol\u00edneas Argentinas confirm\u00f3 el regreso de sus operaciones hacia y desde la Rep\u00fablica Oriental del Uruguay, conectando desde Buenos Aires. A partir del 14 de septiembre -inicialmente los martes y viernes- el vuelo hacia y desde [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9180,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[11],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/9179"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=9179"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/9179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/9180"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=9179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=9179"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=9179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}