{"id":9222,"date":"2021-09-03T03:02:48","date_gmt":"2021-09-03T03:02:48","guid":{"rendered":"https:\/\/puntoapunto.com.ar\/?p=315745"},"modified":"2021-09-03T03:02:48","modified_gmt":"2021-09-03T03:02:48","slug":"aviles-nacion-se-manejo-en-un-contexto-gris-es-de-sentido-comun-reabrir-el-aeropuerto","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/09\/03\/aviles-nacion-se-manejo-en-un-contexto-gris-es-de-sentido-comun-reabrir-el-aeropuerto\/","title":{"rendered":"Avil\u00e9s: \u201cNaci\u00f3n se manej\u00f3 en un contexto gris, es de sentido com\u00fan reabrir el aeropuerto\u201d"},"content":{"rendered":"<p>Una semana atr\u00e1s, el Gobernado<strong> Juan Schiaretti<\/strong> envi\u00f3 un petitorio dirigido al Jefe de Gabinete del Gobierno nacional, Santiago Cafiero, en donde \u201c<strong>propone al aeropuerto local, \u2018Ingeniero Ambrosio Taravella\u2019, como corredor a\u00e9reo seguro internacional<\/strong>, en el marco de lo dispuesto por Decisi\u00f3n Administrativa N\u00ba 793\/2021 de dicha cartera nacional\u201d.<\/p>\n<p>En la solicitud, Schiaretti detalla que&nbsp;en la provincia existe un <a href=\"https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2021\/08\/PROTOCOLO-VIAJEROS-EXTERIOR.pdf\" target=\"_blank\" rel=\"noopener\">protocolo de viajes a\u00e9reos y terrestres para el ingreso a C\u00f3rdoba<\/a> que ya fue aprobado por el Ministerio de Salud cordob\u00e9s.<\/p>\n<p>Si bien con cautela, en la administraci\u00f3n provincial ven como \u201cviable\u201d que el pedido sea atendido favorablemente y los consideran como \u201calgo de sentido com\u00fan\u201d.<\/p>\n<p>PERFIL C\u00d3RDOBA consult\u00f3 sobre el tema al presidente de la Agencia C\u00f3rdoba Turismo, <strong>Esteban Avil\u00e9s<\/strong>, quien destac\u00f3 que el planteo permanente de la provincia es<strong> \u201crecuperar y potenciar la conectividad a\u00e9rea que supimos tener\u201d.<\/strong><\/p>\n<p>\u201c<strong>Lo venimos reclamando en cada reuni\u00f3n del Consejo Federal de Turismo<\/strong> y la semana pasada en el encuentro con los representantes de todo el turismo nacional. En ese sentido lo que hizo Cafiero, despu\u00e9s de varias reuniones y pedidos que se ven\u00edan profundizando, fue emitir la resoluci\u00f3n administrativa (793\/21) en la cual, por primera vez en toda la pandemia, les solicita a los gobernadores sumarse a dos puntos muy precisos\u201d.<\/p>\n<p>Y detall\u00f3 los dos temas: \u201cTomar las medidas necesarias para disponer lo que se denomina <strong>\u2018aeropuertos seguros\u2019<\/strong> no solo en los vuelos de cabotaje sino tambi\u00e9n en los viajes internacionales para los argentinos varados en el exterior y la posibilidad de<strong> realizar una \u2018prueba piloto\u2019 con viajeros de Chile y Uruguay\u201d.<\/strong><\/p>\n<p>Con esos dos planteos, \u201ccambi\u00f3 la posici\u00f3n de la Naci\u00f3n al dejar de lado la situaci\u00f3n muy centralizada que ven\u00eda teniendo al mantener como \u00fanica puerta de entrada el aeropuerto de Ezeiza y se flexibilizan las condiciones al comunic\u00e1rselo al gobernador\u201d, explic\u00f3.<\/p>\n<p>A partir de esta nueva situaci\u00f3n, se realiz\u00f3 una reuni\u00f3n interministerial (Coordinaci\u00f3n, Industria y Comercio y Salud) y con la Agencia, para adecuar los protocolos que C\u00f3rdoba ya ten\u00eda en el aeropuerto con los vuelos de cabotaje a los internacionales. \u201cEsto se hizo en forma inmediata, porque ya lo ten\u00edamos aceitado\u201d, afirm\u00f3.<\/p>\n<p>\u201cTodav\u00eda no nos han respondido la nota, pero<strong> entendemos que hay viabilidad de lograrlo<\/strong>.&nbsp;La decisi\u00f3n administrativa de Cafiero habla de un cupo que se repartir\u00eda entre los aeropuertos del interior\u201d, indic\u00f3.<\/p>\n<p>La decisi\u00f3n administrativa del Gobierno nacional establece que, hasta el 5 de septiembre se eleva el cupo semanal de ingreso de pasajeros desde el exterior a 11.900 plazas (1.700 por d\u00eda) y, desde el 6 de septiembre hasta el 1 de octubre, a 16.100 (2.300 diarios). Cabe recordar que la primera provincia que elev\u00f3 un pedido en ese sentido fue Mendoza y luego se sumaron C\u00f3rdoba y tambi\u00e9n Salta.<\/p>\n<h5><strong>Aerol\u00edneas privadas<\/strong><\/h5>\n<p>Al respecto, Avil\u00e9s asegur\u00f3 que \u201cen contactos permanentes con las aerol\u00edneas privadas que operan en este aeropuerto nos aseguraron que, si se las notifica con 15 o 20 d\u00edas de anticipaci\u00f3n, que es lo m\u00ednimo que necesitan para programar sus operaciones, ya estar\u00edan en condiciones de reanudar con tres o cuatro vuelos semanales los viajes al exterior a finales de septiembre o principio de octubre\u201d.<\/p>\n<p>\u201cPero hay que aclarar \u2013a\u00f1adi\u00f3\u2013 que la Naci\u00f3n se manej\u00f3 siempre en un contexto gris, porque derivaba en las provincias la responsabilidad de mantener los hub, pero lo \u00fanico que se pod\u00eda hacer era autorizar los vuelos que dec\u00eda el Gobierno o la Anac\u201d.<\/p>\n<p>\u201cPor otro lado, quienes han podido hacer vuelos de cabotaje destacan que el aeropuerto C\u00f3rdoba es de los m\u00e1s seguros en materia de prevenci\u00f3n sanitaria. Adem\u00e1s, los vuelos que llegan o salen de este aeropuerto tienen un promedio de ocupaci\u00f3n de m\u00e1s del 80%; hay que recordar que C\u00f3rdoba es el epicentro de nueve provincias\u201d, afirm\u00f3.<\/p>\n<h5><strong>-\u00bfSon optimistas?<\/strong><\/h5>\n<p>-M\u00e1s que plantearlo como optimismo, ac\u00e1 hay una realidad: analizando lo que pas\u00f3 con los varados, el conflicto de quienes vuelven a sus destinos se gener\u00f3 por el centralismo que mantuvo el Gobierno nacional en Ezeiza, es una cuesti\u00f3n de sentido com\u00fan. Y en cuanto al hub, si bien entendemos que la pandemia golpe\u00f3 a nivel mundial y no somos la excepci\u00f3n, en el contexto de conectividad en nuestro pa\u00eds estamos muy atrasados.<\/p>\n<h5><strong>Una visita \u2018no oficial\u2019<\/strong><\/h5>\n<p>El pasado martes estuvo en C\u00f3rdoba \u2013en Villa Carlos Paz y Mina Clavero\u2013 el ministro de Turismo de la Naci\u00f3n, Mat\u00edas Lammens, para lanzar el \u00faltimo plan PreViaje.<\/p>\n<p>Consultado Esteban Avil\u00e9s si fue una visita oficial, expres\u00f3: \u201cSi hubiera sido oficial tendr\u00edan que haber convocado a las autoridades provinciales y\/o municipales de donde se realizaron las actividades y no hubo tal convocatoria. Aparentemente no fue una visita institucional. Cuando cualquier ministro de la Naci\u00f3n llega de visita, por una cuesti\u00f3n protocolar se informa a las autoridades. En este caso no ocurri\u00f3\u201d.<\/p>\n<p><strong>-Llam\u00f3 la atenci\u00f3n que en ambas reuniones usted no sal\u00eda en las fotos.<\/strong><\/p>\n<p>-(Risas) No, yo y ninguna autoridad provincial est\u00e1bamos.<\/p>\n<h5><strong>-Estaba el senador Carlos Caserio.<\/strong><\/h5>\n<p>-S\u00ed, estaba el senador y la hija, pero no hab\u00eda autoridades provinciales o municipales.<\/p>\n<p>(Especial por<strong> Juan Erramouspe<\/strong> para <strong>Perfil C\u00f3rdoba<\/strong>)<\/p>\n<div class=\"saboxplugin-wrap\" itemtype=\"http:\/\/schema.org\/Person\" itemscope itemprop=\"author\">\n<div class=\"saboxplugin-tab\">\n<div class=\"saboxplugin-gravatar\"><img alt src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/09\/aviles-nacion-se-manejo-en-un-contexto-gris-es-de-sentido-comun-reabrir-el-aeropuerto.jpg\" srcset=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/09\/aviles-nacion-se-manejo-en-un-contexto-gris-es-de-sentido-comun-reabrir-el-aeropuerto-1.jpg 2x\" class=\"avatar avatar-100 photo\" height=\"100\" width=\"100\" itemprop=\"image\" loading=\"lazy\"><\/div>\n<div class=\"saboxplugin-desc\" readability=\"6.5\">\n<div itemprop=\"description\" readability=\"8\">\n<p>Este articulo fue escrito por la redacci\u00f3n de Punto a Punto. Seguinos en todas nuestras redes sociales<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Una semana atr\u00e1s, el Gobernado Juan Schiaretti envi\u00f3 un petitorio dirigido al Jefe de Gabinete del Gobierno nacional, Santiago Cafiero, en donde \u201cpropone al aeropuerto local, \u2018Ingeniero Ambrosio Taravella\u2019, como corredor a\u00e9reo seguro internacional, en el marco de lo dispuesto por Decisi\u00f3n Administrativa N\u00ba 793\/2021 de dicha cartera nacional\u201d. En la solicitud, Schiaretti detalla que&nbsp;en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9223,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14,11],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/9222"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=9222"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/9222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/9223"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=9222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=9222"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=9222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}