{"id":9410,"date":"2021-09-07T18:35:34","date_gmt":"2021-09-07T18:35:34","guid":{"rendered":"https:\/\/cordoba.gob.ar\/?p=13081"},"modified":"2021-09-07T18:35:34","modified_gmt":"2021-09-07T18:35:34","slug":"la-municipalidad-adhirio-a-la-historia-clinica-electronica-unica-provincial","status":"publish","type":"post","link":"http:\/\/nuevacordoba.net\/index.php\/2021\/09\/07\/la-municipalidad-adhirio-a-la-historia-clinica-electronica-unica-provincial\/","title":{"rendered":"La Municipalidad adhiri\u00f3 a la Historia Cl\u00ednica Electr\u00f3nica \u00danica Provincial"},"content":{"rendered":"<div><img src=\"http:\/\/nuevacordoba.net\/wp-content\/uploads\/2021\/09\/la-municipalidad-adhirio-a-la-historia-clinica-electronica-unica-provincial.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<ul>\n<li><strong>Llaryora calific\u00f3 de \u201chist\u00f3rico\u201d el anuncio para la salud p\u00fablica municipal.<\/strong><\/li>\n<li><strong>Provincia y Municipio unificar\u00e1n la historia cl\u00ednica m\u00e9dica digital del paciente desde que nace hasta que muere.<\/strong><\/li>\n<\/ul>\n<hr>\n<p>El intendente Mart\u00edn Llaryora y el ministro de Salud del Gobierno de C\u00f3rdoba, Diego Cardozo, firmaron un convenio para la adhesi\u00f3n del Municipio al Sistema Provincial de Historia Cl\u00ednica Electr\u00f3nica \u00danica (HCEU).<\/p>\n<p>El sistema integrado que implementa el Gobierno Provincial desde el a\u00f1o 2019, se aplica bajo un est\u00e1ndar internacional y permite que profesionales del sistema de salud de instituciones p\u00fablicas provinciales tengan acceso al resumen de la historia cl\u00ednica de sus pacientes, en contraposici\u00f3n al cerrado sistema existente que solo facilitaba el acceso entre los centros municipales.<\/p>\n<p>De esta manera, a partir del convenio rubricado, hoy comienza el proceso de digitalizaci\u00f3n del sistema de salud municipal, lo que permitir\u00e1 que vecinos que realicen sus estudios en los Centros de Salud del Municipio puedan contar con la informaci\u00f3n en tiempo real y continuar su tratamiento en cualquier localidad de la provincia, personalizando y optimizando interconsultas y derivaciones y mejorando la experiencia de atenci\u00f3n m\u00e9dica en todo el territorio.<\/p>\n<p><em>\u201cLo \u00fanico que hac\u00eda falta para que la uni\u00f3n con la historia cl\u00ednica provincial se lleve a cabo era tomar la decisi\u00f3n pol\u00edtica de transformar digitalmente al municipio, transformaci\u00f3n que genera un antes y un despu\u00e9s en la calidad de vida de los vecinos\u201d<\/em>, expres\u00f3 el intendente Mart\u00edn Llaryora.<\/p>\n<p>Adem\u00e1s, el jefe comunal recalc\u00f3: <em>\u201ccon estas acciones vamos a multiplicar la eficiencia con la misma potencialidad que tenemos hoy. Uno de los legados que vamos a dejar en nuestra gesti\u00f3n es el ingreso pleno a un gobierno municipal que va a poner a C\u00f3rdoba dentro de las grandes capitales del mundo en materia de transformaci\u00f3n digital\u201d.<\/em><\/p>\n<p>En este sentido, Llaryora inform\u00f3 que los hospitales y Centros de Salud est\u00e1n siendo equipados con tecnolog\u00eda de punta y una mayor conectividad, garantizando en todos los casos una velocidad de navegaci\u00f3n acorde a las nuevas demandas del sistema.<\/p>\n<p>A su tiempo, el ministro de Salud, Diego Cardozo, destac\u00f3: <em>\u201ces significativa la importancia para los pacientes y nuestro equipo de salud, no s\u00f3lo de poder contar con una historia \u00fanica de cada ciudadano, sino tambi\u00e9n poder analizarla retrospectivamente a trav\u00e9s de un sistema m\u00e1s ordenado, sustentable y simple para nuestros equipos de salud\u201d.<\/em><\/p>\n<p>Y a\u00f1adi\u00f3: <em>\u201choy comienza una nueva etapa de transformaci\u00f3n sanitaria, donde la integraci\u00f3n Provincia y Municipio se hace realidad con proyectos y acciones concretas que van a hacer historia, sin lugar a dudas, en la salud de los cordobeses\u201d.<\/em><\/p>\n<p>Por su parte, el secretario de Salud, Ariel Aleksandroff, expres\u00f3: <em>\u201ces un salto hist\u00f3rico para nuestros pacientes y todo nuestro personal m\u00e9dico. Con esta iniciativa los turnos se podr\u00e1n gestionar v\u00eda internet sin llevar estudios como radiograf\u00edas o tomograf\u00edas y los vecinos podr\u00e1n llevar su historial m\u00e9dico con ellos en caso de mudanza\u201d.<\/em><\/p>\n<p>El nuevo sistema consta de una plataforma web interna, a la que podr\u00e1n acceder tanto personal m\u00e9dico autorizado, como los mismos pacientes a trav\u00e9s de un usuario y contrase\u00f1a personales.<\/p>\n<p>La informaci\u00f3n almacenada estar\u00e1 disponible en todo momento, previniendo errores y brindando mayor seguridad en la toma de decisiones.<\/p>\n<p>Entre otros beneficios, mejorar\u00e1 la trazabilidad y el control de medicamentos; exigir\u00e1 un registro de internaci\u00f3n y atenci\u00f3n del paciente, el cual no se realizaba hasta la fecha; registrar\u00e1 permisos y an\u00e1lisis de laboratorio eximiendo el uso innecesario del papel; y permitir\u00e1 un mayor seguimiento en la evoluci\u00f3n de pacientes.<\/p>\n<p>A diferencia del sistema anterior, no se precisa la instalaci\u00f3n de infraestructura particular en cada instituci\u00f3n de salud, acelerando el proceso de capacitaci\u00f3n e iniciaci\u00f3n de la HCEU en los centros municipales.<\/p>\n<p>La adhesi\u00f3n de la Municipalidad a la Historia Cl\u00ednica provincial, se enmarca en el Plan Integral de Modernizaci\u00f3n del Estado Municipal, mediante el cual se asignaron 1.200 nuevas computadoras en las DEM, Centros de Salud, Direcci\u00f3n de Especialidades M\u00e9dicas 107, Calidad Alimentaria, Epidemiolog\u00eda, Hogar Padre Lam\u00f3naca, Medicina Preventiva, los tres hospitales, entre otras \u00e1reas del sistema de salud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llaryora calific\u00f3 de \u201chist\u00f3rico\u201d el anuncio para la salud p\u00fablica municipal. Provincia y Municipio unificar\u00e1n la historia cl\u00ednica m\u00e9dica digital del paciente desde que nace hasta que muere. El intendente Mart\u00edn Llaryora y el ministro de Salud del Gobierno de C\u00f3rdoba, Diego Cardozo, firmaron un convenio para la adhesi\u00f3n del Municipio al Sistema Provincial de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9411,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/9410"}],"collection":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/comments?post=9410"}],"version-history":[{"count":0,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/posts\/9410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media\/9411"}],"wp:attachment":[{"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/media?parent=9410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/categories?post=9410"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/nuevacordoba.net\/index.php\/wp-json\/wp\/v2\/tags?post=9410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}